{"id":22493,"date":"2013-05-20T11:06:38","date_gmt":"2013-05-20T09:06:38","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=22493"},"modified":"2023-01-17T13:20:08","modified_gmt":"2023-01-17T12:20:08","slug":"8823-eletti-i-consiglieri-nazionali-dell-ordine-dei-giornalisti","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/8823-eletti-i-consiglieri-nazionali-dell-ordine-dei-giornalisti\/","title":{"rendered":"Eletti i consiglieri nazionali dell&#8217;ordine dei giornalisti"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"color: #000000;\">CATANZARO &#8211; Si sono svolte ieri, in seconda convocazione, a Catanzaro le operazioni di voto per l&#8217; elezione dei cinque consiglieri nazionali dell&#8217;Ordine<\/span><\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"> dei Giornalisti (due professionisti e tre pubblicisti) in rappresentanza della Calabria. Per i professionisti primo eletto e&#8217; risultato Attilio Sabato con 88 voti, secondo eletto Andrea Musmeci con 70 voti. Per i pubblicisti il primo eletto e&#8217; stato Natalino Bianco con 196 voti; secondo eletto Cosimo Bruno con 179 voti, terzo eletto Rosario De Luca con 151 voti. Per quattro degli eletti (Sabato, Musmeci, Bianco e Bruno) si tratta di una riconferma, per De Luca, invece, e&#8217; la prima volta da consigliere nazionale. Soddisfazione per la elezione dei cinque consiglieri nazionali e&#8217; stata espressa dal Presidente dell&#8217;Ordine regionale, Giuseppe Soluri. &#8220;Sono certo &#8211; ha detto Soluri &#8211; che i cinque rappresentanti della Calabria, sia i riconfermati che il nuovo eletto, sapranno rappresentare al meglio la nostra regione nel contesto di un organismo importante come il Consiglio Nazionale dell&#8217;Ordine. Rivolgo ai cinque colleghi le piu&#8217; vive congratulazioni ed il piu&#8217; sincero in bocca al lupo per l&#8217;impegnativo compito&#8221;.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>CATANZARO &#8211; Si sono svolte ieri, in seconda convocazione, a Catanzaro le operazioni di voto per l&#8217; elezione dei cinque consiglieri nazionali dell&#8217;Ordine<\/p>\n","protected":false},"author":22,"featured_media":22494,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-22493","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/22493","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=22493"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/22493\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/22494"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=22493"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=22493"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=22493"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}