{"id":224977,"date":"2024-03-08T14:20:00","date_gmt":"2024-03-08T13:20:00","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=224977"},"modified":"2024-03-08T14:20:00","modified_gmt":"2024-03-08T13:20:00","slug":"operazione-a-buccinasco-sequestrati-terreni-per-500mila-euro-a-boss-della-ndrangheta","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/operazione-a-buccinasco-sequestrati-terreni-per-500mila-euro-a-boss-della-ndrangheta\/","title":{"rendered":"Operazione a Buccinasco: sequestrati terreni per 500mila euro a boss della &#8216;ndrangheta"},"content":{"rendered":"<p>MILANO &#8211; I carabinieri del nucleo investigativo del comando provinciale di Pavia hanno proceduto all&#8217;esecuzione di sequestro, propedeutica alla confisca, <strong>di vari terreni nel comune di Buccinasco (Milano) di propriet\u00e0 di Pasquale Zappia, 84 anni, originario di Plat\u00ec (Reggio Calabria) e conosciuto come uno dei capi della &#8216;ndrangheta calabrese.<\/strong> L&#8217;operazione \u00e8 stata eseguita su delega della Procura della Repubblica di Milano &#8211; Direzione distrettuale antimafia (Dda).<\/p>\n<p>I terreni sequestrati hanno un valore stimato di circa 500mila euro. Le attivit\u00e0 di accertamento patrimoniale sono state effettuate dopo l&#8217;emissione di una interdittiva antimafia da parte della <strong>Prefettura di Milano, sono proseguite con gli accertamenti condotti dai carabinieri della Procura di Pavia e concluse dalla polizia giudiziaria della Dda. Dalle indagini \u00e8 emerso che &#8220;i beni acquisiti<\/strong> &#8211; sottolinea una nota dei carabinieri di Pavia &#8211; fossero frutto di investimento di proventi tratti dalla commissione di delitti lucro-genetici e come, pertanto, fossero meritevoli di recupero da parte dello Stato attraverso l&#8217;applicazione del Codice Antimafia&#8221;. Pasquale Zappia \u00e8 stato coinvolto nel 1993 nell&#8217;operazione &#8220;Nord-Sud&#8221; e successivamente condannato nel processo &#8220;Infinito&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>MILANO &#8211; I carabinieri del nucleo investigativo del comando provinciale di Pavia hanno proceduto all&#8217;esecuzione di sequestro, propedeutica alla confisca, di vari terreni nel comune di Buccinasco (Milano) di propriet\u00e0 di Pasquale Zappia, 84 anni, originario di Plat\u00ec (Reggio Calabria) e conosciuto come uno dei capi della &#8216;ndrangheta calabrese. L&#8217;operazione \u00e8 stata eseguita su delega [&hellip;]<\/p>\n","protected":false},"author":61,"featured_media":224316,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[19],"class_list":["post-224977","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/224977","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=224977"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/224977\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/224316"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=224977"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=224977"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=224977"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}