{"id":225102,"date":"2024-03-11T16:00:38","date_gmt":"2024-03-11T15:00:38","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=225102"},"modified":"2024-03-11T18:05:27","modified_gmt":"2024-03-11T17:05:27","slug":"cosenza-cloaca-maxima-e-liquami-sversati-nel-crati-le-richieste-di-condanna","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/cosenza-cloaca-maxima-e-liquami-sversati-nel-crati-le-richieste-di-condanna\/","title":{"rendered":"Cosenza: &#8220;Cloaca Maxima&#8221; e liquami sversati nel Crati, le richieste di condanna"},"content":{"rendered":"<p>COSENZA &#8211; Al termine dell&#8217;udienza oggi, del processo scaturito dall&#8217;operazione &#8216;<a href=\"https:\/\/quicosenza.it\/news\/?s=cloaca+maxima\">Cloaca Maxima<\/a>&#8216;, il pm Giuseppe Cozzolino, dopo la requisitoria durata circa 3 ore, ha elencato le richieste di condanna per i <strong>sei imputati<\/strong>. Il dibattimento \u00e8 scaturito dall&#8217;operazione, che risale al 2018, e che accert\u00f2 lo sversamento dei liquami prodotti dall\u2019impianto di depurazione consortile di Coda di Volpe, nella zona industriale di Rende, direttamente nel Crati. <strong>Sei persone<\/strong> vennero indagate e accusate di <strong>disastro ambientale<\/strong>.<\/p>\n<p>Un&#8217;operazione che part\u00ec dopo le numerose <strong>denunce dei cittadini<\/strong> che avevano notato e anche immortalato la presenza di schiuma e liquami, accompagnata da un odore nauseabondo, in alcuni punti nei pressi dell\u2019impianto. Dopo la requisitoria sono stati chiesti due anni per Vincenzo Cerrone (e multa da 10.000 euro), mentre per Dionigi Fiorita, Giovanni Provenzano, Annunziato Tenuta, Rosario Volpentesta e Eugenio Valentini, 1 anno e 4 mesi (pi\u00f9 una sanzione da 8mila euro).<\/p>\n<p>Cloaca Maxima venne definita dal procuratore Spagnuolo, all&#8217;epoca del blitz, <strong>&#8220;la pi\u00f9 importante indagine in materia di tutela dell\u2019ambiente mai condotta nel Cosentino&#8221;.<\/strong> I carabinieri-forestali oltre ad una corposa documentazione video e di immagini avevano anche intercettato il direttore dell\u2019impianto Cerrone che dava disposizioni al personale addetto di deviare le acque reflue, indirizzandole proprio nel Crati<strong>, mettendo a rischio pertanto la salute dei cittadini.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Al termine dell&#8217;udienza oggi, del processo scaturito dall&#8217;operazione &#8216;Cloaca Maxima&#8216;, il pm Giuseppe Cozzolino, dopo la requisitoria durata circa 3 ore, ha elencato le richieste di condanna per i sei imputati. Il dibattimento \u00e8 scaturito dall&#8217;operazione, che risale al 2018, e che accert\u00f2 lo sversamento dei liquami prodotti dall\u2019impianto di depurazione consortile di [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":225103,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42],"tags":[19],"class_list":["post-225102","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/225102","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=225102"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/225102\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/225103"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=225102"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=225102"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=225102"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}