{"id":225374,"date":"2024-03-14T10:54:23","date_gmt":"2024-03-14T09:54:23","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=225374"},"modified":"2024-03-14T13:45:49","modified_gmt":"2024-03-14T12:45:49","slug":"cosenza-casi-di-truffa-sul-nuovo-bancomat-diverse-le-vittime-e-denaro-sparito-dai-conti","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/cosenza-casi-di-truffa-sul-nuovo-bancomat-diverse-le-vittime-e-denaro-sparito-dai-conti\/","title":{"rendered":"Cosenza: casi di truffa sul &#8216;nuovo&#8217; bancomat, diverse le vittime e denaro sparito dai conti"},"content":{"rendered":"<p>COSENZA &#8211; Negli ultimi giorni in citt\u00e0, sono state <strong>diverse le denunce ai carabinieri,<\/strong> da parte di correntisti che hanno visto <strong>sparire<\/strong> dai propri conti, <strong>cifre di denaro importanti<\/strong>. La truffa sta riguardando numerosi <strong>clienti di Unicredit<\/strong>. Secondo quanto emerso i malfattori contattano telefonicamente le vittime, in particolare<strong> chi attendeva la sostituzione della propria carta bancomat<\/strong>. A trarre in inganno l&#8217;utente \u00e8 il fatto che, le <strong>telefonate,<\/strong> provengono <strong>proprio da un numero dell&#8217;istituto bancario<\/strong>. Dall&#8217;altra parte l&#8217;interlocutore, a conoscenza di tutti i dati personali della vittima, compreso il numero della carta, chiede alla vittima di fornire <strong>username, password dell&#8217;app e soprattutto il pin del &#8216;vecchio&#8217; bancomat<\/strong> con la scusa di dover procedere all&#8217;attivazione della nuova tessera. Ed \u00e8 qui che scatta la truffa (la cosiddetta <strong>tecnica<\/strong> dello <strong>spoofing)<\/strong>. La telefonata, inoltre, sembra giungere dal vero numero di telefono dell&#8217;istituto bancario come ha confermato alla nostra redazione una delle vittime.<\/p>\n<h3>&#8220;Rubati 2mila euro in un amen. Ad un pensionato 5mila&#8221;<\/h3>\n<p>&#8220;Sono disperata &#8211; racconta una donna alla nostra redazione &#8211; in pochi istanti hanno <strong>sottratto dal mio conto<\/strong> <strong>2mila euro<\/strong>. Io so perfettamente che al telefono non si deve mai fornire alcun tipo di dato personale, e tantomeno non devo dare alcuna possibilit\u00e0 di accesso al mio conto, ma la &#8216;<strong>signorina<\/strong>&#8216; mi ha contattato dal <strong>numero che io ho registrato come quello di Unicredit<\/strong>. Ed era credibile, in quanto mi ha spiegato e fornito una serie di dati di cui, solo la mia banca poteva essere a conoscenza. Poco dopo dal conto ho visto sparire i soldi. I<strong> prelievi illeciti sono stati effettuati a Sarno <\/strong>(nel salernitano) e <strong>stavano anche per prelevare altri 500 euro per fittare un&#8217;auto<\/strong>, ma i truffatori non ci sono riusciti, perch\u00e9 sono riuscita a bloccare in tempo la carta prima che svuotassero del tutto il mio conto. Mi sono recata dai carabinieri a <strong>sporgere denuncia <\/strong>e, purtroppo, mi sono resa conto che non ero l&#8217;unica ad essere caduta in questa trappola. <strong>Ho trovato in fila altre persone che come me, erano state truffate<\/strong>. Tra loro anche un<strong> pensionato al quale avevano sottratto 5mila euro<\/strong>&#8220;.<\/p>\n<h3>L&#8217;audio su WhatsApp e l&#8217;allerta di altri cittadini<\/h3>\n<p>Intanto nelle chat, su <strong>WhatsApp<\/strong>, dopo i diversi casi registrati, \u00e8 scattato l&#8217;allarme: <strong>&#8220;fate attenzione, non fornite alcun dato, bloccate il numero&#8221;<\/strong> e si parla anche &#8220;<strong>di una &#8216;partita di bancomat&#8217; nuovi<\/strong>, utili alla sostituzione di quelli in scadenza dei clienti, che sarebbe stata trafugata dai malviventi autori del raggiro&#8221;. Ma ovviamente quest&#8217;ultimo passaggio non \u00e8 confermato. Gli hacker, inoltre, con tecniche sempre pi\u00f9 avanzate sarebbero <strong>riusciti ad &#8220;immettersi&#8221; nel numero telefonico di Unicredit.<\/strong> In alcuni casi, attraverso un primo SMS, apparentemente riconducibile al servizio clienti del proprio istituto di credito, si viene avvertiti di un blocco del conto o dell&#8217;arrivo della nuova carta bancomat.<\/p>\n<p>Una volta agganciati, i clienti ignari tendono a fidarsi e a fornire i dati che vengono richiesti. Una truffa che sta riguardando diversi clienti Unicredit e con <strong>diverse migliaia di euro sottratti illecitamente dai conti correnti<\/strong>. Nella maggior parte dei casi, <strong>l\u2019autore del reato resta ignoto<\/strong>\u00a0e la conseguenza \u00e8 che <strong>la vittima non riesce ad ottenere la restituzione di quanto illecitamente sottratto<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Negli ultimi giorni in citt\u00e0, sono state diverse le denunce ai carabinieri, da parte di correntisti che hanno visto sparire dai propri conti, cifre di denaro importanti. La truffa sta riguardando numerosi clienti di Unicredit. Secondo quanto emerso i malfattori contattano telefonicamente le vittime, in particolare chi attendeva la sostituzione della propria carta [&hellip;]<\/p>\n","protected":false},"author":19,"featured_media":225377,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42],"tags":[19],"class_list":["post-225374","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/225374","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=225374"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/225374\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/225377"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=225374"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=225374"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=225374"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}