{"id":225435,"date":"2024-03-14T21:10:58","date_gmt":"2024-03-14T20:10:58","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=225435"},"modified":"2024-03-14T20:25:04","modified_gmt":"2024-03-14T19:25:04","slug":"uccisa-e-data-in-pasto-ai-maiali-dopo-8-anni-di-attesa-il-processo-di-maria-chindamo-e-rinviato","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/uccisa-e-data-in-pasto-ai-maiali-dopo-8-anni-di-attesa-il-processo-di-maria-chindamo-e-rinviato\/","title":{"rendered":"Uccisa e data in pasto ai maiali, dopo 8 anni di attesa il processo di Maria Chindamo \u00e8 rinviato"},"content":{"rendered":"<p>CATANZARO &#8211; E&#8217; stata <strong>un&#8217;udienza breve e interlocutoria<\/strong> quella che si \u00e8 tenuta stamani davanti alla Corte d&#8217;assise di Catanzaro in apertura del processo per <strong>l&#8217;omicidio di Maria Chindamo<\/strong>, l&#8217;imprenditrice di 44 anni di Laureana di Borrello (Reggio Calabria), rapita e uccisa a Limbadi (Vibo Valentia) il 6 maggio 2016 e il cui corpo \u00e8 stato poi dato in pasto ai maiali e i resti distrutti con la fresa di un trattore.<\/p>\n<p>Per il delitto \u00e8<strong> imputato Salvatore Ascone<\/strong>, di 58 anni, accusato di avere collaborato alla pianificazione, organizzazione ed esecuzione dell&#8217;omicidio in concorso con <strong>l&#8217;ex suocero di Maria Chindamo, Vincenzo Punturiero,<\/strong> che \u00e8 deceduto, il quale a<strong>vrebbe commissionato il delitto<\/strong> perch\u00e9 imputava il suicidio del figlio alla separazione che questi aveva avuto da Maria Chindamo. Ascone avrebbe partecipato avendo interesse, in proprio e in qualit\u00e0 di referente della cosca Mancuso, ad acquisire un terreno dell&#8217;imprenditrice.<\/p>\n<h4><strong>L&#8217;avvocato di Ascone: &#8220;venga trasferito a Catanzaro per intervento urgente&#8221;<\/strong><\/h4>\n<p>Nel corso dell&#8217;udienza, il difensore di Ascone, <strong>l&#8217;avvocato Salvatore Staiano, ha sollecitato la Corte a trasferire l&#8217;imputato dal carcere di Secondigliano a quello di Catanzaro<\/strong> perch\u00e9 deve essere sottoposto urgentemente a un intervento chirurgico essendo &#8220;affetto da una patologia che potrebbe portarlo alla morte&#8221;. Il presidente, Massimo Forciniti, ha riferito che la Corte gi\u00e0 dall&#8217;8 marzo ha acconsentito a dare il nulla osta per il trasferimento. Il pm Annamaria Frustaci ha poi spiegato che per 4 mesi Ascone ha rifiutato i ricoveri nelle strutture indicate dalle case circondariali nelle quali era detenuto perch\u00e9 voleva essere operato dal suo medico di fiducia. La Procura comunque non si \u00e8 opposta al trasferimento.<\/p>\n<p>L&#8217;avvocato Staiano ha quindi accusato l&#8217;inerzia della casa circondariale e ha chiesto un sollecito perch\u00e9 venga dato seguito al trasferimento. Nel proseguo dell&#8217;udienza \u00e8 stata presentata un&#8217;eccezione di nullit\u00e0 relativa alla notifica della chiusura indagini. Nel processo vengono giudicati anche i presunti autori di un altro delitto, quello di Angelo Antonio Corigliano, ucciso a Mileto il 19 agosto 2013, per il quale sono imputati Giuseppe Mazzitelli, Salvatore Pititto, e Domenico Iannello. La Corte ha quindi aggiornato all&#8217;11 aprile prossimo.<\/p>\n<h4><strong>Il fratello di Maria Chindamo: &#8220;percorso umanamente impegnativo&#8221;<\/strong><\/h4>\n<p>&#8220;Abbiamo iniziato, c&#8217;era una grande tensione da parte mia, sono sicuro che sar\u00e0 un percorso certamente difficile, impegnativo, sia dal punto di vista giuridico che da un punto di vista umano ed emotivo&#8221;. Apparso col <strong>viso stanco, emozionato e anche un po&#8217; teso, Vincenzo Chindamo,<\/strong> ha partecipato alla prima udienza del processo a carico di uno dei presunti responsabili dell&#8217;omicidio della sorella, Maria, l&#8217;imprenditrice rapita e uccisa davanti alla sua azienda a Limbadi il 6 maggio 2016 e il cui corpo \u00e8 stato dato in pasto ai maiali e i resti triturati da un trattore.<\/p>\n<p>Vincenzo Chindamo non ha nascosto il<strong> peso emotivo del processo<\/strong> che andr\u00e0 ad affrontare: &#8220;Abbiamo aspettato otto anni, adesso la paura dei tempi si \u00e8 affievolita. Siamo tutti fermi a seguire con grande attenzione ogni passo di questo cammino. Mi ha fatto piacere avere accanto anche tanti amici, le associazioni, tante persone che si sono affiancate e che hanno dimostrato vicinanza a solidariet\u00e0&#8221;. Presente all&#8217;avvio del dibattimento era anche l&#8217;associazione Libera rappresentata dal referente provinciale Giuseppe Borrello. Vincenzo Chindamo, assistito quale parte civile dall&#8217;avvocato Nicodemo Gentile, ha raccontato che gi\u00e0 da ieri sera ha ricevuto messaggi e attestati di solidariet\u00e0 e questo, ha detto, &#8220;ci fa sentire sempre meno soli e ci conforta veramente tanto&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CATANZARO &#8211; E&#8217; stata un&#8217;udienza breve e interlocutoria quella che si \u00e8 tenuta stamani davanti alla Corte d&#8217;assise di Catanzaro in apertura del processo per l&#8217;omicidio di Maria Chindamo, l&#8217;imprenditrice di 44 anni di Laureana di Borrello (Reggio Calabria), rapita e uccisa a Limbadi (Vibo Valentia) il 6 maggio 2016 e il cui corpo \u00e8 [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":201069,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[19],"class_list":["post-225435","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/225435","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=225435"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/225435\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/201069"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=225435"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=225435"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=225435"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}