{"id":225467,"date":"2024-03-15T12:00:00","date_gmt":"2024-03-15T11:00:00","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=225467"},"modified":"2024-03-15T11:04:30","modified_gmt":"2024-03-15T10:04:30","slug":"imprenditore-al-vertice-di-unassociazione-ndranghetista-confiscati-beni-per-un-milione","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/imprenditore-al-vertice-di-unassociazione-ndranghetista-confiscati-beni-per-un-milione\/","title":{"rendered":"Imprenditore al vertice di un\u2019associazione &#8216;ndranghetista: confiscati beni per un milione"},"content":{"rendered":"<p>ISOLA CAPO RIZZUTO &#8211; La Direzione Investigativa Antimafia<strong> ha dato esecuzione ad un decreto di confisca<\/strong>\u00a0definitivo dopo il vaglio della Suprema Corte di Cassazione.<\/p>\n<p>Destinatario della misura <strong>di prevenzione un imprenditore catanzarese, considerato il \u201cvertice\u201d di un\u2019associazione \u2018ndranghetista,<\/strong> attiva sotto l\u2019influenza delle locali di Cutro e Isola Capo Rizzuto, con epicentro nei territori della provincia di Catanzaro ed in particolare <strong>nei comuni di Vallefiorita, Amaroni e Squillace<\/strong>.<\/p>\n<p>Le indagine hanno fatto emergere <strong>una rilevante sproporzione tra il patrimonio nella disponibilit\u00e0 del proposto e i redditi da lui dichiarati<\/strong>. Tra i beni confiscati figurano l\u2019intero <strong>compendio aziendale di 2 societ\u00e0 attive nei settori della ristorazione e della tinteggiatura e posa in opera di vetri<\/strong>, un\u2019associazione culturale, 10 immobili, un motociclo, una autovettura, nonch\u00e9 rapporti bancari e disponibilit\u00e0 finanziarie, <strong>per un valore complessivo stimato di oltre 1 milione di euro<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ISOLA CAPO RIZZUTO &#8211; La Direzione Investigativa Antimafia ha dato esecuzione ad un decreto di confisca\u00a0definitivo dopo il vaglio della Suprema Corte di Cassazione. Destinatario della misura di prevenzione un imprenditore catanzarese, considerato il \u201cvertice\u201d di un\u2019associazione \u2018ndranghetista, attiva sotto l\u2019influenza delle locali di Cutro e Isola Capo Rizzuto, con epicentro nei territori della provincia [&hellip;]<\/p>\n","protected":false},"author":61,"featured_media":225468,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[19,135],"class_list":["post-225467","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-calabria","tag-copertina","tag-video","post_format-post-format-video"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/225467","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=225467"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/225467\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/225468"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=225467"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=225467"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=225467"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}