{"id":225685,"date":"2024-03-22T06:30:59","date_gmt":"2024-03-22T05:30:59","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=225685"},"modified":"2024-03-18T09:13:52","modified_gmt":"2024-03-18T08:13:52","slug":"rende-pensa-tu-al-via-la-terza-edizione-del-festival-della-scienza","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/rende-pensa-tu-al-via-la-terza-edizione-del-festival-della-scienza\/","title":{"rendered":"Rende: &#8216;Pensa tu&#8217;, al via la terza edizione del Festival della Scienza"},"content":{"rendered":"<p>RENDE &#8211; Quattro giornate dedicate al mondo della scienza e della tecnologia al Parco Acquatico di Rende, con sale espositive e mostre per grandi e piccini. Torna la terza edizione del &#8220;Pensa Tu&#8221; nelle giornate di <strong>sabato 23 e domenica 24 marzo<\/strong>, oltre alle matin\u00e9e de<strong>l 25 e 26 marzo<\/strong>. Il Festival, denominato della \u201c<strong>Scienza e della Curiosit\u00e0<\/strong>\u201d, ha lo scopo di <strong>divulgare la conoscenza scientifica e le tematiche ad essa correlate<\/strong>, offrendo la possibilit\u00e0 di incontrare <strong>scienziati, youtubers, docenti universitari ed appassionati del campo.<\/strong><\/p>\n<p>Nel Parco che lo ospita sar\u00e0 possibile assistere ad un <strong>gran numero di eventi<\/strong>: oltre alle <strong>conferenze<\/strong> infatti, sono allestite delle sale per <strong>mostre<\/strong> ed esposizioni a tema scientifico e tecnologico.<\/p>\n<p><strong>L\u2019inaugurazione \u00e8 prevista domani, sabato 23 marzo, alle ore 10:00<\/strong> ed offrir\u00e0 una serie di incontri con esperti ed attivit\u00e0 coinvolgenti adatte a tutte le et\u00e0. Un programma ricchissimo: <strong>il primo intervento alle 11:00<\/strong> sar\u00e0 dedicato agli appassionati dello spazio, con la presenza di Davide Calcagno di Argotec, prestigiosa azienda di Ingegneria Spaziale Italiana, il quale dialogher\u00e0 con Alfredo Garro del Dipartimento di Ingegneria Informatica dell\u2019Universit\u00e0 della Calabria e Francesco Valentini, del Dipartimento di Fisica.<\/p>\n<p>A chiudere la serie di interventi della prima giornata, quello di Stefano Gandelli, content creator del famoso profilo Instagram divulgativo Geopop, che alle 19:00 affronter\u00e0 il tema delicato della divulgazione scientifica tra fake news e complotti, offrendo una prospettiva illuminante sulla comunicazione della scienza.<\/p>\n<p><strong> Domenica 24 sar\u00e0 dedicata all\u2019Intelligenza Artificiale<\/strong>: il primo talk sar\u00e0 a cura di Carmine Dodaro, professore associato del dipartimento di Matematica ed Informatica, vincitore prestigioso premio \u201cMarco Somalvico\u201d dell\u2019Associazione italiana per l\u2019Intelligenza Artificiale (Aiia), seguito alle 12:00 dell\u2019intervento \u201cOltre l\u2019hype\u201d dell\u2019Associazione Verde Binario e alle 17:00 dell\u2019artista Alessio Ciaffi con \u201cA.I. Art: Visioni di una tecnologia maleducata\u201d. Alle 15:00 un intervento dedicato alla ricostruzione dei dinosauri e degli animali preistorici con Davide Bonadonna, paleoartista italiano, ed Anna Giamborino, presidente dell\u2019Associazione Paleontologica e Paleoartistica Italiana A.P.P.I.<\/p>\n<p>Nel percorso espositivo dell\u2019evento, il<strong> pubblico potr\u00e0 visitare le tante postazioni<\/strong> curate da esperti appartenenti al mondo della scienza, con la partecipazione di musei e realt\u00e0 impegnate attivamente nella valorizzazione del territorio calabrese, tra cui il Comune di Papasidero che presenter\u00e0 all\u2019evento due calchi degli ormai iconici resti scheletrici rinvenuti nella celebre Grotta del Romito.<\/p>\n<p><strong>Non mancheranno poi le riproduzioni di imponenti creature preistoriche<\/strong>: all\u2019interno del percorso, infatti sar\u00e0 possibile ammirare la riproduzione a grandezza naturale di un rinoceronte lanoso e di un ittiosauro, un rettile marino preistorico. Saranno allestite inoltre diverse mostre fotografiche fra le quali spiccano \u201cChi ha paura dei ragni?\u201d di Pierluigi Rizzo e \u201cI.A. e Io\u201d a cura dell\u2019Associazione Fotografica \u201cLadri di Luce\u201d. <strong>Ospiti speciali del festival Amalia Ercoli Finzi,<\/strong> la prima donna a laurearsi <strong>in Ingegneria Aeronautica<\/strong> in Italia, esperta di ingegneria aerospaziale, insieme a sua figlia <strong>Elvina Finzi<\/strong>, <strong>ingegnera nucleare,<\/strong> dirigente presso Luxottica. Il loro intervento \u201cSei un universo: Genere. Generazioni. Scienza\u201d, sar\u00e0 dedicato al ruolo delle ragazze e delle donne nella scienza e nelle discipline STEM e moderato da Alessia Tuselli, sociologa, ricercatrice post doc presso il Centro Studi Interdisciplinari di Genere dell\u2019Universit\u00e0 di Trento.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>RENDE &#8211; Quattro giornate dedicate al mondo della scienza e della tecnologia al Parco Acquatico di Rende, con sale espositive e mostre per grandi e piccini. Torna la terza edizione del &#8220;Pensa Tu&#8221; nelle giornate di sabato 23 e domenica 24 marzo, oltre alle matin\u00e9e del 25 e 26 marzo. Il Festival, denominato della \u201cScienza [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":225688,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563],"tags":[19],"class_list":["post-225685","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/225685","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=225685"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/225685\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/225688"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=225685"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=225685"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=225685"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}