{"id":225793,"date":"2024-03-19T11:19:26","date_gmt":"2024-03-19T10:19:26","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=225793"},"modified":"2024-03-19T11:20:44","modified_gmt":"2024-03-19T10:20:44","slug":"escavatore-in-fiamme-a-guardia-piemontese-si-indaga-sulla-matrice","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/escavatore-in-fiamme-a-guardia-piemontese-si-indaga-sulla-matrice\/","title":{"rendered":"Escavatore in fiamme a Guardia Piemontese, si indaga sulla matrice"},"content":{"rendered":"<p>GUARDIA PIEMONTESE (CS) &#8211; Era parcheggiato all\u2019ingresso della zona Marina, sull\u2019ex Statale 18, a Guardia Piemontese, nei pressi del tracciato ferroviario. Il mezzo, un escavatore, \u00e8 di propriet\u00e0 di una <strong>ditta impegnata nei lavori lungo la linea ferroviaria<\/strong>, ed \u00e8 andato parzialmente distrutto. Per spegnere l&#8217;incendio, divampato nella tarda serata di ieri, i vigili del fuoco hanno lavorato per circa un&#8217;ora, anche per mettere in sicurezza l&#8217;area. Intanto i carabinieri indagano sulla matrice e le <strong>ipotesi fanno propendere per la natura dolosa del rogo.\u00a0<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>GUARDIA PIEMONTESE (CS) &#8211; Era parcheggiato all\u2019ingresso della zona Marina, sull\u2019ex Statale 18, a Guardia Piemontese, nei pressi del tracciato ferroviario. Il mezzo, un escavatore, \u00e8 di propriet\u00e0 di una ditta impegnata nei lavori lungo la linea ferroviaria, ed \u00e8 andato parzialmente distrutto. Per spegnere l&#8217;incendio, divampato nella tarda serata di ieri, i vigili del [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":173583,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[576],"tags":[19],"class_list":["post-225793","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tirreno","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/225793","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=225793"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/225793\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/173583"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=225793"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=225793"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=225793"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}