{"id":225821,"date":"2024-03-19T16:05:34","date_gmt":"2024-03-19T15:05:34","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=225821"},"modified":"2024-03-19T17:33:45","modified_gmt":"2024-03-19T16:33:45","slug":"rende-controlli-a-tappeto-dei-carabinieri-nella-zone-della-movida-sei-persone-denunciate","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/rende-controlli-a-tappeto-dei-carabinieri-nella-zone-della-movida-sei-persone-denunciate\/","title":{"rendered":"Rende, controlli a tappeto dei Carabinieri nella zone della movida: sei persone denunciate"},"content":{"rendered":"<div id=\"articolo\" class=\"uk-panel uk-margin\">\n<p>RENDE &#8211; Avevamo scritto della situazione difficile che si sta vivendo a Rende nelle ultime settimane a causa della crescente situazione anche di<a href=\"https:\/\/quicosenza.it\/news\/area-urbana\/cosenza\/rende-furti-dauto-baby-gang-risse-tra-giovani-e-allarme-criminalita\" target=\"_blank\" rel=\"noopener\"> microcriminalit\u00e0<\/a> soprattutto tra i giovani. I carabinieri hanno effettuato una serie di controlli a tappeto in tutta la zona maggiormente frequentata dai giovani. I risultati dei controlli hanno portato ad oltre <strong>110 persone identificate, 6 denunciate, 64 veicoli controllati e tre documenti di guida ritirati<\/strong>. Inoltre <strong>3 i giovani segnalati alla Prefettura di Cosenza per uso personale di sostanza stupefacente<\/strong>.<\/p>\n<h3>Controlli nelle zone dalla movida di Rende<\/h3>\n<p>Un\u2019attivit\u00e0 che si \u00e8 concentrata soprattutto sulle<strong> aree della movida ove insistono i locali pubblici<\/strong> con maggior afflusso di giovani: bar, pub e ristoranti. Diverse infatti le segnalazioni pervenute al 112 di <strong>disturbo alla quiete pubblica<\/strong>\u00a0dovuti all\u2019<strong>assembramento di adolescenti, talvolta intenti ad abusare di bevande alcoliche<\/strong>, causando, inevitabilmente, schiamazzi nonch\u00e9 difficolt\u00e0 alla circolazione dei veicoli dei residenti.<\/p>\n<p>I Carabinieri sono intervenuti a Rende nelle<strong> zone di via Marconi, Arcavacata, via Rossini e Piazza Santo Sergio con il compito primario di arginare le manifestazioni di comportamenti illegali e ricondurre nell\u2019alveo della legalit\u00e0 i luoghi di divertimento<\/strong>. L\u2019attivit\u00e0 \u00e8 stata coadiuvata anche dai reparti specializzati del N.I.L (Nucleo Ispettorato del Lavoro) e del N.A.S. (Nucleo Antisofisticazione e Sanit\u00e0) di Cosenza.<\/p>\n<h3>Alcool e stupefacenti: due denunce<\/h3>\n<p>Nel corso dei controlli della circolazione stradale sono stati\u00a0<strong>denunciati due soggetti<\/strong>\u00a0<strong>per guida in stato d\u2019ebbrezza alcolica<\/strong>. Questi, fermati durante i posti di controllo mentre erano alla guida delle rispettive autovetture, sono stati sottoposti ad accertamento etilometrico il quale ha dato esito positivo tanto che <strong>il tasso alcolemico riscontrato era superiore ai limiti previsti dalla legge<\/strong>. Uno di questi, aveva anche<strong> causato un sinistro stradale autonomo<\/strong>. Per tale motivo sono state ritirate le patenti di guida mentre le autovetture sono state affidate a persone idonee alla guida. I Carabinieri di Luzzi (CS) invece hanno segnalato alla Prefettura di Cosenza\u00a0<strong>tre giovanissimi<\/strong>\u00a0di et\u00e0 compresa tra i 18 e i 24 anni,<strong>\u00a0per uso personale di sostanze stupefacenti<\/strong>. I militari dell\u2019Arma infatti, hanno sequestrato complessivamente circa<strong>\u00a03 grammi di \u201chashish\u201d.<\/strong><\/p>\n<h3>Controlli nelle attivit\u00e0 commerciali: lavoratori in nero<\/h3>\n<p>Tra le verifiche effettuate nel Comune Rendese, rientrano anche alcuni<strong>\u00a0esercizi di ristorazione,<\/strong>\u00a0ispezionati dai militari del NIL i quali, all\u2019esito del controllo, in un caso hanno sorpreso ben\u00a0<strong>due lavoratori irregolari in nero<\/strong>, in violazione dell\u2019art. 3 del D.L 12\/2002 superando il 10% del personale occupato in nero rispetto alla forza lavoro presente, per cui \u00e8 stata applicata la sanzione pecuniaria complessiva di euro\u00a0<strong>7.800<\/strong>\u00a0(settemilaottocento) e la\u00a0<strong>sospensione dell\u2019attivit\u00e0 imprenditoriale<\/strong>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-204073 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/carabinieri-cosenza-rende.jpg\" alt=\"carabinieri cosenza rende\" width=\"559\" height=\"346\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/carabinieri-cosenza-rende.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/carabinieri-cosenza-rende-300x186.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/carabinieri-cosenza-rende-768x475.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/carabinieri-cosenza-rende-150x93.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/carabinieri-cosenza-rende-696x431.jpg 696w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/carabinieri-cosenza-rende-679x420.jpg 679w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2023\/06\/carabinieri-cosenza-rende-356x220.jpg 356w\" sizes=\"auto, (max-width: 559px) 100vw, 559px\" \/><\/p>\n<p>In un altro locale invece, i Carabinieri del Nucleo Ispettorato del lavoro di Cosenza, oltre ad aver sorpreso\u00a0<strong>un lavoratore irregolare in nero<\/strong>, in violazione dell\u2019art. 3 del D.L 12\/2002 per cui \u00e8 stata applicata la sanzione pecuniaria complessiva di\u00a0<strong>euro 8.900<\/strong>\u00a0(ottomilanovecento) e la\u00a0<strong>sospensione dell\u2019attivit\u00e0 imprenditoriale<\/strong>, \u00e8 stata altres\u00ec riscontrata la mancata redazione del \u201cDVR\u201d inerente l\u2019attivit\u00e0 espletata. Lo stesso controllo \u00e8 stato esperito anche nel Comune di Bisignano dove \u00e8 stata elevata una sanzione di <strong>euro 6.400<\/strong>\u00a0(<strong>seimilaquattrocento<\/strong>) per un lavoratore in nero e mancata redazione del D.V.R.<\/p>\n<h3>Alimenti privi di etichettatura o tracciabilit\u00e0: multa da 1.500 euro<\/h3>\n<p>Mentre il personale del NAS ha riscontrato la presenza di generi alimentari privi di qualsiasi etichettatura o elemento di tracciabilit\u00e0, sottoposti a sequestro amministrativo ed applicando la corrispettiva sanzione di\u00a0<strong>euro 1.500<\/strong> (millecinquecento).<\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>RENDE &#8211; Avevamo scritto della situazione difficile che si sta vivendo a Rende nelle ultime settimane a causa della crescente situazione anche di microcriminalit\u00e0 soprattutto tra i giovani. I carabinieri hanno effettuato una serie di controlli a tappeto in tutta la zona maggiormente frequentata dai giovani. I risultati dei controlli hanno portato ad oltre 110 [&hellip;]<\/p>\n","protected":false},"author":55,"featured_media":225823,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,44],"tags":[19],"class_list":["post-225821","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-rende","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/225821","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=225821"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/225821\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/225823"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=225821"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=225821"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=225821"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}