{"id":226143,"date":"2024-03-23T12:00:23","date_gmt":"2024-03-23T11:00:23","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=226143"},"modified":"2024-03-23T13:00:50","modified_gmt":"2024-03-23T12:00:50","slug":"treni-fine-settimana-difficile-per-chi-viaggia-da-oggi-24-ore-di-sciopero-nazionale","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/treni-fine-settimana-difficile-per-chi-viaggia-da-oggi-24-ore-di-sciopero-nazionale\/","title":{"rendered":"Treni, fine settimana difficile per chi viaggia. Da oggi 24 ore di sciopero nazionale"},"content":{"rendered":"<p>ROMA &#8211; Si annuncia un<strong> fine settimana di disagi per chi deve viaggiare in treno<\/strong>. A partire dalle 21.00 di oggi, sabato 23 marzo, sono state proclamate 24 ore di agitazione da alcune sigle sindacali autonome <b>SGB, USB e CUB Trasporti <\/b>che riguarda il personale di bordo e di macchina di Gruppo Fs (coinvolti non solo i regionali ma anche Intercity e Frecce di Trenitalia), ma anche <strong>Italo, Trenord e Tper<\/strong>. Stop alla circolazione ferroviaria fino alle 21.00 di domenica 24 marzo, a eccezione delle tratte protette.<\/p>\n<p>&#8220;<strong>Gli scioperi nazionali potrebbero avere un impatto significativo sulla circolazione ferroviaria e comportare cancellazioni totali e parziali di Frecce, Intercity e treni Regionali di Trenitalia<\/strong>. Gli effetti, in termini di cancellazioni e ritardi, potranno verificarsi anche prima e protrarsi oltre l&#8217;orario di termine degli scioperi&#8221; sottolinea la nota del Gruppo FS.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-175070 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/Paola-Treni-stazione-frecciarossa-2.jpg\" alt=\"Paola Treni stazione frecciarossa\" width=\"560\" height=\"351\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/Paola-Treni-stazione-frecciarossa-2.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/Paola-Treni-stazione-frecciarossa-2-300x188.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2022\/12\/Paola-Treni-stazione-frecciarossa-2-768x481.jpg 768w\" sizes=\"auto, (max-width: 560px) 100vw, 560px\" \/><\/p>\n<div class=\"textComponent aem-GridColumn aem-GridColumn--default--12\">\n<div>\n<p>L\u2019agitazione sindacale pu\u00f2 comportare modifiche al servizio anche prima dell\u2019inizio e dopo la sua conclusione.\u00a0I<strong> viaggiatori potranno richiedere il rimborso del biglietto<\/strong> secondo quanto previsto dalle Condizioni Generali di Trasporto di ciascun vettore, consultabili sul sito delle singole Imprese Ferroviarie.\u00a0 Informazioni su collegamenti e servizi attraverso l<strong>\u2019app Trenitalia, la sezione Infomobilit\u00e0<\/strong> del sito di Ferrovie, sito trenitaliatper.it,<strong> il numero verde gratuito 800\/892021<\/strong>, oltre che nelle biglietterie e presso il personale di assistenza clienti. Restano garantite alcune corse nazionali e i treni regionali negli orarie pi\u00f9 utilizzati dai pendolari, tra le 6 e le 9 e tra le 18 e le 21. Qui l<a href=\"https:\/\/www.trenitalia.com\/content\/dam\/tcom\/allegati\/trenitalia_2014\/informazioni\/TABELLA_B_Treni_garantiti_DPLH.pdf\" rel=\"noopener\">&#8216;elenco<\/a> dei treni comunque garantiti anche in caso di sciopero.<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>ROMA &#8211; Si annuncia un fine settimana di disagi per chi deve viaggiare in treno. A partire dalle 21.00 di oggi, sabato 23 marzo, sono state proclamate 24 ore di agitazione da alcune sigle sindacali autonome SGB, USB e CUB Trasporti che riguarda il personale di bordo e di macchina di Gruppo Fs (coinvolti non [&hellip;]<\/p>\n","protected":false},"author":55,"featured_media":226145,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[19],"class_list":["post-226143","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/226143","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=226143"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/226143\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/226145"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=226143"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=226143"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=226143"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}