{"id":226260,"date":"2024-03-25T09:44:04","date_gmt":"2024-03-25T08:44:04","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=226260"},"modified":"2024-03-25T09:44:04","modified_gmt":"2024-03-25T08:44:04","slug":"ritardo-volo-verona-lamezia-terme-risarcite-mamma-e-figlia-di-cosenza","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/ritardo-volo-verona-lamezia-terme-risarcite-mamma-e-figlia-di-cosenza\/","title":{"rendered":"Ritardo volo Verona-Lamezia Terme, risarcite mamma e figlia di Cosenza"},"content":{"rendered":"<p>COSENZA &#8211; La sentenza \u00e8 stata emessa dall&#8217;Ufficio del Giudice di Pace di Verona. I fatti risalgono al 6 maggio scorso relativamente ad un ritardo <strong>del volo Ryanair Verona &#8211; Lamezia Terme<\/strong>. I due passeggeri, mamma e figlia di Cosenza, avendo subito un ritardo superiore a tre ore rispetto all&#8217;orario previsto, hanno richiesto un&#8217;indennit\u00e0 o una compensazione pecuniaria come previsto dalla normativa comunitaria.<\/p>\n<p>Il giudice ha quindi stabilito che, in conformit\u00e0 al Regolamento CE 261\/04, ai passeggeri spetta una compensazione pecuniaria di <strong>250 euro<\/strong> ciascuno <strong>per ritardi superiori a tre ore<\/strong>. La sentenza ha accolto la richiesta dei passeggeri, <strong>condannando la compagnia aerea<\/strong> al pagamento di 250 euro per ciascun passeggero, per un totale di <strong>500 euro.<\/strong><\/p>\n<p>Questa decisione rappresenta un importante passo avanti nella tutela dei diritti dei passeggeri aerei in Italia, sottolineando l&#8217;importanza di una rigorosa applicazione delle normative europee in materia di trasporti aerei e garantendo una maggiore trasparenza e responsabilit\u00e0 da parte delle compagnie aeree nei confronti dei propri clienti. In un settore in cui i ritardi e le cancellazioni possono avere un impatto significativo sulla vita dei viaggiatori, questa sentenza invia un chiaro segnale alle compagnie aeree affinch\u00e9 rispettino i diritti dei passeggeri e garantiscano un servizio affidabile e puntuale.<\/p>\n<p>\u00abItaliaRimborso accoglie con soddisfazione la sentenza emessa dal Giudice di Pace di Verona \u2013 affermano dalla claim company \u2013. La decisione rappresenta un importante <strong>riconoscimento dei diritti dei passeggeri aerei<\/strong> e conferma la responsabilit\u00e0 delle compagnie aeree nel garantire un servizio affidabile e puntuale. Siamo soddisfatti del pronunciamento del Giudice di Pace di Verona che ha riconosciuto il diritto dei passeggeri coinvolti a ricevere un&#8217;adeguata compensazione per il ritardo subito sul volo. Questa decisione conferma che le compagnie aeree devono rispettare le normative europee in materia di trasporti aerei e garantire un servizio di qualit\u00e0 ai propri clienti\u00bb.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; La sentenza \u00e8 stata emessa dall&#8217;Ufficio del Giudice di Pace di Verona. I fatti risalgono al 6 maggio scorso relativamente ad un ritardo del volo Ryanair Verona &#8211; Lamezia Terme. I due passeggeri, mamma e figlia di Cosenza, avendo subito un ritardo superiore a tre ore rispetto all&#8217;orario previsto, hanno richiesto un&#8217;indennit\u00e0 o [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":226261,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42],"tags":[19],"class_list":["post-226260","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/226260","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=226260"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/226260\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/226261"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=226260"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=226260"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=226260"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}