{"id":226301,"date":"2024-03-25T15:20:59","date_gmt":"2024-03-25T14:20:59","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=226301"},"modified":"2024-03-25T15:24:01","modified_gmt":"2024-03-25T14:24:01","slug":"blocco-operatorio-dellannunziata-tra-garze-dimenticate-nelladdome-e-infermieri-in-fuga","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/blocco-operatorio-dellannunziata-tra-garze-dimenticate-nelladdome-e-infermieri-in-fuga\/","title":{"rendered":"\u00abBlocco operatorio dell&#8217;Annunziata tra garze dimenticate nell&#8217;addome e infermieri in fuga\u00bb"},"content":{"rendered":"<p>COSENZA &#8211; &#8220;Io, questa volta, non voglio partire, subito, lancia in resta all\u2019indirizzo del Commissario straordinario dell\u2019azienda ospedaliera di Cosenza. Questa volta, voglio provare a ragionare con il dott. De Salazar, adoperando, inizialmente, il dizionario della pacatezza dialettica. E gli prospetto una questione, altamente seria e delicata, la cui sostanza, immagino, sia a sua perfetta conoscenza, e rispetto, alla quale, per\u00f2, si registra, per non dire altro, una colposa inerzia. Parler\u00f2 del <strong>Blocco operatorio unico dell\u2019Annunziata<\/strong>&#8220;. Cos\u00ec esordisce in una nota il consigliere comunale e consigliere provinciale di Cosenza <strong>Giuseppe Ciacco<\/strong>.<\/p>\n<p>Sgombrando, sin da subito, il terreno da ogni malizioso equivoco: sia ben chiaro, il mio indice non \u00e8 puntato in direzione dei<strong> medici, degli infermieri e degli operatori socio-sanitari,<\/strong> che, &#8211; prosegue Ciacco &#8211;\u00a0 in quel blocco operatorio, quotidianamente, stanno in trincea con dedizione e abnegazione. perch\u00e9, assai verosimilmente, costoro sono, loro stessi, <strong>vittime incolpevoli di potenziali e malefiche disfunzioni coordinative<\/strong>. E io, proprio sulle disfunzioni coordinative, focalizzer\u00f2 la mia attenzione, rappresentando i fatti, come \u00e8 mio costume, con pertinente cognizione di causa.<\/p>\n<h4><strong>&#8220;Garze nell&#8217;addome e infermieri in fuga: perch\u00e9 De Salazar \u00e8 immobile?&#8221;<\/strong><\/h4>\n<p>&#8220;E, allora, &#8211; incalza Ciacco &#8211; formulo al dott. De Salazar alcuni sintomatici punti di domanda. Dott. De Salazar, \u00e8 vero che, in quel blocco operatorio, pu\u00f2 capitare, anche di recente, che, <strong>all\u2019esito di un intervento chirurgico, nell\u2019addome di un paziente, venga dimenticata una garza di 5 cm, poi rimossa, sottoponendo lo stesso paziente, magari previa esecuzione di tomografia computerizzata, a intervento chirurgico d\u2019urgenza?<\/strong> E\u2019 vero che, nel blocco operatorio dell\u2019Annunziata, pu\u00f2 capitare che la conta delle garze, in palese violazione delle linee guida ministeriali, venga effettuata &#8211; incredibile a dirsi e a credersi &#8211; dal solo operatore socio-sanitario e, per di pi\u00f9, in assoluto silenzio? E\u2019 vero che, in quel blocco operatorio, pu\u00f2 capitare che, nel corso di un intervento d\u2019urgenza, un infermiere abbandoni la sala operatoria anzi tempo, quando l\u2019intervento non \u00e8, neanche, a met\u00e0 della relativa durata di esecuzione? E\u2019 vero che, in quel blocco, pu\u00f2 capitare che, il registro operatorio di una sala, assegni a un infermiere il dono dell\u2019ubiquit\u00e0, attestandone la presenza in quella sala, mentre, in realt\u00e0, nello stesso spazio temporale, quell\u2019infermiere era presente, in un\u2019altra sala? E\u2019 vero che diversi, non uno, ma forse<strong> 4\/5 infermieri, in servizio presso quel blocco operatorio, nelle ultime settimane, hanno avanzato formale richiesta di trasferimento presso altre Unit\u00e0 operative?<\/strong> E, quali sarebbero le motivazioni sottese a cotanto agognato <strong>esodo di massa?<\/strong> Forse <strong>una manifesta e dispotica inettitudine organizzativa?<\/strong><\/p>\n<p>E, allora, puta caso che le circostanze che io, qui e ora, ho dedotto, siano vere, Lei, dott. De Salazar, perch\u00e9 rimane mano nella mano? <strong>Quali sono le arcane ragioni, dott. De Salazar, del suo immobilismo<\/strong>. Chi e che cosa Le impedisce di intervenire? Eppure, il blocco operatorio \u00e8 la cellula strategica di ogni Ospedale, nella quale le misure di sicurezza dovrebbero essere osservate con parossistico rigore, bandendo ogni compiacente lassismo e recidendo ogni ambiguo cordone protezionistico. La sala operatoria rappresenta, statisticamente, uno degli ambienti sanitari con i pi\u00f9 alti livelli di rischio clinico. E, allora, \u00e8, semplicemente, scellerato gestire un blocco operatorio con dissennata frivolezza. E sarebbe, anche, scellerato, se qualcuno tentasse di organizzare audits farlocchi, spregiudicatamente, finalizzati a camuffare la dissennata frivolezza. E, tuttavia, \u00e8, altrettanto e ugualmente, scellerato consentire una siffatta gestione.<\/p>\n<p>Dott. De Salazar,<strong> se la vicenda della garza fosse vera &#8211; e io mi auguro che non lo sia -, sarebbe, drammaticamente, superato ogni limite di guardia.<\/strong> Lei, lo sa che cosa dice la Corte di Cassazione, a proposito della ritenzione di una garza nel sito chirurgico? Dice, esattamente, questo: \u201ctrattasi di un fenomeno sentinella, ad altissima rilevanza sotto il profilo della colpa grave, causativo, non raramente, di esito infausto\u201d. Una definizione da far accapponare la pelle! La misura \u00e8 colma. La vita dei pazienti, &#8211; conclude Ciacco &#8211; sull\u2019altare di intollerabili atteggiamenti pavoneggianti, non pu\u00f2 essere, cinicamente, trasfigurata in una selvaggia roulette russa. Occorre restituire onore e dignit\u00e0 all\u2019Azienda ospedaliera di Cosenza. Dott. De Salazar, tragga le debite conseguenze&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; &#8220;Io, questa volta, non voglio partire, subito, lancia in resta all\u2019indirizzo del Commissario straordinario dell\u2019azienda ospedaliera di Cosenza. Questa volta, voglio provare a ragionare con il dott. De Salazar, adoperando, inizialmente, il dizionario della pacatezza dialettica. E gli prospetto una questione, altamente seria e delicata, la cui sostanza, immagino, sia a sua perfetta [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":202033,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563],"tags":[19],"class_list":["post-226301","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/226301","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=226301"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/226301\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/202033"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=226301"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=226301"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=226301"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}