{"id":226391,"date":"2024-03-26T15:35:14","date_gmt":"2024-03-26T14:35:14","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=226391"},"modified":"2024-03-26T15:37:36","modified_gmt":"2024-03-26T14:37:36","slug":"diamantecs-ennesimo-rifiuto-ad-installare-le-antenne-4g-e-5g-il-comune-denunciato-alla-corte-dei-conti","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/diamantecs-ennesimo-rifiuto-ad-installare-le-antenne-4g-e-5g-il-comune-denunciato-alla-corte-dei-conti\/","title":{"rendered":"A Diamante le antenne della discordia, ennesimo &#8216;no&#8217; del Comune: denunciato alla Corte dei Conti"},"content":{"rendered":"<p>COSENZA \u2013 Il Comune di Diamante (CS) finisce sotto i riflettori della Procura della Repubblica e della Corte dei Conti per il <strong>reiterato rifiuto di autorizzare l\u2019installazione sul suo territorio di due infrastrutture per le telecomunicazioni mobili<\/strong>. Il <strong>TAR Calabria<\/strong> ha ritenuto che i numerosi provvedimenti assunti dal Comune abbiano violato l\u2019obbligo in capo a un\u2019amministrazione pubblica di conformarsi ai provvedimenti dell\u2019autorit\u00e0 giudiziaria e<strong> ha trasmesso alla Procura della Repubblica di Paola il fascicolo relativo all\u2019ennesimo rifiuto.<\/strong> Nel frattempo, la vicenda \u00e8 anche all\u2019attenzione della <strong>Corte dei Conti<\/strong> per l\u2019accertamento di eventuali danni erariali.<\/p>\n<p>Sar\u00e0 quindi la magistratura penale e contabile ad approfondire i contorni di una vicenda che, <strong>dopo ben 8 condanne<\/strong> in sede amministrativa al Comune di Diamante (6 sentenze\/ordinanze del TAR e 2 del Consiglio di Stato) <strong>con 5 condanne alle spese (per un totale di oltre 10mila euro)<\/strong>, \u00e8 divenuta emblematica della difficolt\u00e0 di portare su alcuni territori infrastrutture digitali e condivise,<strong> in grado di abilitare servizi 4G e 5G<\/strong> degli operatori di telecomunicazione.<\/p>\n<h3><strong>Antenne 4G e 5G: Diamante si oppone dal 2020<\/strong><\/h3>\n<p>La trasmissione degli atti alla Procura della Repubblica di Paola per l\u2019inosservanza dei provvedimenti dell\u2019Autorit\u00e0 (ex art. 650 del Codice penale) \u00e8 stato deciso dal TAR Calabria lo scorso 15 febbraio dopo che, a partire dal<strong> maggio 2020,<\/strong> i<strong>l comune di Diamante ha rifiutato per ben otto volte di autorizzare l\u2019inizio dei lavori a INWIT<\/strong> per la realizzazione di impianti di telecomunicazioni, sulla base di regolamenti comunali poi ritenuti illegittimi dal TAR stesso.<\/p>\n<p>Il comune di Diamante <strong>ha continuato a non conformarsi alle sei pronunce a suo sfavore da parte del Tar stesso<\/strong> (a cui INWIT aveva fatto ricorso) <strong>e alle due pronunce del Consiglio di Stat<\/strong>o (a cui il Comune si \u00e8 appellato per 3 volte dopo la bocciatura del suo operato da parte del TAR). I giudici amministrativi hanno infatti sempre ritenuto <strong>illegittimo il rifiuto del Comune<\/strong> e al contempo affermato la fondatezza delle ragioni di INWIT che, in quanto gestore di un pubblico servizio, ha di fatto l\u2019obbligo di realizzare la copertura del territorio italiano con servizi di telecomunicazione elettronica. Pur conoscendo o dovendo conoscere il quadro giuridico che configura l\u2019installazione di infrastrutture per le telecomunicazioni mobili come opere di urbanizzazione primaria, prioritarie in quanto aventi caratteri di pubblica utilit\u00e0, il Comune di Diamante ha invece reiterato un ingiustificato comportamento ostruzionistico.<\/p>\n<p>Mentre a livello nazionale sono state gi\u00e0 adottate numerose semplificazioni, a livello locale ancora troppi regolamenti comunali non consentono un passo adeguato nella realizzazione delle infrastrutture, limitandone la localizzazione in aree non utili al fine della copertura, come cimiteri o discariche. Nel caso del Comune di Diamante, si \u00e8 addirittura arrivati al paradosso di impedirne la costruzione, con un<strong> evidente ritardo nella realizzazione di infrastrutture fondamentali per la digitalizzazione del Paese<\/strong> e per la riduzione del digital divide. In generale, negli ultimi due anni circa il 13% delle autorizzazioni richieste da INWIT \u00e8 diventato oggetto di contenzioso con le amministrazioni locali.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA \u2013 Il Comune di Diamante (CS) finisce sotto i riflettori della Procura della Repubblica e della Corte dei Conti per il reiterato rifiuto di autorizzare l\u2019installazione sul suo territorio di due infrastrutture per le telecomunicazioni mobili. Il TAR Calabria ha ritenuto che i numerosi provvedimenti assunti dal Comune abbiano violato l\u2019obbligo in capo a [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":140995,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[576],"tags":[19],"class_list":["post-226391","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-tirreno","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/226391","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=226391"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/226391\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/140995"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=226391"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=226391"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=226391"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}