{"id":22657,"date":"2013-05-23T07:19:34","date_gmt":"2013-05-23T05:19:34","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=22657"},"modified":"2023-01-17T13:20:18","modified_gmt":"2023-01-17T12:20:18","slug":"8909-filmati-dalle-iene-forestali-calabresi-aperta-inchiesta","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/8909-filmati-dalle-iene-forestali-calabresi-aperta-inchiesta\/","title":{"rendered":"Filmati dalle IENE forestali Calabresi, aperta inchiesta"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"color: #000000;\">CATANZARO &#8211; Dopo il servizio andato in onda alla <strong>trasmissione tv &#8220;Le Iene&#8221;<\/strong> che mostrava diversi operai <strong>forestali assenti<\/strong> dai posti di lavoro durante l&#8217;<strong>orario di servizio<\/strong>,<\/span><\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\"> e la conseguente denuncia del Commissario dell&#8217;Afor Calabria, la Procura della Repubblica di Catanzaro ha aperto in proposito un fascicolo d&#8217;indagine. Sara&#8217; il sostituto procuratore Carlo Villani a dirigere le investigazioni sui presunti casi di assenteismo, e come prima cosa il magistrato ha acquisito il video della trasmissione televisiva andata in onda su <strong>&#8220;Italia 1&#8221; il 14 aprile scorso<\/strong>. Proprio sulla base delle immagini contenute nel servizio gli inquirenti stanno procedendo all&#8217;identificazione degli operai forestali che durante l&#8217;orario di lavoro si trovavano altrove, <strong>dediti a tutt&#8217;altre faccende<\/strong>. A tal fine saranno acquisiti tutti i fogli di presenza dei cantieri interessati, la cui regolarita&#8217; sara&#8217; verificata con controlli incrociati. I presunti casi di <strong>assenteismo tra i forestali calabresi<\/strong> tornano alla ribalta della cronaca ad appena due giorni di distanza da quando, lunedi&#8217;, nell&#8217;ambito di una precedente inchiesta, il sostituto Villani ha emesso un avviso di conclusione indagini nei confronti di <strong>dieci operai dell&#8217;Afor accusati<\/strong>, a vario titolo, di truffa e falso aggravati per avere, secondo l&#8217;accusa, attestato falsamente la propria presenza in servizio nel cantiere Colle Ntopa di Magisano, nel catanzarese, mentre i carabinieri li avrebbero avvistati nel centro del paese &#8220;ciascuno impegnato &#8211; ha scritto il pubblico ministero &#8211; in faccende di natura privata&#8221;.<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">&nbsp;<\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">link al video delle IENE <a href=\"http:\/\/www.video.mediaset.it\/video\/iene\/puntata\/383805\/pelazza-forestali-in-calabria.html\" rel=\"noopener\">clicca<\/a><\/span><\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">&nbsp;<\/span><\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CATANZARO &#8211; Dopo il servizio andato in onda alla trasmissione tv &#8220;Le Iene&#8221; che mostrava diversi operai forestali assenti dai posti di lavoro durante l&#8217;orario di servizio,<\/p>\n","protected":false},"author":22,"featured_media":22658,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-22657","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/22657","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=22657"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/22657\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/22658"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=22657"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=22657"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=22657"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}