{"id":226766,"date":"2024-04-07T17:00:09","date_gmt":"2024-04-07T15:00:09","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=226766"},"modified":"2024-04-03T10:33:15","modified_gmt":"2024-04-03T08:33:15","slug":"lunical-punta-alla-formazione-sulla-mobilita-elettrica-e-leconomia-circolare","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/lunical-punta-alla-formazione-sulla-mobilita-elettrica-e-leconomia-circolare\/","title":{"rendered":"L&#8217;Unical punta alla formazione sulla mobilit\u00e0 elettrica e l&#8217;economia circolare"},"content":{"rendered":"<p>RENDE (CS) &#8211; E\u2019 allo start il master per l\u2019istruzione di alta qualit\u00e0 rivolto ai professionisti del futuro green gi\u00e0 dietro l\u2019angolo.<\/p>\n<p>Il Meec \u00e8 il primo <strong>master di secondo livello in mobilit\u00e0 elettrica ed economia circolare per neolaureati e lavoratori. <\/strong>Sar\u00e0 presentato <strong>gioved\u00ec 4 aprile, alle 15<\/strong>, nel palazzo della Provincia di Cosenza di piazza XV marzo, nel centro storico.<\/p>\n<p>La prima edizione del Meec accoglier\u00e0 fino a trenta\u00a0 partecipanti e, in base a una graduatoria di merito, verranno subito erogate (in tre tranche), <strong>borse di studio di 20mila euro <\/strong>ciascuna per dodici corsisti.<\/p>\n<p><em>Ai partecipanti sar\u00e0 conferito il titolo <\/em>di \u201cesperto in gestione di sistemi e strutture per la mobilit\u00e0 elettrica e l\u2019economia circolare\u201d.<\/p>\n<p>Il percorso formativo nasce da un progetto del <strong>Dimes dell\u2019Universit\u00e0 della Calabria<\/strong>, nel contesto dei patti territoriali per l\u2019alta formazione, finanziati dal Mur, ed \u00e8 rivolto a laureati in ingegneria, matematica, fisica, economia, economia aziendale, finanza, statistica e informatica, chimica.<\/p>\n<p>Un ruolo attivo \u00e8 svolto dalle imprese: attraverso la partecipazione ai moduli formativi e attraverso gli stage aziendali, ma anche per l\u2019assorbimento di nuovi profili professionali, necessari all\u2019evoluzione di un mondo a misura di veicolo elettrico. Un mondo che ha bisogno di diffusi e innovativi sistemi di carica, delle competenze per la manutenzione e la riparazione, di professionisti con competenze adeguate in materia di riciclo.<\/p>\n<p>La partnership del progetto \u00e8 di quelle che innescano rapporti immediati con le imprese, nel segno della <em>mission<\/em> dei Patti territoriali. Si tratta della <strong>Motus-E<\/strong>, la prima e principale associazione italiana costituita <strong>per accelerare il cambiamento verso la mobilit\u00e0 elettrica. <\/strong><\/p>\n<p><strong>In Motus-E fanno sistema, insieme con gli atenei, i principali marchi automobilistici, le industrie, i fornitori di energia, le imprese di servizio, i movimenti di opinione sulla sostenibilit\u00e0 ambientale.<\/strong><\/p>\n<p>L\u2019evento di presentazione del Meec 2023\/2024, gioved\u00ec 4 aprile, \u00e8 anche l\u2019occasione per fare il punto nazionale ed europeo sulla doppia tematica: la circolazione elettrica e il modello di produzione e consumo basato sul riciclo.<\/p>\n<p>I lavori saranno aperti dai saluti istituzionali di <strong>Rosaria Succurro<\/strong>, presidente della Provincia di Cosenza; seguir\u00e0 l\u2019intervento del direttore del master, il docente Unical <strong>Gregorio Cappuccino<\/strong>, che presenter\u00e0 l\u2019intero progetto con un intervento dal titolo: <em>\u201cL\u2019Unical e il patto con il territorio\u201d<\/em>. Per il governo regionale, l\u2019assessore allo Sviluppo economico <strong>Rosario Var\u00ec<\/strong>, interverr\u00e0 sul tema: <em>\u201cLa Regione a sostegno delle imprese e dei cittadini calabresi per la transizione ecologica\u201d. <\/em><\/p>\n<p>Previsti i contributi del docente Unical <strong>Piero Guido<\/strong>, co-responsabile del master, <em>La mobilit\u00e0 del futuro in Calabria \u00e8 gi\u00e0 realt\u00e0\u201d<\/em> e dei rappresentanti della partnership: <strong>Fabio Pressi<\/strong>, <em>\u201cMotus-E: l\u2019unione fa la forza\u201d<\/em>; <strong>Francesco Naso<\/strong>, <em>\u201cIl ruolo della formazione tra le opportunit\u00e0 e le sfide della E-Mobility\u201d<\/em>.<\/p>\n<p>Il dirigente regionale delle Ferrovie della Calabria, <strong>Aristide Vercillo Martino<\/strong>, far\u00e0 il punto su <em>\u201cASSTRA e la sfida della mobilit\u00e0 elettrica in Calabria\u201d<\/em>. In conclusione una storia di successo, quella della tenuta di \u201cSerragiumenta\u201d di Altomonte. <strong>Paolo Canonaco<\/strong> sar\u00e0 testimonial di una Calabria votata alla produzione enogastronomica biologica, al turismo esperienziale, allo sviluppo di realt\u00e0 produttive totalmente alimentate da energie rinnovabili.<\/p>\n<p>Varia e complessa la tematica al centro del progetto Unical.<\/p>\n<p><em>\u00abMobilit\u00e0 elettrica non significa soltanto il veicolo ad uso aziendale o privato, dall\u2019automobile, alla navetta, alla bici. C\u2019\u00e8 tutto un altro versante che riguarda i vari settori dell\u2019economia; basti pensare alle macchine, agli attrezzi, ai mezzi <\/em><em>off road<\/em><em> per la lavorazione in agricoltura e nelle industrie\u00bb, spiega l\u2019ingegnere Gregorio Cappuccino, docente di Elettronica del Dipartimento di ingegneria informatica, modellistica, elettronica e sistemistica. <\/em><\/p>\n<p><em>\u00abIn questo nuovo orizzonte si sta muovendo anche il settore pubblico. \u00a0Gli autobus elettrici hanno una crescente diffusione, del tutto inattesa; i droni verranno utilizzati molto presto, appena sar\u00e0 licenziato il relativo regolamento, per il trasporto di medicinali e di sacche ematiche da un ospedale a un altro\u00bb. <\/em><\/p>\n<p><em>Intorno al Meec c\u2019\u00e8 un ampio progetto per creare un <\/em><em>learning<\/em> <em>gateway<\/em><em> fisico del settore, cio\u00e8 un punto di riferimento e di scambio per le <\/em><em>best practices<\/em><em>.<\/em><\/p>\n<p><em>\u00abIl cambiamento, oltre ad essere un dato di fatto, \u00e8 un\u2019esigenza di mercato. Il futuro &#8211; dice ancora l\u2019ideatore e responsabile del master, &#8211; \u00e8 il recupero delle batterie dalle apparecchiature elettroniche e dagli autoveicoli e per arrivare preparati dobbiamo essere in grado di sfruttare a pieno il valore del riciclo. In questo campo si sta investendo moltissimo e sono interessati anche gli operatori locali. Per tutti questi motivi c\u2019\u00e8 assoluto bisogno di professionalit\u00e0 ben formate, con competenze tecniche, normative e manageriali<\/em>\u00bb.<\/p>\n<p><strong>Le domande di richiesta di partecipazione al Meec devono essere inoltrate entro il prossimo 30 aprile.<\/strong> Le borse di studio copriranno i costi di iscrizione (pari a 1.900 euro a iscritto, mille per gli uditori), per circa met\u00e0 dei corsisti, fornendo un sostegno finanziario importante agli studenti e offrendo loro un ulteriore incentivo all\u2019accesso alla formazione di alto livello.<\/p>\n<p>Tutte le informazioni utili possono essere visionate all\u2019indirizzo web <a href=\"https:\/\/meec.dimes.unical.it\" rel=\"noopener\">https:\/\/meec.dimes.unical.it<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>RENDE (CS) &#8211; E\u2019 allo start il master per l\u2019istruzione di alta qualit\u00e0 rivolto ai professionisti del futuro green gi\u00e0 dietro l\u2019angolo. Il Meec \u00e8 il primo master di secondo livello in mobilit\u00e0 elettrica ed economia circolare per neolaureati e lavoratori. Sar\u00e0 presentato gioved\u00ec 4 aprile, alle 15, nel palazzo della Provincia di Cosenza di [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":226767,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[7],"tags":[19],"class_list":["post-226766","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-universita","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/226766","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=226766"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/226766\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/226767"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=226766"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=226766"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=226766"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}