{"id":227264,"date":"2024-04-11T09:30:55","date_gmt":"2024-04-11T07:30:55","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=227264"},"modified":"2024-04-08T15:16:15","modified_gmt":"2024-04-08T13:16:15","slug":"gerace-porta-del-sole-ecco-i-9-interventi-che-trasformeranno-il-borgo-in-centro-turistico","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/gerace-porta-del-sole-ecco-i-9-interventi-che-trasformeranno-il-borgo-in-centro-turistico\/","title":{"rendered":"&#8220;Gerace Porta del Sole&#8221;: ecco i 9 interventi che trasformeranno il borgo in centro turistico"},"content":{"rendered":"<p>GERACE (RC) &#8211; Sono mesi intensi per la perla dello Jonio, al centro dell\u2019attenzione per gli interventi di riqualificazione ad ampio raggio che le daranno un nuovo volto. I lavori rientrano nel grande progetto <strong>\u201c<a href=\"https:\/\/quicosenza.it\/news\/calabria\/gerace-porta-del-sole-il-grande-progetto-che-cambiera-volto-al-meraviglioso-borgo-della-calabria\" target=\"_blank\" rel=\"noopener\">Gerace, Porta del sole<\/a>\u201d, <\/strong>messo in piedi a seguito d<strong>i un finanziamento di 20 milioni di euro del Pnrr del Ministero della cultura<\/strong> e che vede la Regione Calabria al fianco del Comune di Gerace. <strong>L\u2019antica e caratteristica cittadina si appresta a diventare un centro turistico<\/strong> la cui struttura ricettiva e alberghiera si presenter\u00e0 in una veste del tutto nuova, come per esempio \u201cl\u2019albergo diffuso\u201d.<\/p>\n<h3>Cosa comporter\u00e0 il progetto per Gerace<\/h3>\n<p>\u201cGerace, Porta del sole\u201d \u00e8 un progetto, quindi, volto a <strong>rendere il borgo ionico meta ancora pi\u00f9 appetibile in modo innovativo e originale.<\/strong> Il progetto punta infatti a una rigenerazione culturale e sociale di Gerace, attraverso un nuovo modello di sviluppo economico e di attrattivit\u00e0 residenziale, che tiene sempre conto della sua<strong> identit\u00e0 territoriale<\/strong>. Per garantire tutto ci\u00f2, si incentiver\u00e0 anche la nascita di nuove imprese e quindi di occupazione. Motivo per cui si punta alla formazione, mediante hub e laboratori specifici, di personale specializzato e professionale.<\/p>\n<h3>I nove interventi mirati<\/h3>\n<p>Di cos\u00ec vasta portata, il progetto si suddivide in <strong>nove interventi<\/strong> mirati, che risponderanno alle esigenze della comunit\u00e0 e del turista. I lavori vanno dalla ristrutturazione e riqualificazione di antichi edifici al miglioramento dell\u2019accessibilit\u00e0 al borgo; dall\u2019erogazione di servizi turistici, culturali e di animazione a corsi formativi e a incentivi alle imprese.<br \/>\nI cantieri sono gi\u00e0 aperti ed altri saranno avviati nei prossimi mesi, mentre la loro conclusione \u00e8 prevista per il 2026. Intanto, ecco di seguito gli interventi divisi per settori.<\/p>\n<p><strong>Artinborgo Festival<\/strong>\u00a0(600 mila euro): verr\u00e0 potenziato il festival \u201cIl borgo Incantato: l\u2019arte di strada nei vicoli\u201d, che si svolge dal 1999 con ulteriori eventi volti alla valorizzazione del patrimonio storico e architettonico, del sistema produttivo locale e dell\u2019identit\u00e0 locale in chiave partecipativa.<\/p>\n<p><strong>Hub Creativit\u00e0 Mediterranea<\/strong>\u00a0(1,5 milioni di euro): si prevedono due laboratori.<br \/>\nIl primo di restauro, dove i beni culturali del borgo diventeranno un laboratorio per giovani, universit\u00e0, accademie di belle arti e associazioni locali. Il secondo un laboratorio di artigianato che punta ad essere un luogo di studio, di ricerca e apprendimento delle tradizioni manifatturiere artigianali.<\/p>\n<p><strong>Hub formazione turistica<\/strong>\u00a0(600 mila euro): per la sua realizzazione saranno recuperati e adeguati i locali ex-mattatoio e lo spazio esterno chiostro del Convento della Chiesa di San Francesco d&#8217;Assisi. Questi luoghi saranno adibiti a spazio all\u2019aperto per eventi, workshop, networking e corsi di formazione per accompagnatori turistici.<\/p>\n<p><strong>Albergo diffuso<\/strong>\u00a0(7,7 milioni di euro): prevede il riuso e l\u2019adeguamento di abitazioni con la realizzazione di 160 posti letto luxury, servizi di wellness spa e co-working con \u201cart space\u201d in cui ogni stanza\/spazio diventa luogo anche di esposizione artistica.<\/p>\n<p><strong>Accessibilit\u00e0 fisica<\/strong>\u00a0(3 milioni di euro): si lavorer\u00e0 a creare un accesso facilitato al borgo per la limitazione veicolare del traffico nel centro storico. Sar\u00e0 anche realizzato un ascensore che porter\u00e0 dalla zona del parcheggio al borgo.<\/p>\n<p><strong>Sistema di illuminazione integrato<\/strong>\u00a0(800 mila euro): saranno realizzati impianti di illuminazione decorativa e artistica per i monumenti.<\/p>\n<p><strong>Gerace porta digitale<\/strong>\u00a0(600 mila euro): non mancheranno i servizi digitali per la fruizione del patrimonio artistico e culturale.<\/p>\n<p><strong>Incentivi per lo sviluppo<\/strong>\u00a0(4 milioni di euro): per dare concretezza al progetto sono previsti incentivi per le piccole e medie imprese, imprese femminili e giovanili e imprese del terzo settore, tutte operanti in ambito culturale, artistico, turistico, ricreativo, sociale.<\/p>\n<p><strong>Marketing territoriale<\/strong>\u00a0(1,2 milioni di euro): la promozione del borgo sar\u00e0 fondamentale. Si prevedono diverse azioni in merito: come la proposta di candidatura del borgo a patrimonio Unesco; varie attivit\u00e0 di formazione e capacity building per migliorare le potenzialit\u00e0 espresse e inespresse del territorio e l\u2019accoglienza turistica. Infine, sono comprese anche attivit\u00e0 di comunicazione e promozione delle risorse artigianali e turistiche.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>GERACE (RC) &#8211; Sono mesi intensi per la perla dello Jonio, al centro dell\u2019attenzione per gli interventi di riqualificazione ad ampio raggio che le daranno un nuovo volto. I lavori rientrano nel grande progetto \u201cGerace, Porta del sole\u201d, messo in piedi a seguito di un finanziamento di 20 milioni di euro del Pnrr del Ministero [&hellip;]<\/p>\n","protected":false},"author":55,"featured_media":227265,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[19,135],"class_list":["post-227264","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-calabria","tag-copertina","tag-video","post_format-post-format-video"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/227264","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=227264"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/227264\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/227265"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=227264"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=227264"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=227264"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}