{"id":22745,"date":"2013-05-24T13:31:20","date_gmt":"2013-05-24T11:31:20","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=22745"},"modified":"2023-01-17T13:20:23","modified_gmt":"2023-01-17T12:20:23","slug":"8953-ndrangheta-lamezia-fratello-netturbino-ucciso-chiede-giustizia","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/8953-ndrangheta-lamezia-fratello-netturbino-ucciso-chiede-giustizia\/","title":{"rendered":"&#8216;Ndrangheta: lamezia, fratello netturbino ucciso chiede giustizia"},"content":{"rendered":"<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Lamezia Terme (Catanzaro) &#8211; &#8220;Due netturbini uccisi dalla mafia sul lavoro. Due colombe innocenti che gridano ancora in volo sete di giustizia&#8221;. <\/span><\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\"><span style=\"color: #000000;\">Questa la scritta che campeggia sull&#8217;enorme striscione posto all&#8217;ingresso del Tribunale e della Procura di Lamezia Terme da Francesco Cristiano, fratello di Pasquale, il netturbino ucciso insieme al collega Francesco Tramonte il 24 maggio del 1991 a Lamezia in un agguato di tipo mafioso. Oggi ricorrono 21 anni da quel duplice omicidio, che non ha portato a nessun colpevole. Da qui la protesta di Francesco Cristiano che di buon mattino ha appeso uno striscione davanti l&#8217;ingresso del palazzo di giustizia. &#8220;Voglio che sia riaperto il caso come ci aveva promesso l&#8217;ex procuratore della Repubblica di Lamezia Salvatore Vitello &#8211; afferma Cristiano &#8211; la mia famiglia non vuole parate, chiediamo solo giustizia. Due persone innocenti morte mentre stavano lavorando&#8221;.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Lamezia Terme (Catanzaro) &#8211; &#8220;Due netturbini uccisi dalla mafia sul lavoro. Due colombe innocenti che gridano ancora in volo sete di giustizia&#8221;.<\/p>\n","protected":false},"author":22,"featured_media":22746,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-22745","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/22745","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=22745"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/22745\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/22746"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=22745"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=22745"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=22745"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}