{"id":227465,"date":"2024-04-11T09:09:36","date_gmt":"2024-04-11T07:09:36","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=227465"},"modified":"2024-04-11T09:09:36","modified_gmt":"2024-04-11T07:09:36","slug":"tre-chili-di-droga-tra-hashish-e-cocaina-due-persone-in-manette","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/tre-chili-di-droga-tra-hashish-e-cocaina-due-persone-in-manette\/","title":{"rendered":"Tre chili di droga tra hashish e cocaina, due persone in manette"},"content":{"rendered":"<p>CROTONE &#8211; Nell&#8217;ambito di mirati controlli con l&#8217;impiego di unit\u00e0 cinofile antidroga nelle pi\u00f9 importanti localit\u00e0 della provincia crotonese, la guardia di finanza in prossimit\u00e0 del centro cittadino di Isola di Capo Rizzuto, ha fermato due autovetture dopo averle notate affiancarsi. I <strong>conducenti si erano scambiati qualcosa per poi allontanarsi<\/strong> seguendo <strong>opposte direzioni<\/strong>. Ritenendo fondato il sospetto che si fosse concretizzata una cessione di droga, i finanzieri di Crotone hanno fermato l\u2019autovettura del soggetto ricevente. L\u2019evidente stato di agitazione mostrato da quest\u2019ultimo ha spinto i militari a far intervenire i <strong>pastori tedeschi \u201cJack\u201d e \u201cInd\u00f9\u201d,<\/strong> il cui fiuto ha consentito di rinvenire un involucro in plastica contenente un piccolo quantitativo di cocaina. E&#8217; scattata per\u00f2 la perquisizione domiciliare, nell&#8217;abitazione del <strong>soggetto cedente<\/strong>, che ha permesso di sorprendere il soggetto insieme ad un&#8217;altra persona mentre confezionavano la cocaina.<\/p>\n<p>All\u2019esito delle operazioni sono stati sequestrati circa <strong>due chili e mezzo di hashish<\/strong> ed oltre <strong>mezzo chilo di cocaina<\/strong>, insieme a vario materiale utilizzato per il taglio, la pesatura ed il confezionamento della droga. Durante la perquisizione, \u00e8 stata anche trovata una pistola cal. 45, tipo revolver, detenuta illegalmente, che dagli accertamenti \u00e8 risultata oggetto di furto, compiuto in Emilia Romagna nel febbraio 2022. I due sono stati arrestati per i reati di spaccio di stupefacenti, detenzione illegale di arma e ricettazione. La sostanza sequestrata, se immessa sul mercato illecito, avrebbe fruttato nelle piazze di spaccio<strong> migliaia di dosi e proventi illeciti per circa 75 mila euro.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>CROTONE &#8211; Nell&#8217;ambito di mirati controlli con l&#8217;impiego di unit\u00e0 cinofile antidroga nelle pi\u00f9 importanti localit\u00e0 della provincia crotonese, la guardia di finanza in prossimit\u00e0 del centro cittadino di Isola di Capo Rizzuto, ha fermato due autovetture dopo averle notate affiancarsi. I conducenti si erano scambiati qualcosa per poi allontanarsi seguendo opposte direzioni. Ritenendo fondato [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":227466,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[19],"class_list":["post-227465","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/227465","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=227465"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/227465\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/227466"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=227465"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=227465"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=227465"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}