{"id":227473,"date":"2024-04-11T09:50:16","date_gmt":"2024-04-11T07:50:16","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=227473"},"modified":"2024-04-11T10:33:29","modified_gmt":"2024-04-11T08:33:29","slug":"grave-problema-a-banca-sella-e-hype-da-giorni-conti-bloccati-e-servizi-down-utenti-infuriati","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/grave-problema-a-banca-sella-e-hype-da-giorni-conti-bloccati-e-servizi-down-utenti-infuriati\/","title":{"rendered":"Grave problema a Banca Sella e Hype: da giorni conti bloccati e servizi down. Utenti infuriati"},"content":{"rendered":"<p>COSENZA &#8211; Da almeno 4 giorni, a<strong> causa di un grosso problema tecnico<\/strong>, risulta impossibile<strong> effettuare l&#8217;accesso al proprio home banking sia nel caso di Hype che nel caso di Banca Sella<\/strong>. Ma i problemi non si limitano solo a Banking, Smart Business Sella e app, visto che diversi correntisti lamentano<strong> l&#8217;impossibilit\u00e0 ad effettuare qualsiasi tipo di operazione o pagamento, oltre a vedere il proprio conto corrente azzerato.<\/strong><\/p>\n<p>Tantissimi utenti stanno segnalando <strong>l\u2019impossibilit\u00e0 di ricevere lo stipendio e bonifici<\/strong>, <strong>effettuare acquisti con la carta di credito<\/strong> e pagare Rid e bollette accreditate direttamente sul conto corrente. In pi\u00f9, gli esercenti che utilizzano il Pos che si appoggia a Banca Sella, <strong>non riescono ad avere i pagamenti effettuati dai clienti con i movimenti sempre a zero<\/strong>. Una vera e propria &#8220;paralisi di servizi&#8221; dovuta ad un problema tecnico derivato da interventi di manutenzione.<\/p>\n<p><a href=\"https:\/\/quicosenza.it\/news\/italia\/grave-problema-a-banca-sella-e-hype-da-giorni-conti-bloccati-e-servizi-down-utenti-infuriati\/attachment\/sella\" rel=\"attachment wp-att-227478\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-227478 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/04\/Sella.jpg\" alt=\"Sella\" width=\"510\" height=\"803\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/04\/Sella.jpg 864w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/04\/Sella-191x300.jpg 191w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/04\/Sella-651x1024.jpg 651w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/04\/Sella-768x1209.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/04\/Sella-150x236.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/04\/Sella-300x472.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/04\/Sella-696x1096.jpg 696w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/04\/Sella-267x420.jpg 267w\" sizes=\"auto, (max-width: 510px) 100vw, 510px\" \/><\/a><\/p>\n<h3>Unione consumatori &#8220;inaccettabile una tempistica cos\u00ec lunga&#8221;<\/h3>\n<p>&#8220;<em><strong>Non \u00e8 accettabile una tempistica cos\u00ec lunga per risolvere dei problemi tecnici<\/strong>. <strong>\u00c8 dall&#8217;8 aprile che dicono ai consumatori che sar\u00e0 al pi\u00f9 presto ripristinata la piena operativit\u00e0<\/strong>. Peccato che ancora oggi ci siano disservizi e rallentamenti. Il danno dei clienti \u00e8 ingente e a questo punto la banca deve provvedere a indennizzarli, oltre a rispondere degli eventuali danni che hanno subito per colpa dei ritardi nei pagamenti. Per questo invitiamo i consumatori a presentare formale reclamo alla Banca, con le richieste risarcitorie<\/em>&#8220;. \u00c8 quanto afferma<strong> Massimiliano Dona, presidente dell&#8217;Unione Nazionale Consumatori<\/strong>.<\/p>\n<h3>Banca Sella: &#8220;problema tecnico, stiamo lavorando&#8221;<\/h3>\n<p>Travolta da critiche e lamentele, Banca Sella ha comunicato che &#8220;a<strong> causa di un <a href=\"https:\/\/www.sella.it\/-\/aggiornamenti-sui-problemi-tecnici-in-corso\" rel=\"noopener\">problema tecnico interno<\/a>, verificatosi successivamente ad alcuni interventi di manutenzione periodica dei sistemi informatici<\/strong> avvenuti nel fine settimana, si stanno riscontrando rallentament<strong>i e interruzioni nell&#8217;accesso e nell&#8217;utilizzo dei servizi online (Internet Banking e app) e nel funzionamento di pagamenti tramite carte di debito e prepagate<\/strong>&#8220;. L&#8217;istituto di credito ha fatto sapere che\u00a0i <strong>tecnici sono al lavoro in corso per ripristinare la piena operativit\u00e0 al pi\u00f9 presto.<\/strong> Nel frattempo, Banca Sella ha comunicato che\u00a0\u00e8 possibile operare tramite le seguenti modalit\u00e0:<\/p>\n<ul>\n<li><strong>Succursale, per operativit\u00e0 di cassa e operazioni di pagamento<\/strong> (come bonifici, F24, bollettini ecc.). Le succursali seguiranno un orario continuato e prolungato nei\u00a0giorni di apertura, in attesa della completa risoluzione dei rallentamenti<\/li>\n<li><strong>Assistenza Clienti,<\/strong> che rimane a piena disposizione, seppur con alcuni rallentamenti visto il numero elevato di richieste, sia per l\u2019operativit\u00e0 che per ricevere maggiori informazioni<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Da almeno 4 giorni, a causa di un grosso problema tecnico, risulta impossibile effettuare l&#8217;accesso al proprio home banking sia nel caso di Hype che nel caso di Banca Sella. Ma i problemi non si limitano solo a Banking, Smart Business Sella e app, visto che diversi correntisti lamentano l&#8217;impossibilit\u00e0 ad effettuare qualsiasi [&hellip;]<\/p>\n","protected":false},"author":55,"featured_media":227474,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[19],"class_list":["post-227473","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/227473","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=227473"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/227473\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/227474"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=227473"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=227473"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=227473"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}