{"id":22810,"date":"2013-05-28T06:53:47","date_gmt":"2013-05-28T04:53:47","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=22810"},"modified":"2023-01-17T13:20:26","modified_gmt":"2023-01-17T12:20:26","slug":"8989-pedofilia-indagato-a-genova-il-bidello-di-un-asilo","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/8989-pedofilia-indagato-a-genova-il-bidello-di-un-asilo\/","title":{"rendered":"Pedofilia: indagato a Genova il bidello di un asilo"},"content":{"rendered":"<p>Genova &#8211; Un uomo di sessant&#8217;anni, bidello in un asilo, \u00e8 stato accusato di pedofilia.<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">La denuncia \u00e8 scattata dai genitori di quattro bambine, frequentanti l&#8217;istituto e ora, l&#8217;uomo dovr\u00e0 rispondere del <strong>reato punito dall&#8217;articolo 609 bis e ter commi 1, 5 bis e 2<\/strong>.<br \/>L&#8217;accusa \u00e8 di palpeggiamenti subiti dalle piccole quando le accompagnava in bagno.&nbsp; A dare il via all&#8217;inchiesta \u00e8 stato il racconto delle bambine. <br \/>In seguito, gli agenti, su disposizione del pm, hanno installato telecamere nascoste, che hanno documentato le violenze in almeno sei episodi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Genova &#8211; Un uomo di sessant&#8217;anni, bidello in un asilo, \u00e8 stato accusato di pedofilia.<\/p>\n","protected":false},"author":22,"featured_media":22811,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,16],"tags":[],"class_list":["post-22810","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-italia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/22810","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=22810"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/22810\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/22811"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=22810"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=22810"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=22810"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}