{"id":228593,"date":"2024-04-26T07:30:36","date_gmt":"2024-04-26T05:30:36","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=228593"},"modified":"2024-04-26T07:33:55","modified_gmt":"2024-04-26T05:33:55","slug":"bisignano-si-lavora-per-il-riconoscimento-igp-del-broccolo-di-rapa","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/bisignano-si-lavora-per-il-riconoscimento-igp-del-broccolo-di-rapa\/","title":{"rendered":"Bisignano: si lavora per il riconoscimento IGP del &#8216;broccolo di rapa&#8217;"},"content":{"rendered":"<p>BISIGNANO (CS) &#8211; \u00c8 tutto pronto per la seconda edizione del <strong>Festival della Rapa<\/strong>, evento organizzato dall\u2019Assessorato allo Sviluppo Agricolo del Comune di Bisignano, diretto da Francesco Chiaravalle, protagonista del <strong>percorso di valorizzazione e promozione <\/strong>di uno dei <strong>principali ortaggi della valle del Crati<\/strong>, il <strong>broccolo di rapa<\/strong>, ricercatissimo per le sue singolari qualit\u00e0 di gusto e per le eccellenti propriet\u00e0 nutraceutiche. La manifestazione si terr\u00e0 domani, <strong>sabato 27 aprile a Bisignano, su Viale Roma<\/strong>, con degustazione di prodotti e piatti tipici a base di rapa, abbinati con gusto agli ottimi vini delle cantine locali.<\/p>\n<p>Il primo appuntamento del ricco programma messo su dall\u2019assessorato di Chiaravalle avr\u00e0 inizio alle ore <strong>17.00<\/strong> presso la Sala Caff\u00e8 Letterario della Biblioteca comunale, con un <strong>\u201ctuffo nel passato rurale tra gusto e tradizioni\u201d,<\/strong> focus del tema che avr\u00e0 al centro del dibattito le \u201ccolture biologiche e le tecniche di produzioni al giorno d\u2019oggi\u201d.\u00a0I lavori del convegno sull\u2019importanza che ricopre il comparto agricolo e rurale del territorio dell\u2019antica Besidiae saranno aperti dai saluti di: Francesco Fucile, Sindaco della Citt\u00e0 di Bisignano; Francesco Chiaravalle, Consigliere provinciale e Assessore della Citt\u00e0 di Bisignano; Rosaria Amalia Capparelli, Presidente del GAL Valle del Crati; Rosaria Succurro, Presidente della Provincia di Cosenza; Franco Aceto, Presidente regionale di Coldiretti Calabria; Luca Pignataro, Presidente di CIA (Confederazione Italiana Agricoltori) Calabria Nord.<\/p>\n<p>Seguiranno, moderati dal giornalista Valerio Caparelli, interventi sul tema con le relazioni di: Vincenzo Liguori, biologo nutrizionista; Massimino Magliocchi, Presidente del Consorzio Olio Calabria IGP; Pierfranco Costa, Direttore del GAL Valle del Crati; Marcello Bruno, funzionario ARSAC; Fulvia Michela Caligiuri, Commissario dell\u2019Azienda Regionale per lo Sviluppo dell\u2019Agricoltura Calabrese. I lavori saranno conclusi dall\u2019intervento dell\u2019Assessore all\u2019Agricoltura della Regione Calabria, on. Gianluca Gallo.<\/p>\n<p>Sar\u00e0 aperto anche un <strong>villaggio rurale<\/strong> e uno spazio di postazioni di assaggio e degustazione enogastronomica del paniere di prodotti del territorio, allestito per soddisfare i palati di quanti parteciperanno all\u2019evento di promozione della Rapa di Bisignano.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>BISIGNANO (CS) &#8211; \u00c8 tutto pronto per la seconda edizione del Festival della Rapa, evento organizzato dall\u2019Assessorato allo Sviluppo Agricolo del Comune di Bisignano, diretto da Francesco Chiaravalle, protagonista del percorso di valorizzazione e promozione di uno dei principali ortaggi della valle del Crati, il broccolo di rapa, ricercatissimo per le sue singolari qualit\u00e0 di [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":228594,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[19],"class_list":["post-228593","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/228593","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=228593"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/228593\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/228594"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=228593"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=228593"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=228593"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}