{"id":22872,"date":"2013-05-29T11:03:54","date_gmt":"2013-05-29T09:03:54","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=22872"},"modified":"2023-01-17T13:20:29","modified_gmt":"2023-01-17T12:20:29","slug":"9020-lutto-nel-mondo-dello-spettacolo-per-la-morte-di-franca-rame","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/9020-lutto-nel-mondo-dello-spettacolo-per-la-morte-di-franca-rame\/","title":{"rendered":"Lutto nel mondo dello spettacolo per la morte di Franca Rame"},"content":{"rendered":"<p>L\u2019attrice <strong>Franca Rame<\/strong>, &nbsp;moglie e collega di Dario Fo, si \u00e8 spenta a Milano all\u2019et\u00e0 di 84 anni.<\/p>\n<p>Fervente sostenitrice del <strong>femminismo italiano<\/strong>&nbsp;nel 1973 &nbsp;fu rapita e stuprata da militanti di estrema destra, non ha mai dimenticato lo scacco ricevuto soprattutto per la lunga ed avvilente durata del processo: <strong>ben 25 anni<\/strong> .<\/p>\n<p>Franca Rame ha passato la sua vita dedicandosi al <strong>teatro<\/strong> e soprattutto all\u2019<strong>impegno civile<\/strong>!<\/p>\n<p>Una donna di successo che si \u00e8 impegnata a livello politico, ricevendo nel 1999&nbsp;la <em><strong>laurea honoris causa<\/strong><\/em> da parte dell\u2019<strong>Universit\u00e0 di Wolverhampton<\/strong>&nbsp;insieme al marito. Alle elezioni del 2006 si era candidata capolista al senato in Piemonte, Lombardia, Veneto, Emilia Romagna, Toscana ed Umbria tra le file dell\u2019Italia dei Valori. Verr\u00e0 poi eletta senatrice in Piemonte.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019attrice Franca Rame, &nbsp;moglie e collega di Dario Fo, si \u00e8 spenta a Milano all\u2019et\u00e0 di 84 anni. Fervente sostenitrice del femminismo italiano&nbsp;nel 1973 &nbsp;fu rapita e stuprata da militanti di estrema destra, non ha mai dimenticato lo scacco ricevuto soprattutto per la lunga ed avvilente durata del processo: ben 25 anni . Franca Rame [&hellip;]<\/p>\n","protected":false},"author":22,"featured_media":22873,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,40,34],"tags":[],"class_list":["post-22872","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-cultura-spettacolo","category-magazine"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/22872","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=22872"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/22872\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/22873"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=22872"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=22872"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=22872"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}