{"id":228941,"date":"2024-04-30T08:22:07","date_gmt":"2024-04-30T06:22:07","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=228941"},"modified":"2024-04-30T08:23:25","modified_gmt":"2024-04-30T06:23:25","slug":"escalation-di-rapine-a-castrovillari-in-manette-il-rapinatore-seriale-video","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/escalation-di-rapine-a-castrovillari-in-manette-il-rapinatore-seriale-video\/","title":{"rendered":"Escalation di rapine a Castrovillari, in manette il rapinatore seriale &#8211; VIDEO"},"content":{"rendered":"<p>CASTROVILLARI (CS) &#8211; Il 25 gennaio 2024 era riuscito a mettere a segno il primo colpo in danno <strong>di una parafarmacia di Castrovillari per poi fermarsi per circa due mesi<\/strong> quando, nel volgere di appena venti giorni, aveva iniziato nuovamente a colpire lo stesso territorio della capitale del Pollino,<strong> che ha visto il ripetersi in rapida successione di altri episodi di rapina del tutto analoghi tra loro<\/strong>: un soggetto solitario, con il volto coperto da passamontagna e cappuccio, ma soprattutto che <strong>armato di pistola faceva irruzione all\u2019interno di esercizi commerciali in concomitanza dell\u2019orario di chiusura serale impossessandosi dell\u2019incasso<\/strong>.<\/p>\n<p>Un\u2019escalation di rapine che avevano creato particolare allarme nel territorio. Partendo dalla descrizione fornita dalle vittime degli eventi, i carabinieri hanno dapprima individuato la macchina che il soggetto utilizzava da Cassano All\u2019ionio per raggiungere le attivit\u00e0 poi a dare un nome al reale utilizzatore di quel veicolo. L<strong>&#8216;uomo C.G., 33enne originario di Cassano All\u2019ionio, \u00e8 indagato per quattro rapine consumate ed una tentata, tutte commesse a mano armata.<\/strong><\/p>\n<p>Un quadro indiziario ricostruito analiticamente dalla Procura di Castrovillari che nella richiesta di misura cautelare ha riepilogato dettagliatamente i vari elementi raccolti dai carabinieri, <strong>tutti convergenti verso il 33enne cassanese che \u00e8 stato condotto presso la locale Casa Circondariale.<\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CASTROVILLARI (CS) &#8211; Il 25 gennaio 2024 era riuscito a mettere a segno il primo colpo in danno di una parafarmacia di Castrovillari per poi fermarsi per circa due mesi quando, nel volgere di appena venti giorni, aveva iniziato nuovamente a colpire lo stesso territorio della capitale del Pollino, che ha visto il ripetersi in [&hellip;]<\/p>\n","protected":false},"author":61,"featured_media":228942,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[19,135],"class_list":["post-228941","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-provincia","tag-copertina","tag-video","post_format-post-format-video"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/228941","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=228941"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/228941\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/228942"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=228941"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=228941"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=228941"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}