{"id":229317,"date":"2024-05-04T19:30:26","date_gmt":"2024-05-04T17:30:26","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=229317"},"modified":"2024-05-04T19:34:35","modified_gmt":"2024-05-04T17:34:35","slug":"elezioni-comunali-giorni-decisivi-per-la-presentazione-delle-liste","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/elezioni-comunali-giorni-decisivi-per-la-presentazione-delle-liste\/","title":{"rendered":"Elezioni comunali, giorni decisivi per la presentazione delle liste"},"content":{"rendered":"<p>Ultimate le liste per le elezioni europee, l&#8217;attenzione si sposta sulle <strong>comunali<\/strong>. Ancora pochi giorni, una settimana circa di lavoro per le forze politiche impegnate. <strong>Le liste, infatti, andranno presentate dalle 8 del 10 maggio alle ore 12 dell&#8217;11<\/strong>.<\/p>\n<p>Sette giorni di riflessione, dunque, <strong>nei 135 comuni calabresi<\/strong> nei quali si rinnoveranno i consigli comunali. Solo 4, per\u00f2, i centri superiori ai 15000 abitanti, ovvero <strong>Corigliano Rossano<\/strong>, che \u00e8 anche il comune pi\u00f9 popoloso, <strong>Gioia Tauro, Montalto Uffugo e Vibo Valentia<\/strong>, unica citt\u00e0 capoluogo.<\/p>\n<p>Nello specifico sono <strong>19 i comuni in cui si andr\u00e0 al voto in provincia di Catanzaro, 65 nel cosentino, 11 nel crotonese, 27 nel reggino e 13 in provincia di Vibo Valentia<\/strong>.<br \/>\nLa nuova legge consente il terzo mandato ai sindaci con popolazione fra i 15000 e i 5000 abitanti. Sotto questa soglia non c&#8217;\u00e8 pi\u00f9 alcun limite. Alcuni primi cittadini, quindi, potrebbero riproporsi. E&#8217; il caso di <strong>Antonio Russo a Crosia, Francesco Cosentino a Cittanova, Antonio Palermo a Mendicino, Francesco Mauro a Sellia Marina, Virginia Mariotti a San Marco Argentano, Ferdinando Nociti a Spezzano Albanese e Paolo Montalti a Villapiana<\/strong>. C&#8217;\u00e8, ovviamente, chi ha gi\u00e0 deciso di ritornare in corsa e chi comunque rinuncer\u00e0 a questa nuova chance.<\/p>\n<p>E poi ci sono i comuni pi\u00f9 piccoli. In alcuni casi, soprattutto in alcuni centri, la sfida \u00e8 stata sempre accesa fino all&#8217;ultimo voto. Si sa, a volte, anche una sola famiglia pu\u00f2 determinare le sorti di una legislatura. E cos\u00ec potrebbe essere anche stavolta. Sempre ammesso che ci saranno almeno due liste a competere, perch\u00e9 <strong>pare che in alcuni comuni potrebbe essere presente una sola lista<\/strong>. In soccorso \u00e8 spesso arrivata una cosiddetta &#8220;lista civetta&#8221;&#8230;altrimenti bisogner\u00e0 <strong>portare al voto almeno il 40% degli aventi diritto<\/strong>. Non un&#8217;impresa semplice in considerazione del fatto che molti residenti, in pratica, vivono fuori e non tornano per le elezioni. Ed anche in considerazione del numero di votanti in costante calo. A maggior ragione quando non \u00e8 presente un&#8217;alternativa. Ancora pochi giorni e ne sapremo di pi\u00f9.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ultimate le liste per le elezioni europee, l&#8217;attenzione si sposta sulle comunali. Ancora pochi giorni, una settimana circa di lavoro per le forze politiche impegnate. Le liste, infatti, andranno presentate dalle 8 del 10 maggio alle ore 12 dell&#8217;11. Sette giorni di riflessione, dunque, nei 135 comuni calabresi nei quali si rinnoveranno i consigli comunali. [&hellip;]<\/p>\n","protected":false},"author":65,"featured_media":229318,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[19,135],"class_list":["post-229317","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-calabria","tag-copertina","tag-video","post_format-post-format-video"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/229317","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/65"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=229317"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/229317\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/229318"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=229317"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=229317"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=229317"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}