{"id":229930,"date":"2024-05-13T12:00:30","date_gmt":"2024-05-13T10:00:30","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=229930"},"modified":"2024-05-13T11:37:09","modified_gmt":"2024-05-13T09:37:09","slug":"caloveto-contro-lo-spopolamento-interventi-su-scuole-sociale-e-sicurezza","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/caloveto-contro-lo-spopolamento-interventi-su-scuole-sociale-e-sicurezza\/","title":{"rendered":"Caloveto contro lo spopolamento: interventi su scuole, sociale e sicurezza"},"content":{"rendered":"<p>CALOVETO (CS) \u2013 La riqualificazione e la consegna alla comunit\u00e0 di una nuova, bella e decorosa <strong>piazza dei Caduti<\/strong>, salotto e cuore pulsante del borgo, traduce forse meglio di tanti altri interventi la visione che ha ispirato anche gli ultimi 5 anni di governo: <strong>difendere Caloveto dallo spopolamento,<\/strong> promuovere coesione sociale e creare opportunit\u00e0 di crescita e sviluppo eco-sostenibile per tutti. <strong>Sono pi\u00f9 di 6 i milioni di euro<\/strong> di finanziamenti intercettati ed ottenuti dall\u2019Amministrazione Comunale nel decennio 2014-2024 e che hanno consentito di continuare ad elevare la qualit\u00e0 della vita e migliorare i servizi al cittadino. La Giunta Municipale rende noto l&#8217;impegno di questi ultimi anni sia andato nella direzione di <strong>ridurre al minimo i disagi<\/strong> e, anzi, di sfruttare tutte le potenzialit\u00e0 di un comune dell\u2019entroterra, trasformando le criticit\u00e0 in punti di vantaggio.<\/p>\n<p>Dalla mitigazione del <strong>rischio idrogeologico<\/strong>, alla <strong>riqualificazione del patrimonio comunale e di quello edilizio scolastico<\/strong>, dall\u2019efficientamento energetico al miglioramento della raccolta differenziata che ha consentito, grazie all\u2019impegno di tutta la comunit\u00e0 di raggiungere, da un timido 12% lo straordinario traguardo del 75% di raccolta differenziata. Sono solo alcune delle coordinate del percorso portati avanti ed alle quali si vuole dare continuit\u00e0. <strong>Un borgo a misura di famiglia<\/strong>, garantendo ambienti sicuri per le comunit\u00e0 educanti e servizi per i ragazzi \u00e8 stato uno degli obiettivi principali perseguiti dall\u2019Amministrazione Comunale.<\/p>\n<p>EDILIZIA SCOLASTICA<\/p>\n<p>L\u2019adeguamento dell\u2019edificio scolastico (150 mila euro con fondi MIUR e INAIL), con opere di messa in sicurezza interna, opere murarie, impianto elettrico nuovo, rifacimento del pavimento, cambio dei servizi igienici, scale per trasporto per disabili; riparazione della trave in cemento amato nella scuola elementare-media (30 mila euro); adeguamento sismico ex scuola media sita in via Sant\u2019Antonio (792 mila euro).<\/p>\n<p>CONSOLIDAMENTO DI VIA RIMEMBRANZA E LOCALIT\u00c0 TRE CROCI &#8211; 990 MILA EURO<\/p>\n<p>Grazie al finanziamento di circa un milione di euro da parte del Ministero degli Interni e della Finanza, sono in fase di ultimazione gli interventi di messa in sicurezza del costone, da anni interessato dal fenomeno franoso e motivo di preoccupazione, ad ogni allarme maltempo, per i residenti.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CALOVETO (CS) \u2013 La riqualificazione e la consegna alla comunit\u00e0 di una nuova, bella e decorosa piazza dei Caduti, salotto e cuore pulsante del borgo, traduce forse meglio di tanti altri interventi la visione che ha ispirato anche gli ultimi 5 anni di governo: difendere Caloveto dallo spopolamento, promuovere coesione sociale e creare opportunit\u00e0 di [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":229936,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[],"class_list":["post-229930","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/229930","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=229930"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/229930\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/229936"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=229930"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=229930"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=229930"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}