{"id":23026,"date":"2013-06-03T11:31:44","date_gmt":"2013-06-03T09:31:44","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=23026"},"modified":"2023-01-17T13:20:38","modified_gmt":"2023-01-17T12:20:38","slug":"9099-migliora-la-gestione-regionale-della-spesa-sanitaria","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/9099-migliora-la-gestione-regionale-della-spesa-sanitaria\/","title":{"rendered":"Migliora la gestione regionale della spesa sanitaria"},"content":{"rendered":"<p>CATANZARO &#8211; Il Presidente della Regione Giuseppe Scopelliti &#8211; informa una nota dell\u2019Ufficio Stampa della Giunta regionale \u2013 commenta il rapporto della Ragioneria generale dello Stato pubblicato oggi sul Corriere della Sera che &nbsp;\u201cconferma, per quanto riguarda la nostra regione, che la gestione commissariale della sanita\u2019sta producendo risultati notevoli.<\/p>\n<p>  <!--more-->  <\/p>\n<p>Come mostrano i grafici l&#8217;azione di contenimento della spesa che abbiamo attuato non \u00e8 una percentuale minima se si considera l&#8217;operazione straordinaria che siamo stati chiamati ad affrontare appena eletti. La spesa in Calabria tra il 2002 ed il 2006 e\u2019 aumentata del 4,2%, tra il 2006 ed il 2010 del 3,5%.&nbsp; Nel periodo compreso tra il 2010 ed il 2012, che corrisponde alla nostra gestione amministrativa, \u00e8 diminuita dell\u20191,3%. C\u2019e\u2019 da aggiungere, per far capire la difficolt\u00e0 in cui ci siamo trovati ad operare, che abbiamo trovato una voragine nei conti della sanita\u2019 con una situazione contabile fantasma che oggi, finalmente, trova certezze e risposte estremamente positive. Con la crisi economica, per noi, appena insediati, non e\u2019 stato facile avviare un&#8217;opera di risanamento drastica ma il senso di responsabilita\u2019 che ci ha guidato fino ad ora e che continuera\u2019 fino al risanamento totale e\u2019 questo e i risultati si vedono. Come regione siamo in controtendenza anche nella spesa pro-capite nella farmaceutica che e\u2019 gradualmente scesa dai 275 euro del 2009, anno della sottoscrizione del Piano di Rientro, ai 268 euro per il 2010, per poi ridursi ai 231,2 euro del 2011 e arrivare ai 163 euro nel periodo gennaio-settembre 2012 cosi\u2019 come illustra il rapporto dell&#8217;Osservatorio Nazionale sull&#8217;Impiego dei Medicinali. Infine il recentissimo sblocco di 411 milioni dal Consiglio dei Ministri e\u2019 un ulteriore premio che incoraggia ancor di piu\u2019 il lavoro che stiamo facendo giorno dopo giorno insieme a tutta la squadra commissariale ed il dipartimento salute. Le criticita\u2019 non mancano ma le affrontiamo con senso di&nbsp; responsabilita\u2019 verso la nostra gente, e\u2019 il segnale che la Calabria sta ripartendo verso la giusta direzione&#8221;.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CATANZARO &#8211; Il Presidente della Regione Giuseppe Scopelliti &#8211; informa una nota dell\u2019Ufficio Stampa della Giunta regionale \u2013 commenta il rapporto della Ragioneria generale dello Stato pubblicato oggi sul Corriere della Sera che &nbsp;\u201cconferma, per quanto riguarda la nostra regione, che la gestione commissariale della sanita\u2019sta producendo risultati notevoli.<\/p>\n","protected":false},"author":22,"featured_media":23027,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-23026","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/23026","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=23026"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/23026\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/23027"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=23026"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=23026"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=23026"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}