{"id":230292,"date":"2024-05-17T10:48:40","date_gmt":"2024-05-17T08:48:40","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=230292"},"modified":"2024-05-17T10:56:02","modified_gmt":"2024-05-17T08:56:02","slug":"subdola-truffa-ad-una-70enne-cosentina-le-rubano-le-fedi-sostituendole-con-due-tarocchi","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/subdola-truffa-ad-una-70enne-cosentina-le-rubano-le-fedi-sostituendole-con-due-tarocchi\/","title":{"rendered":"Subdola truffa ad una 70enne cosentina: le rubano le fedi sostituendole con due anelli &#8220;tarocchi&#8221;"},"content":{"rendered":"<p>CORIGLIANO &#8211; ROSSANO (CS) &#8211; <strong>Una donna di 70 anni \u00e8 stata truffata da due individui <\/strong>che sono <strong>riusciti a sostituire le fedi nuziali che portava al dito<\/strong> (la sua e quella del marito defunto) <strong>con due anelli di metallo falsi<\/strong>. Solo una volta tornata a casa la nuora della povera signora si \u00e8 accorta della truffa e si \u00e8 recata con un figlio dai carabinieri per sporgere denuncia. <strong>\u00c8 accaduto due giorni fa a Rossano<\/strong>.<\/p>\n<p><strong>La donna stava camminando per strada<\/strong> quando \u00e8 stata fermata da un&#8217;auto di colore grigio con a bordo <strong>un uomo e una donna dal marcato accento straniero<\/strong>. I due, con modi gentili, hanno chiesto alcune informazioni alla 70enne e, in particolare, <strong>se nelle vicinanze era presenta un&#8217;oreficeria di sua conoscenza<\/strong>, perch\u00e9 avevano necessit\u00e0 di acquistare un anello. Nel mentre i due <strong>notano le fedi al dito della donna<\/strong> e le chiedono come mai portasse due anelli insieme. La donna spiega che una era la sua e l&#8217;altra del marito defunto e che all&#8217;interno degli anelli erano <strong>presenti le incisioni con i nomi e la data del matrimonio<\/strong>. A questo punto <strong>i due truffatori metto in atto il loro subdolo piano<\/strong>.<\/p>\n<p><strong> Chiedono alla donna<\/strong> <strong>di poter vedere gli anelli<\/strong>, cosa che la donna fa. Dopo averle fatto i complimenti per gli anelli &#8220;<em>che belli che sono<\/em>&#8220;, li <strong>restituiscono insieme ad un foglio di carta<\/strong> chiedendo alla donna di scrivere il nome della localit\u00e0 nella quali si trovavano, visto che a loro dire<strong> non ne erano a conoscenza<\/strong>. La truffa a questo punto \u00e8 compiuta, i due individui se ne vanno con il bottino. Come detto, solo una volta che la donna \u00e8 rincasata ci si \u00e8 resi conto della truffa. Ha raccontato alla nuora la storia che, subito insospettita, <strong>ha controllato le fedi rendendosi conto che non solo mancavano le incisioni<\/strong> ma che i due anelli nuziali erano stati <strong>sostituite con due anelli di metallo di color oro.<\/strong> L&#8217;orefice della donna ha confermato che si trattava di due anelli finti.<strong> Alla povera donna non \u00e8 rimasto che sporgere denuncia ai carabinieri<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CORIGLIANO &#8211; ROSSANO (CS) &#8211; Una donna di 70 anni \u00e8 stata truffata da due individui che sono riusciti a sostituire le fedi nuziali che portava al dito (la sua e quella del marito defunto) con due anelli di metallo falsi. Solo una volta tornata a casa la nuora della povera signora si \u00e8 accorta [&hellip;]<\/p>\n","protected":false},"author":55,"featured_media":230295,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[572],"tags":[19],"class_list":["post-230292","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ionio","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/230292","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=230292"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/230292\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/230295"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=230292"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=230292"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=230292"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}