{"id":23072,"date":"2013-06-04T07:48:43","date_gmt":"2013-06-04T05:48:43","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=23072"},"modified":"2023-01-17T13:20:40","modified_gmt":"2023-01-17T12:20:40","slug":"9122-due-morti-e-sette-feriti-nel-cosentino-la-statale-106-colpisce-ancora","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/9122-due-morti-e-sette-feriti-nel-cosentino-la-statale-106-colpisce-ancora\/","title":{"rendered":"La 106 &#8216;colpisce&#8217; ancora, due morti e 7 feriti: &#8220;Andavano a lavorare i campi&#8221;"},"content":{"rendered":"<p>COSENZA &#8211; La statale ionica continua a mietere vittime.<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">Un grave incidente avvenuto stamane all&#8217;altezza di Trebisacce \u00e8 costato la vita a due persone. A sole ventiquattro ore dalla morte delle due anziane travolte da un mezzo in corsa mentre erano intente ad attraversare la strada statale, la 106 \u00e8 nuovamente al centro delle cronache. In base ai primi accertamenti l&#8217;incidente stradale verificatosi stamane avrebbe coinvolto un furgone Fiat Ducato con a bordo uomini e donne diretti in Basilicata per lavorare dei campi che, per cause ancora in corso d&#8217;accertamento sarebbe finito fuori strada. Quattro dei pendolari, tutti di nazionalit\u00e0 romena, sono stati ricoverati presso i locali nosocomi di Corigliano e Rossano. Altri tre feriti che hanno riportato lesioni maggiori sono invece stati trasferiti all&#8217;ospedale l&#8217;Annunziata di Cosenza con l&#8217;elisoccorso in gravi condizioni, mentre per due dei braccianti l&#8217;arrivo delle ambulanze non \u00e8 servito a scongiurarne la morte. Le due ultime vittime della &#8216;statale della morte&#8217; si chiamavano Marcel Mocan, 44 anni, e Doru Badu, 42. In base a una prima ricostruzione della dinamica dell&#8217;incidente, il sinistro sarebbe stato provocato dall&#8217;esplosione d&#8217;uno degli pneumatici del furgoncino diretto a Scanzano Ionico per la raccolta delle fragole. I braccianti erano partiti mezz&#8217;ora prima da Rossano, dove ha sede la cooperativa per la quale lavoravano stagionalmente. L&#8217;unica a rimanese illesa \u00e8 stata la guidatrice del furgone, una 27enne, che dopo il ribaltamento del mezzo ha avuto la lucidit\u00e0 di scendere prontamente dal furgone per fermare le auto in arrivo al fine di evitare che potessero travolgere il Ducato rimasto sulla carreggiata, nel quale erano incastrati tra le lamiere i suoi connazionali. Le due vittime invece al momento dei vari impatti del furgoncino fuori controllo con il gard-rail erano state sbalzate fuori dal veicolo schiantandosi sull&#8217;asfaldo. I poliziotti stanno attualmente indagando sull&#8217;incidente, mentre a Crotone circa quaranta arresti hanno stamane sferrato un duro colpo alla &#8216;grande famiglia&#8217; che degli appalti della 106 ha fatto per anni una delle branche principali del priprio business drenando, con il consenso della politica locale, denaro pubblico dalle casse dello Stato alle tasche della criminalit\u00e0 organizzata.<\/p>\n<p style=\"text-align: justify;\">&nbsp;<\/p>\n<p><span style=\"font-family: Arial,Helvetica,sans-serif; font-size: 14px; line-height: 19.9896px;\">&nbsp;<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; La statale ionica continua a mietere vittime.<\/p>\n","protected":false},"author":22,"featured_media":23073,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,42],"tags":[],"class_list":["post-23072","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-cosenza"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/23072","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=23072"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/23072\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/23073"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=23072"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=23072"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=23072"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}