{"id":231216,"date":"2024-05-28T15:20:04","date_gmt":"2024-05-28T13:20:04","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=231216"},"modified":"2024-05-28T15:27:36","modified_gmt":"2024-05-28T13:27:36","slug":"corigliano-rossano-vicenda-tre-emme-parla-loperaio-licenziato-gesto-discriminatorio","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/corigliano-rossano-vicenda-tre-emme-parla-loperaio-licenziato-gesto-discriminatorio\/","title":{"rendered":"Corigliano Rossano, vicenda \u201cTre Emme\u201d parla l\u2019operaio licenziato: \u2018gesto discriminatorio\u2019"},"content":{"rendered":"<p>CORIGLIANO ROSSANO &#8211; <strong>Licenziato per essersi assentato per andare a curare il figlio<\/strong>. E\u2019 accaduto a <strong>Giovanni Zangaro<\/strong>, lavoratore della societ\u00e0 cooperativa di logistica e trasporti <strong>Tre Emme di Corigliano Calabro<\/strong> che opera nella sede del centro di distribuzione Conad\u00a0in appalto per la azienda madre <strong>Pac 2000, <\/strong>in contrada Salice.<\/p>\n<p>Un licenziamento, che ha fatto scattare la <a href=\"https:\/\/quicosenza.it\/news\/ionio\/licenziato-perche-si-era-assentato-20-minuti-per-curare-il-figlio-scatta-la-protesta-dei-colleghi\">protesta dei colleghi<\/a> e dei sindacati nei confronti dell\u2019azienda. In sostanza il giovane lavoratore quando si \u00e8 allontanato per andare a sincerarsi dello stato di salute del figlio, dopo aver avvisato il responsabile del cantiere del momento, si sarebbe dimenticato di timbrare il cartellino.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CORIGLIANO ROSSANO &#8211; Licenziato per essersi assentato per andare a curare il figlio. E\u2019 accaduto a Giovanni Zangaro, lavoratore della societ\u00e0 cooperativa di logistica e trasporti Tre Emme di Corigliano Calabro che opera nella sede del centro di distribuzione Conad\u00a0in appalto per la azienda madre Pac 2000, in contrada Salice. Un licenziamento, che ha fatto [&hellip;]<\/p>\n","protected":false},"author":59,"featured_media":231220,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[572],"tags":[19,135],"class_list":["post-231216","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-ionio","tag-copertina","tag-video","post_format-post-format-video"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/231216","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/59"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=231216"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/231216\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/231220"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=231216"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=231216"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=231216"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}