{"id":231460,"date":"2024-06-02T20:00:25","date_gmt":"2024-06-02T18:00:25","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=231460"},"modified":"2024-06-02T18:45:57","modified_gmt":"2024-06-02T16:45:57","slug":"matteo-renzi-a-cosenza-per-presentare-la-lista-stati-uniti-deuropa","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/matteo-renzi-a-cosenza-per-presentare-la-lista-stati-uniti-deuropa\/","title":{"rendered":"Matteo Renzi a Cosenza per presentare la lista Stati Uniti D\u2019Europa"},"content":{"rendered":"<p>COSENZA &#8211; Domani, <strong>luned\u00ec 3 giugno, <\/strong>una occasione di dialogo politico con <strong>Matteo Renzi,<\/strong> che <strong>sar\u00e0 a Cosenza<\/strong> e presenter\u00e0 il progetto politico della Lista Stati Uniti D\u2019Europa ad elettori, elettrici e simpatizzanti.<\/p>\n<p>Insieme al senatore Renzi ci saranno<strong> i candidati Filomena Greco, Nunzia Paese, Stefano Mascaro e Giuseppe Varacalli.<\/strong> L\u2019incontro, al quale sono invitati i cittadini e le cittadine, si svolger\u00e0 (a ingresso libero fino ad esaurimento dei posti) alle ore 18,00 nello spazio del Teatro Alfonso Rendano, in Piazza XXV Marzo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Domani, luned\u00ec 3 giugno, una occasione di dialogo politico con Matteo Renzi, che sar\u00e0 a Cosenza e presenter\u00e0 il progetto politico della Lista Stati Uniti D\u2019Europa ad elettori, elettrici e simpatizzanti. Insieme al senatore Renzi ci saranno i candidati Filomena Greco, Nunzia Paese, Stefano Mascaro e Giuseppe Varacalli. L\u2019incontro, al quale sono invitati [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":176058,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42],"tags":[19],"class_list":["post-231460","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/231460","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=231460"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/231460\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/176058"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=231460"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=231460"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=231460"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}