{"id":231550,"date":"2024-06-01T11:44:21","date_gmt":"2024-06-01T09:44:21","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=231550"},"modified":"2024-06-01T13:05:49","modified_gmt":"2024-06-01T11:05:49","slug":"a2-tragico-scontro-tra-unauto-e-un-camion-tra-cosenza-e-rogliano-muore-32enne-due-i-feriti","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/a2-tragico-scontro-tra-unauto-e-un-camion-tra-cosenza-e-rogliano-muore-32enne-due-i-feriti\/","title":{"rendered":"A2: tragico scontro tra un&#8217;auto e un camion tra Cosenza e Rogliano. Muore 32enne, due i feriti"},"content":{"rendered":"<p>COSENZA &#8211; Incidente mortale sull&#8217;A2 autostrada del Mediterraneo<strong> poco prima della svincolo di Rogliano in direzione Reggio Calabria, corsia Sud<\/strong>. Il violento impatto \u00e8 avvenuto tra un autofurgone ed un auto,<strong> purtroppo il bilancio \u00e8 di una vittima<\/strong>, si tratta di un 32enne che si trovava alla guida della macchina. Ci sarebbero anche due feriti. Una in condizioni gravi.<\/p>\n<p><strong>I feriti sono stati estratti dalle lamiere e sono stati affidati al personale sanitario del Suem118<\/strong> per le cure del caso e il successivo trasferimento in ospedale.Sul posto l&#8217;elisoccorso e la polizia stradale. <strong>Attualmente a causa dell&#8217;incidente mortale il traffico, nel tratto interessato dal sinistro, \u00e8 paralizzato.<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-231558 \" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/06\/acdb8874-38b8-4a7f-9bba-54d6356c9791.jpg\" alt=\"\" width=\"502\" height=\"753\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/06\/acdb8874-38b8-4a7f-9bba-54d6356c9791.jpg 1023w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/06\/acdb8874-38b8-4a7f-9bba-54d6356c9791-200x300.jpg 200w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/06\/acdb8874-38b8-4a7f-9bba-54d6356c9791-682x1024.jpg 682w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/06\/acdb8874-38b8-4a7f-9bba-54d6356c9791-768x1152.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/06\/acdb8874-38b8-4a7f-9bba-54d6356c9791-280x420.jpg 280w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/06\/acdb8874-38b8-4a7f-9bba-54d6356c9791-150x225.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/06\/acdb8874-38b8-4a7f-9bba-54d6356c9791-300x450.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/06\/acdb8874-38b8-4a7f-9bba-54d6356c9791-696x1044.jpg 696w\" sizes=\"auto, (max-width: 502px) 100vw, 502px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>In aggiornamento<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Incidente mortale sull&#8217;A2 autostrada del Mediterraneo poco prima della svincolo di Rogliano in direzione Reggio Calabria, corsia Sud. Il violento impatto \u00e8 avvenuto tra un autofurgone ed un auto, purtroppo il bilancio \u00e8 di una vittima, si tratta di un 32enne che si trovava alla guida della macchina. Ci sarebbero anche due feriti. [&hellip;]<\/p>\n","protected":false},"author":61,"featured_media":231554,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[19],"class_list":["post-231550","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/231550","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=231550"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/231550\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/231554"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=231550"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=231550"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=231550"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}