{"id":231556,"date":"2024-06-01T12:59:20","date_gmt":"2024-06-01T10:59:20","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=231556"},"modified":"2024-06-01T12:59:20","modified_gmt":"2024-06-01T10:59:20","slug":"falso-allarme-bomba-nella-stazione-denunciato-un-40enne-cosentino","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/falso-allarme-bomba-nella-stazione-denunciato-un-40enne-cosentino\/","title":{"rendered":"Falso allarme bomba  nella stazione, denunciato un 40enne cosentino"},"content":{"rendered":"<div class=\"uk-width-2-3@m uk-first-column\">\n<div id=\"articolo\" class=\"uk-panel uk-margin\">\n<p>VICENZA &#8211; <strong>Un 40enne cosentino \u00e8 stato denunciato dalla polizia di Vicenza per aver segnalato la presenza di una bomba nella stazione ferroviaria di Vicenza<\/strong>, che \u00e8 stato accertato essere inesistente. La telefonata \u00e8 giunta al 113 poco dopo mezzanotte. Un uomo ha riferito agli operatori che all\u2019interno della stazione ferroviaria c\u2019era un ordigno esplosivo, posizionato da un terrorista latitante magrebino. Prima di attivare <strong>il piano di emergenza anti-terrorismo, gli agenti della questura hanno per\u00f2 svolto un preliminare<\/strong> accertamento sull\u2019utenza telefonica da cui proveniva la segnalazione.<\/p>\n<p>E cos\u00ec hanno constatato come l\u2019anonimo interlocutore fosse un noto mitomane, conosciuto in diverse Questure d\u2019Italia per analoghe false segnalazioni. Le ultime le aveva fatte solo qualche giorno prima a Venezia e Treviso. <strong>A scopo precauzionale sono state comunque inviate le volanti presso la stazione ferroviaria ed allertata la PolFer per dei mirati controlli, il cui esito \u00e8 stato comunque negativo<\/strong>: nessun ordigno presente nel luogo segnalato o nelle vicinanze.<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>VICENZA &#8211; Un 40enne cosentino \u00e8 stato denunciato dalla polizia di Vicenza per aver segnalato la presenza di una bomba nella stazione ferroviaria di Vicenza, che \u00e8 stato accertato essere inesistente. La telefonata \u00e8 giunta al 113 poco dopo mezzanotte. Un uomo ha riferito agli operatori che all\u2019interno della stazione ferroviaria c\u2019era un ordigno esplosivo, [&hellip;]<\/p>\n","protected":false},"author":61,"featured_media":231557,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[19],"class_list":["post-231556","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/231556","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=231556"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/231556\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/231557"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=231556"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=231556"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=231556"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}