{"id":231747,"date":"2024-06-11T10:00:02","date_gmt":"2024-06-11T08:00:02","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=231747"},"modified":"2024-06-11T09:15:40","modified_gmt":"2024-06-11T07:15:40","slug":"gerace-2-hub-laboratori-per-riscoprire-antichi-saperi-e-dare-slancio-alloccupazione","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/gerace-2-hub-laboratori-per-riscoprire-antichi-saperi-e-dare-slancio-alloccupazione\/","title":{"rendered":"Gerace: 2 Hub\/laboratori per riscoprire antichi saperi e dare slancio all\u2019occupazione"},"content":{"rendered":"<p>GERACE (RC) &#8211; Per molti secoli i cosiddetti \u201csaperi\u201d o \u201cmaestranze\u201d degli artigiani ceramisti, scalpellini, ebanisti, scultori, decoratori e restauratori, hanno rappresentato un importante asset dell\u2019<strong>economia di Gerace<\/strong>. Far riscoprire e interpretare in chiave innovativa questi \u201csaperi\u201d \u00e8 uno degli obiettivi principali che caratterizzano il grande progetto di riqualificazione urbana denominato <strong><a href=\"https:\/\/quicosenza.it\/news\/calabria\/462770-gerace-porta-del-sole-presentato-il-progetto-per-valorizzare-uno-dei-borghi-piu-belli\" target=\"_blank\" rel=\"noopener\">\u201cGerace, Porta del Sole<\/a>\u201d<\/strong>.<\/p>\n<p>Come pi\u00f9 volte detto in altri articoli, il progetto \u00e8 messo in piedi a seguito di un finanziamento di <strong>20 milioni di euro del Pnrr del Ministero della cultura destinati al Comune di Gerace<\/strong>, che vede al suo fianco la Regione Calabria. Fino al 2026, anno di chiusura dei lavori, il borgo di Gerace \u00e8 interessato da interventi di riqualificazione urbana e di valorizzazione del patrimonio storico culturale, che si diramano in pi\u00f9 direzioni.<\/p>\n<p><a href=\"https:\/\/quicosenza.it\/news\/?attachment_id=231749\" rel=\"attachment wp-att-231749\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-231749\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/06\/Gerace-Porta-Del-Sol2.jpg\" alt=\"Gerace Porta Del Sole2\" width=\"970\" height=\"617\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/06\/Gerace-Porta-Del-Sol2.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/06\/Gerace-Porta-Del-Sol2-300x191.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/06\/Gerace-Porta-Del-Sol2-768x489.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/06\/Gerace-Porta-Del-Sol2-660x420.jpg 660w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/06\/Gerace-Porta-Del-Sol2-150x95.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/06\/Gerace-Porta-Del-Sol2-696x443.jpg 696w\" sizes=\"auto, (max-width: 970px) 100vw, 970px\" \/><\/a><\/p>\n<h3><strong>I due Hub\/laboratori <\/strong><\/h3>\n<p>Uno degli interventi, tra l\u2019altro parte fondamentale dell\u2019intero progetto, \u00e8 la realizzazione di <strong>due Laboratori\/spazi creativi<\/strong> in cui i giovani possono riscoprire alcune professioni e \u201cmaestranze\u201d. \u201cSaperi\u201d legati specialmente al settore del recupero dei beni culturali o dell\u2019artigianato tipico. I due Hub\/laboratori della creativit\u00e0, dotati di attrezzature professionali, saranno in grado quindi di ospitare percorsi di ricerca, sperimentazione, apprendimento e specializzazione in settori chiave per l\u2019economia locale, come il restauro dei beni culturali e dell\u2019artigianato creativo.<\/p>\n<h3><strong>Obiettivi <\/strong><\/h3>\n<p>Attraverso i due hub ci sar\u00e0 la riscoperta in chiave innovativa del <strong>patrimonio culturale immateriale di Gerace e dell\u2019intera Calabria<\/strong>. Nei laboratori i giovani potranno formarsi e specializzarsi in restauro e artigianato artistico e creativo, che per essere messi in atto richiedono una forte specializzazione e una pratica costante sul campo. Con la realizzazione dei <strong>due hub\/laboratori, che avranno sede nei locali di edifici storici e religiosi<\/strong> a loro volta restaurati, non solo Gerace sar\u00e0 in grado di valorizzare il suo patrimonio culturale immateriale, ma creer\u00e0 i presupposti per dare un input al tasso di occupazione. Gli hub infatti avranno un ruolo decisivo nella nascita di start up dell\u2019artigianato e della creativit\u00e0 in generale. Nello specifico, il Comune e la Regione prevedono un i<strong>ncremento del 20% dell\u2019occupazione giovanile n<\/strong>onch\u00e9 una maggiore qualificazione degli artigiani locali. L\u2019intervento inoltre consentir\u00e0 di conservare e <strong>valorizzare i saperi artigianali locali e renderli competitivi sul mercato di riferimento<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>GERACE (RC) &#8211; Per molti secoli i cosiddetti \u201csaperi\u201d o \u201cmaestranze\u201d degli artigiani ceramisti, scalpellini, ebanisti, scultori, decoratori e restauratori, hanno rappresentato un importante asset dell\u2019economia di Gerace. Far riscoprire e interpretare in chiave innovativa questi \u201csaperi\u201d \u00e8 uno degli obiettivi principali che caratterizzano il grande progetto di riqualificazione urbana denominato \u201cGerace, Porta del Sole\u201d. [&hellip;]<\/p>\n","protected":false},"author":55,"featured_media":231748,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[135],"class_list":["post-231747","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-calabria","tag-video","post_format-post-format-video"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/231747","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=231747"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/231747\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/231748"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=231747"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=231747"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=231747"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}