{"id":231801,"date":"2024-06-05T10:14:27","date_gmt":"2024-06-05T08:14:27","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=231801"},"modified":"2024-06-05T10:14:27","modified_gmt":"2024-06-05T08:14:27","slug":"lotto-e-10elotto-festeggia-la-calabria-con-due-super-vincite-ad-acri-e-vibo-valentia","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/lotto-e-10elotto-festeggia-la-calabria-con-due-super-vincite-ad-acri-e-vibo-valentia\/","title":{"rendered":"Lotto e 10eLotto: festeggia la Calabria con due super vincite ad Acri e Vibo Valentia"},"content":{"rendered":"<p>COSENZA &#8211; La Calabria \u00e8 stata una delle Regioni pi\u00f9 fortunate nelle ultime estrazioni del Lotto e 10eLotto avendo fatto registrare due super vincite.<\/p>\n<p>La pi\u00f9 alta \u00e8 stata realizzata al <strong>Lotto ad Acri,<\/strong> in provincia di Cosenza, con una quaterna sulla ruota di Roma da <strong>10.500 euro, a fronte di una spesa complessiva di un solo euro<\/strong>. E&#8217; quanto riporta l&#8217;agenzia di stampa &#8216;Agimeg&#8217;.<\/p>\n<p>Al<strong> 10eLotto festeggia Vibo Valentia con un &#8216;8&#8217; da 10.000 euro<\/strong> centrato con la Modalit\u00e0 Frequente, ovvero quella che si gioca ogni 5 minuti.<\/p>\n<p>Un anno fortunato per Cosenza dove sono stati vinti <strong><a href=\"https:\/\/quicosenza.it\/news\/area-urbana\/rende-maxi-vincita-da-un-milione-di-euro-al-millionday-in-una-nota-tabaccheria\" target=\"_blank\" rel=\"noopener\">un milione di euro<\/a><\/strong>, qualche mese fa, <strong>a Rende con un MillionDAY in una nota tabaccheria.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; La Calabria \u00e8 stata una delle Regioni pi\u00f9 fortunate nelle ultime estrazioni del Lotto e 10eLotto avendo fatto registrare due super vincite. La pi\u00f9 alta \u00e8 stata realizzata al Lotto ad Acri, in provincia di Cosenza, con una quaterna sulla ruota di Roma da 10.500 euro, a fronte di una spesa complessiva di [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":220314,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17,28],"tags":[19],"class_list":["post-231801","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","category-provincia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/231801","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=231801"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/231801\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/220314"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=231801"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=231801"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=231801"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}