{"id":231986,"date":"2024-06-06T18:30:07","date_gmt":"2024-06-06T16:30:07","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=231986"},"modified":"2024-06-06T17:20:09","modified_gmt":"2024-06-06T15:20:09","slug":"sequestrate-due-discariche-abusive-su-300-metri-trovati-rifiuti-tossici-e-pneumatici-usati","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/sequestrate-due-discariche-abusive-su-300-metri-trovati-rifiuti-tossici-e-pneumatici-usati\/","title":{"rendered":"Sequestrate due discariche abusive: su 300 metri trovati rifiuti tossici e pneumatici usati"},"content":{"rendered":"<p>CATANZARO &#8211; Due discariche abusive di notevoli dimensioni sono state sequestrate al termine di un&#8217;operazione della Polizia locale di Catanzaro nella zona sud della citt\u00e0. In particolare,<strong> personale del nucleo di Polizia ambientale, diretto dal tenente colonnello Salvatore Tarantino &#8211; con la supervisione del comandante Vincenzo Ruocco e su input del sindaco Nicola Fiorita &#8211; sono intervenuti in Viale Isonzo e in localit\u00e0 Aranceto<\/strong>, per eseguire rilievi e verifiche riguardo all&#8217;ipotesi di reato di gestione illecita di rifiuti e l&#8217;inquinamento delle acque superficiali e del suolo. Le discariche sono state trovate<strong> in aree scoperte su terreno naturale, privo di impermeabilizzazione, e esposte agli agenti atmosferici e al dilavamento delle acque meteorich<\/strong>e, in assenza di sistemi per il coinvolgimento e lo smaltimento, e nelle adiacenze di civili abitazioni.<\/p>\n<p>In viale Isonzo \u00e8 stata sequestrata un&#8217;area di 110 metri quadri su cui erano depositati in maniera incontrollata, circa 150 metri cubi di rifiuti speciali pericolosi, alcuni dei quali etichettati come nocivi e tossici, con probabile presenza di amianto. <strong>Nella seconda area, sequestrata in localit\u00e0 Aranceto, estesa per circa 180 metri quadri, sono stati trovati rifiuti speciali infiammabili, nei pressi di alcune case, con un pericolo di incendio, a causa della presenza di un cumulo di pneumatici usati per quasi 150 metri cubi.<\/strong> La Polizia locale ha denunciato i due presunti trasgressori all&#8217;Autorit\u00e0 giudiziaria e proceder\u00e0 a disporre nei loro confronti, previa ratifica da parte dell&#8217;Arpacal, le prescrizioni per lo smaltimento a norma dei rifiuti nelle zone interessate. &#8220;Devo ringraziare il nucleo di Polizia ambientale &#8211; commenta l&#8217;assessora alla sicurezza Marinella Giordano &#8211; che ha lavorato, con impegno e grandi sacrifici, per tre giorni in questa operazione che contribuisce a dare evidenza dell&#8217;attenzione dell&#8217;Amministrazione nella periferia sud della citt\u00e0.<\/p>\n<p>Parliamo di aree messe a rischio dalla presenza di cumuli di rifiuti a cielo aperto, in gran parte pericolosi per la salute dei residenti. Con pochi uomini e poche risorse, la Polizia locale sta facendo il massimo per tradurre, in azioni concrete, obiettivi fondamentali come la tutela del territorio, il decoro urbano e la sicurezza su cui non si pu\u00f2 transigere&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CATANZARO &#8211; Due discariche abusive di notevoli dimensioni sono state sequestrate al termine di un&#8217;operazione della Polizia locale di Catanzaro nella zona sud della citt\u00e0. In particolare, personale del nucleo di Polizia ambientale, diretto dal tenente colonnello Salvatore Tarantino &#8211; con la supervisione del comandante Vincenzo Ruocco e su input del sindaco Nicola Fiorita &#8211; [&hellip;]<\/p>\n","protected":false},"author":61,"featured_media":231987,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[19],"class_list":["post-231986","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/231986","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=231986"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/231986\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/231987"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=231986"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=231986"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=231986"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}