{"id":231989,"date":"2024-06-06T17:25:23","date_gmt":"2024-06-06T15:25:23","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=231989"},"modified":"2024-06-06T17:25:23","modified_gmt":"2024-06-06T15:25:23","slug":"abramo-customer-care-mille-lavoratori-a-rischio-in-calabria-400-in-corteo","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/abramo-customer-care-mille-lavoratori-a-rischio-in-calabria-400-in-corteo\/","title":{"rendered":"Abramo customer care, mille lavoratori a rischio in Calabria: 400 in corteo"},"content":{"rendered":"<p>CATANZARO &#8211; Circa 400 dei mille lavoratori della Abramo Customer Care hanno manifestato stamani davanti al centro Tim di Catanzaro per richiamare l&#8217;attenzione delle istituzioni e della Tim sulla loro situazione.<strong> A fine giugno infatti scade l&#8217;ultima proroga del contratto con la Tim e i mille dipendenti rischiano il licenziamento per la crisi del settore dei call center e la fine delle commesse. <\/strong>Alla manifestazione, promossa dai sindacati Slc Cgil, Fistel Cisl, Uilcom Uil e Ugl Telecomunicazioni, hanno partecipato lavoratori provenienti dalle sedi di Settingiano, Crotone e Montalto Uffugo. Al loro fianco anche i sindaci di Catanzaro e Crotone, Nicola Fiorita e Vincenzo Voce.<\/p>\n<p>&#8220;Si tratta &#8211; ha detto Fiorita &#8211; di una grandissima difficolt\u00e0, in una citt\u00e0 come la nostra, dove il lavoro vale triplo perch\u00e9 chi lo perde poi non lo ritrova pi\u00f9. Noi abbiamo partecipato molto volentieri al Consiglio comunale di Crotone. Ritengo che sia necessario adottare tutte le misure per dare ossigeno a questi lavoratori.<strong> Devo dire che la Regione sta facendo tutto il possibile da questo punto di vista. Queste per\u00f2 sono misure emergenziali che possono dare il tempo per arrivare a una misura strutturale che va ricercata con grandissimo coraggio anche immaginando che si possano affidare a personale qualificato come quello che ha lavorato fino ad oggi per la Tim<\/strong>, servizi che possono essere svolti per la Regione o altri enti, per garantire la vera sopravvivenza di queste famiglie. Le istituzioni stanno facendo la loro parte, adesso deve farlo Tim per dare il tempo di trovare soluzioni strutturali&#8221;. &#8220;La criticit\u00e0 &#8211; ha detto Voce &#8211; \u00e8 sotto gli occhi di tutti. Tim deve rendersi conto che i volumi di traffico devono andare ai nostri lavoratori. Che non pensassero di distribuirli in altri centri. Non possiamo permetterci di perdere nemmeno un lavoratore.<\/p>\n<p>Dobbiamo unire le forze per portare a casa un risultato che si sta protraendo ormai da troppo tempo. Sono tre anni che viviamo questa situazione da incubo. Dobbiamo salvare i posti di lavoro e concentrarci su questo obiettivo.<strong> Di sicuro il presidente Occhiuto sta facendo tanto, ma qui serve l&#8217;intervento del governo. Per situazioni simili, con poche decine di lavoratori, convocano tavoli su tavoli e qui sembra che ci siano lavoratori di serie A e di serie B. Noi non molliamo, vedremo come continuare la protesta, perch\u00e9 ripeto i volumi di traffico devono restare a questi lavoratori&#8221;<\/strong>. Per i sindacati si tratta di &#8220;una mobilitazione che continuer\u00e0 per avere delle risposte dal committente che \u00e8 Tim.<\/p>\n<p>Occorre una maggiore sensibilit\u00e0 da parte della politica a tutti i livelli. Roberto Occhiuto e l&#8217;assessore regionale al lavoro Giovanni Calabrese stanno seguendo la vicenda per mettere a terra una potenziale soluzione.<strong> Inevitabile che il tavolo che stiamo chiedendo al ministero sar\u00e0 quello all&#8217;interno del quale si dovr\u00e0 comunque trovare una soluzione per mettere al sicuro il perimetro occupazionale di mille lavoratori di questa regione che gi\u00e0 soffre dal punto di vista del lavoro.<\/strong> Si parla a livello nazionale, giustamente, di vertenze che riguardano anche 100-150 persone, \u00e8 preoccupante che qui ci siano mille posti di lavoro nell&#8217;incertezza e se ne parli poco&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>CATANZARO &#8211; Circa 400 dei mille lavoratori della Abramo Customer Care hanno manifestato stamani davanti al centro Tim di Catanzaro per richiamare l&#8217;attenzione delle istituzioni e della Tim sulla loro situazione. A fine giugno infatti scade l&#8217;ultima proroga del contratto con la Tim e i mille dipendenti rischiano il licenziamento per la crisi del settore [&hellip;]<\/p>\n","protected":false},"author":61,"featured_media":231990,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[19],"class_list":["post-231989","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/231989","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=231989"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/231989\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/231990"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=231989"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=231989"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=231989"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}