{"id":23200,"date":"2013-06-06T11:28:54","date_gmt":"2013-06-06T09:28:54","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=23200"},"modified":"2023-01-17T13:20:48","modified_gmt":"2023-01-17T12:20:48","slug":"9190-evasione-o-lupara-bianca-il-pentito-lo-giudice-scompare-dalla-localita-segreta","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/9190-evasione-o-lupara-bianca-il-pentito-lo-giudice-scompare-dalla-localita-segreta\/","title":{"rendered":"Evasione o lupara bianca? Il pentito Lo Giudice scompare dalla &#8216;casa segreta&#8217;"},"content":{"rendered":"<p style=\"text-align: justify;\">REGGIO CALABRIA \u2013 Nessuna traccia del boss.<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">A dare la conferma dell\u2019irreperibilit\u00e0 del collaboratore di giustizia prima a capo dell\u2019omonima cosca \u00e8 la direzione distrettuale antimafia. Il pentito di \u2018ndrangheta pare non sia pi\u00f9 nella localit\u00e0 protetta presso la quale stava scontando gli arresti domiciliari. Stamattina l\u2019ex ras di Reggio Calabria avrebbe dovuto essere ascoltato come teste nell\u2019udienza del processo Archi-Astrea sugli affari della cosca di Archi e i legami con i vertici della politica reggina nonch\u00e9 dei rapporti tra \u2018Ndrangheta, Comune di Reggio Calabria e Regione Calabria. Il giudice Giuseppe Campagna ha per\u00f2 comunicato che l&#8217;uomo non sarebbe stato sentito per problemi tecnici nella traduzione al sito protetto da cui eseguire il collegamento in video conferenza. Lo Giudice rappresenta uno dei pi\u00f9 importanti, quindi pericolosi, pentiti della \u2018ndrangheta. Un personaggio scomodo da eliminare. Nel corso della sua collaborazione con gli inquirenti Lo Giudice si \u00e8 autoaccusato delle bombe esplose sotto l\u2019ufficio della Procura generale di Reggio Calabria nel gennaio 2010, sotto l\u2019abitazione del pg Salvatore di Landro nell\u2019agosto dello stesso anno, e del lanciarazzi fatto trovare a duecento metri dagli uffici giudiziari come segnale intimidatorio nei confronti dei magistrati reggini. Le autorit\u00e0 stanno attualmente indagando per rintracciare Antonino Lo Giudice. Vivo o morto.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>REGGIO CALABRIA \u2013 Nessuna traccia del boss.<\/p>\n","protected":false},"author":22,"featured_media":23201,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-23200","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/23200","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=23200"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/23200\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/23201"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=23200"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=23200"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=23200"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}