{"id":232543,"date":"2024-06-12T14:38:17","date_gmt":"2024-06-12T12:38:17","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=232543"},"modified":"2024-06-12T14:38:17","modified_gmt":"2024-06-12T12:38:17","slug":"primato-unical-domande-in-crescita-per-il-quinto-anno-consecutivo-28","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/primato-unical-domande-in-crescita-per-il-quinto-anno-consecutivo-28\/","title":{"rendered":"Primato Unical: domande in crescita per il quinto anno consecutivo (+28)"},"content":{"rendered":"<p>RENDE (CS) &#8211; \u00c8 in costante crescita la capacit\u00e0 attrattiva dell\u2019Universit\u00e0 della Calabria. Lo testimoniano, ancora una volta, le domande di partecipazione al <strong><a href=\"https:\/\/quicosenza.it\/news\/universita\/unical-parte-lammissione-anticipata-per-i-corsi-di-laurea-magistrale-ecco-come-iscriversi\" target=\"_blank\" rel=\"noopener\">bando di ammissione anticipata<\/a> ai corsi di laurea triennale<\/strong> e a ciclo unico per il 2024\/2025 che fanno segnare un dato davvero considerevole: <strong>28% di studenti in pi\u00f9 rispetto all\u2019anno accademico precedente,<\/strong> che a sua volta aveva fatto registrare un aumento del 31% sui numeri del 2022\/2023.<\/p>\n<h3><strong>Segno \u201cpi\u00f9\u201d per il quinto anno consecutivo<\/strong><\/h3>\n<p>Dopo oltre un decennio di calo degli iscritti fino al 2019\/20, per il quinto anno consecutivo dall\u2019insediamento del rettore Nicola Leone, l\u2019Unical migliora i suoi numeri.\u00a0<strong>Lo scorso anno erano arrivate 2.252 domande di ammissione anticipata,<\/strong> correttamente corredate dal certificato ottenuto con il Tolc (Test on line Cisia), mentre <strong>quest\u2019anno sono 2.873.<\/strong> Un aumento di<strong> ben 621 studenti,<\/strong> pari al 28%; mentre rispetto al 2019\/20, anno di inizio dell\u2019attuale mandato rettorale, le domande sono pi\u00f9 che raddoppiate, con un incremento di 1.628 studenti, pari al 131% in pi\u00f9.<\/p>\n<p>Salgono le istanze di iscrizione a quasi tutti i corsi di laurea triennali e a ciclo unico che prevedono l\u2019ammissione anticipata: <strong>tra i pi\u00f9 richiesti Ingegneria informatica<\/strong> con 291 domande, <strong>Economia aziendale<\/strong> (189),<strong> Informatica<\/strong> (187),<strong> Ingegneria gestionale<\/strong> (185),<strong> Lettere e beni culturali e Ingegneria meccanica<\/strong> (151).<\/p>\n<h3><strong>Unical controcorrente<\/strong><\/h3>\n<p>Numeri in assoluta controtendenza con il quadro nazionale e, in particolare, rispetto alle drammatiche previsioni sul futuro delle universit\u00e0 del Mezzogiorno. Basti pensare che dal 2011 al 2021 gli atenei del Sud hanno perso oltre 100 mila iscritti (dati Anvur) e che \u2013 a causa del calo demografico e dell\u2019emigrazione \u2013 secondo l\u2019ultimo rapporto Svimez entro il 2041 potrebbe verificarsi un ulteriore calo del 27% degli iscritti nel Meridione.<\/p>\n<p>E se il contrasto al possibile calo di iscritti passa anche attraverso il potenziamento dell\u2019attrattivit\u00e0 internazionale, \u00e8 da sottolineare il dato sulle domande di studenti extra Ue che arrivano a quota 154 (con una crescita del 157% nel confronto con lo scorso anno).<\/p>\n<h3><strong>Premiata la formazione di qualit\u00e0 e in presenza<\/strong><\/h3>\n<p>\u00abSempre pi\u00f9 giovani scelgono l\u2019Unical come sede di studio universitaria, \u2013 commenta il rettore Leone \u2013 per la qualit\u00e0 di un\u2019offerta formativa in costante aggiornamento e le tante opportunit\u00e0 offerte dal nostro campus. La crescita del 28% delle domande di ammissione anticipata, rispetto al 2023\/2024, e addirittura del 131% nel confronto con il primo anno del mio mandato rettorale, ci riempie di fiducia, in attesa dei dati definitivi sulle iscrizioni che giungeranno al termine delle due successive fasi di ammissione\u00bb.<\/p>\n<p>Certamente meno esposte al declino demografico del Paese e ai flussi migratori negativi sono le universit\u00e0 online, che secondo l\u2019ultimo rapporto realizzato dall\u2019Area Studi Mediobanca hanno fatto segnare un\u2019enorme crescita degli iscritti negli ultimi dodici anni. \u00abSono convinto che la formazione delle universit\u00e0 telematiche \u2013 commenta il Rettore \u2013 che si riceve attraverso lo schermo di un computer, senza possibilit\u00e0 di confronto, non sia paragonabile a quella delle universit\u00e0 in presenza. La vera natura della formazione universitaria non pu\u00f2 prescindere dal confronto umano, diretto e quotidiano, con i docenti e con gli altri studenti. \u00c8 cos\u00ec, attraverso il confronto e le relazioni socio-culturali,\u00a0che si forma la coscienza critica e si forgiano i protagonisti del futuro, capaci di affrontare le sfide di una societ\u00e0 in continua evoluzione\u00bb.<\/p>\n<h3><strong>Ammissione standard<\/strong><\/h3>\n<p>Chi non riuscir\u00e0 ad entrare in questa prima fase in un corso di laurea triennale e a ciclo unico potr\u00e0 comunque partecipare all\u2019ammissione standard, il cui bando sar\u00e0 pubblicato a fine giugno nella <a href=\"https:\/\/www.unical.it\/didattica\/iscriversi-studiare-laurearsi\/ammissioni\/\" rel=\"noopener\">sezione dedicata<\/a>\u00a0del portale di ateneo.<\/p>\n<p>Per tutti i corsi sar\u00e0 previsto lo svolgimento dei Tolc necessario per stilare le graduatorie per selezionare gli ammessi in caso di saturazione dei posti a bando. Ma il test \u00e8 innanzitutto uno strumento di verifica del possesso di un\u2019adeguata preparazione iniziale. L\u2019eventuale accertamento della presenza di lacune comporter\u00e0 l\u2019assegnazione di obblighi formativi aggiuntivi (OFA) che potranno in ogni caso essere estinti seguendo i pre-corsi erogati dall\u2019ateneo a settembre e superando il relativo esame. I candidati che non sosterranno il Tolc saranno inseriti in coda in graduatoria con l\u2019assegnazione del punteggio minimo al test e l\u2019attribuzione di tutti gli obblighi formativi previsti.<\/p>\n<h3><strong>Lauree magistrali<\/strong><\/h3>\n<p>\u00c8 gi\u00e0 aperta la fase di <a href=\"https:\/\/www.unical.it\/didattica\/iscriversi-studiare-laurearsi\/ammissioni\/ammissione-lauree-magistrali\/\" rel=\"noopener\">ammissione anticipata ai corsi di laurea magistrale<\/a>\u00a0dell\u2019Unical. Possono partecipare anche gli studenti che non sono ancora in possesso del titolo di accesso, ma che lo conseguiranno entro l\u2019anno accademico 2023\/2024 (prima della laurea triennale non sar\u00e0 possibile sostenere esami della magistrale). L\u2019Unical intende cos\u00ec garantire ai suoi studenti la piena continuit\u00e0 del percorso di studio, evitando i ritardi e le interruzioni che potrebbero generarsi nel passaggio da triennale a magistrale.<\/p>\n<p>L\u2019offerta formativa \u00e8 molto ampia, con 38 corsi di cui 10 erogati interamente in lingua inglese, che rafforzano la vocazione internazionale dell\u2019Universit\u00e0 della Calabria. Per favorire l\u2019iscrizione di studenti europei ed extra regionali, l\u2019accesso a tali corsi sar\u00e0 regolato tramite colloqui online.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>RENDE (CS) &#8211; \u00c8 in costante crescita la capacit\u00e0 attrattiva dell\u2019Universit\u00e0 della Calabria. Lo testimoniano, ancora una volta, le domande di partecipazione al bando di ammissione anticipata ai corsi di laurea triennale e a ciclo unico per il 2024\/2025 che fanno segnare un dato davvero considerevole: 28% di studenti in pi\u00f9 rispetto all\u2019anno accademico precedente, [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":232544,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[7],"tags":[19],"class_list":["post-232543","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-universita","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/232543","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=232543"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/232543\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/232544"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=232543"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=232543"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=232543"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}