{"id":232647,"date":"2024-06-14T07:48:22","date_gmt":"2024-06-14T05:48:22","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=232647"},"modified":"2024-06-14T14:49:43","modified_gmt":"2024-06-14T12:49:43","slug":"minaccia-di-morte-sui-sociale-dalle-brigate-rosse-denunciato-lautore-e-solo-un-mitomane","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/minaccia-di-morte-sui-sociale-dalle-brigate-rosse-denunciato-lautore-e-solo-un-mitomane\/","title":{"rendered":"Minaccia di morte sui sociale dalle &#8220;Brigate Rosse&#8221;: denunciato l&#8217;autore, \u00e8 solo un mitomane"},"content":{"rendered":"<p>GIOIA TAURO &#8211; \u201cL\u2019esercito rivoluzionario ha promulgato sentenza definitiva di morte\u201d. Cos\u00ec iniziava il commento minatorio, poi eliminato, rivolto nei confronti dei cosiddetti \u201cdiarchi fascisti\u201d, due politici, uno dei quali gi\u00e0 deputato.<strong> Negli ultimi mesi dello scorso anno, in alcuni video sulla piattaforma \u201cyoutube\u201d, erano apparsi dei commenti decisamente preoccupanti, nei confronti dei due politici che, preoccupati per la propria incolumit\u00e0, si erano rivolti ai Carabinieri<\/strong>.<\/p>\n<p>I militari della Stazione di Gioia Tauro, da subito si attivavano al fine di individuare i possibili autori, <strong>nascosti dietro ambigui nickname visibili dalla piattaforma social, che riportavano anche la sigla \u201cKGB\u201d nel nome<\/strong>. \u201cSappiamo dove abiti, cosa mangi, a che ora hai preso il treno\u201d, \u201csar\u00e0 eseguita la sentenza di morte da parte del plotone di esecuzione proletario\u201d, era il tenore di alcuni commenti che, dopo poco, erano stati subito rimossi dagli autori, evidentemente pi\u00f9 lenti dei Carabinieri che, da subito, li avevano individuati.<\/p>\n<p>In alcuni commenti, alle minacce presenti, veniva aggiunta la firma \u201cBR \u2013 PCC\u201d, chiaramente riconducibile all<strong>e \u201cBrigate Rosse, Partito Comunista Combattente\u201d o quella delle \u201cNBR\u201d (Nuove Brigate Rosse),<\/strong> particolarmente evocatrice di anni che hanno visto cadere, anche in tempi pi\u00f9 recenti, alcuni servitori dello Stato. Le due vittime, sono entrambe politicamente attive: una, oltre all\u2019impegno politico cura, tra l\u2019altro, un canale \u201cyoutube\u201d particolarmente seguito.<\/p>\n<p>Il fatto che venissero citati luoghi specifici dove effettivamente le vittime vivevano o erano temporaneamente transitate, aveva indotto gli investigatori a non sottovalutare assolutamente il contenuto dei messaggi, attivando da subito ogni pista investigativa. Le indagini successive, hanno fatto ritenere opportuno il coinvolgimento del Raggruppamento Operativo Speciale dei Carabinieri, che ha condotto tutti gli approfondimenti necessari, grazie all\u2019altissima specializzazione del proprio personale. Con l\u2019aiuto di tali specialisti, si \u00e8 potuto individuare, in maniera univoca, <strong>la persona che si celava dietro ai commenti minatori.<\/strong><\/p>\n<p>Fortunatamente, gli accertamenti effettuati, hanno permesso di escludere, con ragionevole certezza, ogni collegamento con ambienti dell\u2019eversione, considerando il gesto come un\u2019iniziativa di un singolo individuo,<strong> un mitomane, residente in Trentino-Alto Adige.<\/strong> L\u2019evento, oltre a sottolineare la nuova importanza che sempre pi\u00f9 hanno i reati informatici, soprattutto tramite l\u2019esplosione dei social media, non deve far sottovalutare le conseguenze che possono avere alcune esternazioni nel mondo virtuale.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>GIOIA TAURO &#8211; \u201cL\u2019esercito rivoluzionario ha promulgato sentenza definitiva di morte\u201d. Cos\u00ec iniziava il commento minatorio, poi eliminato, rivolto nei confronti dei cosiddetti \u201cdiarchi fascisti\u201d, due politici, uno dei quali gi\u00e0 deputato. Negli ultimi mesi dello scorso anno, in alcuni video sulla piattaforma \u201cyoutube\u201d, erano apparsi dei commenti decisamente preoccupanti, nei confronti dei due politici [&hellip;]<\/p>\n","protected":false},"author":61,"featured_media":231708,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[19],"class_list":["post-232647","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/232647","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=232647"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/232647\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/231708"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=232647"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=232647"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=232647"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}