{"id":232698,"date":"2024-06-18T06:30:13","date_gmt":"2024-06-18T04:30:13","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=232698"},"modified":"2024-06-14T14:20:24","modified_gmt":"2024-06-14T12:20:24","slug":"vertenze-abramo-cc-e-tirocinanti-occhiuto-domani-incontra-i-sindacati","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/vertenze-abramo-cc-e-tirocinanti-occhiuto-domani-incontra-i-sindacati\/","title":{"rendered":"Vertenze Abramo CC e tirocinanti, Occhiuto domani incontra i sindacati"},"content":{"rendered":"<p>COTRONEI &#8211; &#8220;<strong>Mercoled\u00ec 19 giugno<\/strong> avr\u00f2 un <strong>incontro con Cgil, Cisl e Uil<\/strong> sulla vertenza <strong>dell&#8217;Abramo Customar Care<\/strong> e sui <strong>tirocinanti<\/strong> di inclusione sociale&#8221;. E&#8217; quanto ha annunciato nei giorni scorsi il presidente della Regione, Roberto Occhiuto, a margine di un&#8217;iniziativa della Cisl a &#8220;Villaggio Palumbo&#8221;, a Cotronei.<\/p>\n<p>&#8220;L&#8217;incontro mi \u00e8 stato sollecitato dalle stesse organizzazioni sindacali e ho ritenuto di convocarlo nel pi\u00f9 breve tempo possibile&#8221;. &#8220;<strong>Su queste vertenze<\/strong>, per\u00f2 &#8211; ha aggiunto Occhiuto &#8211; <strong>io ci lavoro quotidianamente<\/strong>. Sto avendo <strong>un&#8217;interlocuzione costante con il governo e con Tim<\/strong>, a cui ho spiegato che la Regione \u00e8 disposta a intervenire anche con risorse proprie per favorire il &#8216;<strong>reskilling&#8217; di questi lavoratori. <\/strong>\u00c8 una <strong>vicenda complessa e gigantesca<\/strong> che riguarda circa mille persone in Calabria. So che il tempo stringe e per questo ci sto lavorando ogni giorno. E intanto mercoled\u00ec ascolter\u00f2 anche i sindacati&#8221;.<\/p>\n<p><strong>&#8220;Per quanto riguarda invece i Tirocinanti<\/strong>, si tratta di una vicenda che <strong>io ho ereditato<\/strong>. E credo che nessun governo regionale si sia impegnato pi\u00f9 del mio in questi anni per tentare di dare dignit\u00e0 a queste persone. Stiamo individuando percorsi che possano prevedere un progressivo assorbimento di questo bacino, ma \u00e8 chiaro che saranno prorogati perch\u00e9 non si possono lasciare a casa quattromila persone&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COTRONEI &#8211; &#8220;Mercoled\u00ec 19 giugno avr\u00f2 un incontro con Cgil, Cisl e Uil sulla vertenza dell&#8217;Abramo Customar Care e sui tirocinanti di inclusione sociale&#8221;. E&#8217; quanto ha annunciato nei giorni scorsi il presidente della Regione, Roberto Occhiuto, a margine di un&#8217;iniziativa della Cisl a &#8220;Villaggio Palumbo&#8221;, a Cotronei. &#8220;L&#8217;incontro mi \u00e8 stato sollecitato dalle stesse [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":232699,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[17],"tags":[19],"class_list":["post-232698","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-calabria","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/232698","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=232698"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/232698\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/232699"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=232698"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=232698"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=232698"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}