{"id":232870,"date":"2024-06-18T09:24:46","date_gmt":"2024-06-18T07:24:46","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=232870"},"modified":"2024-06-18T09:26:23","modified_gmt":"2024-06-18T07:26:23","slug":"strade-dissestate-a-donnici-presto-un-cronoprogramma-di-interventi","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/strade-dissestate-a-donnici-presto-un-cronoprogramma-di-interventi\/","title":{"rendered":"Strade dissestate a Donnici, presto un cronoprogramma di interventi"},"content":{"rendered":"<p>COSENZA &#8211; Proseguono i sopralluoghi in citt\u00e0 per fare il punto della situazione sui lavori di bonifica gi\u00e0 iniziati e gli interventi da effettuare e i consiglieri comunali Daniela Puzzo e Francesco Gigliotti, hanno avuto modo di effettuare un giro nella <strong>frazione di Donnici. <\/strong>Grazie anche all\u2019aiuto dei cittadini, hanno potuto constatare le situazioni pi\u00f9 critiche.<\/p>\n<p>\u201cDa <strong>Contrada Colla<\/strong>\u00a0a <strong>Calacroce<\/strong>, la strada che collega Donnici superiore e inferiore, abbiamo verificato le <strong>criticit\u00e0 del manto stradale<\/strong> delle zone di <strong>Lucido, Albo, Fiego, Falco di Fiego, Colli.<\/strong> Subito dopo \u2013 spiegano i consiglieri Puzzo e Gigliotti &#8211; abbiamo incontrato il dirigente Raffaele Notte, del Settore manutenzione, per illustrare lo stato dei luoghi e predisporre un intervento ad hoc. <strong>Alcune strade saranno bitumate, per altre saranno effettuati i primi rattoppi&#8221;.<\/strong><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-232872 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/06\/sopralluogo-donnici-consiglieri-puzzo-gigliotti-02.jpg\" alt=\"\" width=\"594\" height=\"368\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/06\/sopralluogo-donnici-consiglieri-puzzo-gigliotti-02.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/06\/sopralluogo-donnici-consiglieri-puzzo-gigliotti-02-300x186.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/06\/sopralluogo-donnici-consiglieri-puzzo-gigliotti-02-768x475.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/06\/sopralluogo-donnici-consiglieri-puzzo-gigliotti-02-679x420.jpg 679w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/06\/sopralluogo-donnici-consiglieri-puzzo-gigliotti-02-150x93.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/06\/sopralluogo-donnici-consiglieri-puzzo-gigliotti-02-696x431.jpg 696w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/06\/sopralluogo-donnici-consiglieri-puzzo-gigliotti-02-356x220.jpg 356w\" sizes=\"auto, (max-width: 594px) 100vw, 594px\" \/><\/p>\n<p>&#8220;Siamo al lavoro \u2013 assicurano i consiglieri &#8211; per poter predisporre, insieme al dirigente Notte, <strong>un Piano di manutenzione e stilare un cronoprogramma<\/strong> degli interventi da effettuare al pi\u00f9 presto. L\u2019amministrazione comunale in questi anni si \u00e8 da subito messa al lavoro per la riqualificazione di importanti aree degradate della citt\u00e0. Ed \u00e8 stato lo stesso sindaco Franz Caruso e il dirigente del settore a chiedere il supporto di tutti i consiglieri in modo da essere costantemente presenti sul territorio e rispondere alle esigenze dei cittadini. Continua l\u2019opera di <strong>recupero degli spazi verdi e sicurezza delle strade<\/strong>. Dobbiamo, per\u00f2, fare i conti anche con le risorse a disposizione dell\u2019Ente e la complessit\u00e0 delle varie criticit\u00e0 presenti in alcune zone della citt\u00e0. La nostra presenza sul territorio \u00e8 costante e continueremo ad <strong>effettuare dei sopralluoghi nei prossimi giorni in base alle segnalazioni arrivate anche dai cittadini\u201d.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Proseguono i sopralluoghi in citt\u00e0 per fare il punto della situazione sui lavori di bonifica gi\u00e0 iniziati e gli interventi da effettuare e i consiglieri comunali Daniela Puzzo e Francesco Gigliotti, hanno avuto modo di effettuare un giro nella frazione di Donnici. Grazie anche all\u2019aiuto dei cittadini, hanno potuto constatare le situazioni pi\u00f9 [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":232871,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42],"tags":[19],"class_list":["post-232870","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/232870","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=232870"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/232870\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/232871"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=232870"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=232870"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=232870"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}