{"id":232967,"date":"2024-06-19T09:04:43","date_gmt":"2024-06-19T07:04:43","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=232967"},"modified":"2024-06-19T10:42:06","modified_gmt":"2024-06-19T08:42:06","slug":"maturita-2024-ecco-le-tracce-della-prima-prova-ci-sono-ungaretti-pirandello-e-montalcini","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/maturita-2024-ecco-le-tracce-della-prima-prova-ci-sono-ungaretti-pirandello-e-montalcini\/","title":{"rendered":"Maturit\u00e0 2024, ecco le tracce della prima prova: Ungaretti, Pirandello, Montalcini, patrimonio artistico selfie\u00a0e\u00a0blog"},"content":{"rendered":"<p>ROMA &#8211; <strong>Ungaretti per l\u2019analisi della poesia poetica e Pirandello, testo in prosa, attesissimi<\/strong>. Poi un testo tratto da <strong>\u201cStoria d\u2019Europa\u201d di Galasso che invita i maturandi a riflettere sulla bomba atomica<\/strong>. Ancora,<strong> l\u2019elogio dell\u2019imperfezione di Rita Levi Montalcini<\/strong>, una riflessione su\u00a0<strong>selfie\u00a0<\/strong>e\u00a0<strong>blog<\/strong>, &#8220;<strong>Arte, musica, poesia, Natura fra ascolto e comunicazione<\/strong>&#8220;<strong> di Nicoletta\u00a0Polla-Mattiot<\/strong> o il<strong>\u00a0patrimonio artistico da un testo della giurista Maria Agostina Cabiddu<\/strong>. Alle 8.30 sono state distribuite le <strong>sette tracce per la prima prova scritta, quella di Italiano<\/strong>, nella\u00a0 <a href=\"https:\/\/quicosenza.it\/news\/area-urbana\/ansia-ed-e-emozioni-speranze-e-motivazioni-esami-di-stato-al-via-per-circa-6mila-maturandi-cosentini\" target=\"_blank\" rel=\"noopener\">Maturit\u00e0 2024.<\/a><\/p>\n<h3>Il Ministro Valditara: \u201cAvrei scelto il tema di storia\u201d<\/h3>\n<p>&#8220;<strong>Avrei scelto la traccia storica. La storia mi piace molto \u00e8 una materia di grande riliev<\/strong>o, di grande importanza perch\u00e9 costruisce il nostro passato, la nostra identit\u00e0 e risponde alla domanda chi siamo e che vogliamo essere. Ma in realt\u00e0 non posso rispondere, non posso approfondire fino all&#8217;uscita ufficiale delle tracce&#8221;. L<strong>o ha detto il ministro dell&#8217;Istruzione e del Merito, Giuseppe Valditara<\/strong>, a SkyTg24.<\/p>\n<p><strong>TUTTE LE SETTE TRACCE<\/strong><\/p>\n<p><span style=\"color: #ff0000;\"><strong>Tipologia A (Analisi del testo)<\/strong><\/span><br \/>\nA1: Testo poetico di <strong>Giuseppe Ungaretti<br \/>\n<\/strong>A2: Testo in prosa di\u00a0<strong>Luigi Pirandello<\/strong><\/p>\n<p><span style=\"color: #ff0000;\"><strong>Tipologia B (Testo argomentativo)<\/strong><\/span><br \/>\nB1: <strong>&#8220;Storia d&#8217;Europa&#8221;<\/strong> di<strong>\u00a0<\/strong>Giuseppe Galasso<br \/>\nB2: Testo tratto da Maria Agostina\u00a0<strong>Cabiddu\u00a0<\/strong>in &#8220;Rivista Aic (Associazione italiana dei costituzionalisti)&#8221;<br \/>\nB3: &#8220;<strong>Riscoprire il silenzio. Arte, musica, poesia, Natura fra ascolto e comunicazione<\/strong>&#8221; di Nicoletta\u00a0<strong>Polla-Mattiot<\/strong><\/p>\n<p><span style=\"color: #ff0000;\"><strong>Tipologia C (Tema di attualit\u00e0)<\/strong><\/span><br \/>\nC1: Testo tratto da\u00a0<strong>Rita Levi Montalcini in &#8220;Elogio dell&#8217;imperfezione&#8221;<\/strong><br \/>\nC2: Testo tratto da Maurizio Camilito in &#8220;<strong>Profili, selfie e blog<\/strong>&#8221;<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-232955 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/06\/Maturita-telesio.jpg\" alt=\"\" width=\"568\" height=\"320\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/06\/Maturita-telesio.jpg 1600w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/06\/Maturita-telesio-300x169.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/06\/Maturita-telesio-1024x576.jpg 1024w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/06\/Maturita-telesio-768x432.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/06\/Maturita-telesio-1536x864.jpg 1536w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/06\/Maturita-telesio-747x420.jpg 747w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/06\/Maturita-telesio-150x84.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/06\/Maturita-telesio-696x392.jpg 696w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/06\/Maturita-telesio-1068x601.jpg 1068w\" sizes=\"auto, (max-width: 568px) 100vw, 568px\" \/><\/p>\n<p><strong>Giuseppe Ungaretti e Luigi Pirandello<\/strong><\/p>\n<p><strong>&#8216;Pellegrinaggio&#8217;\u00a0la poesia di Giuseppe Ungaretti<\/strong>\u00a0 \u00e8 la prima traccia della prima prova scritta della Maturit\u00e0 2024. Tratta dalla raccolta &#8216;Vita di un uomo\u201d,\u00a0<strong>Giuseppe Ungaretti<\/strong>\u00a0racconta la propria esperienza<strong> di soldato sul fronte del Carso durante la Prima guerra mondiale<\/strong>. Scritta nell\u2019agosto del 1916 a Valloncello del Carso, insieme ad altre liriche come \u201cSono una creatura\u201d, \u201cIn dormiveglia\u201d, \u201cMonotonia\u201d e \u201cSan Martino del Carso\u201d, questa poesia incarna le <strong>innovative caratteristiche dello stile ungarettiano<\/strong>.C&#8217;\u00e8 anche <strong>Pirandello tra gli autori proposti alla maturit\u00e0<\/strong>.\u00a0 Nel testo di Pirandello, tratto da romanzo <strong>&#8216;Quaderni di Serafino Gubbio operatore&#8217; del 1925<\/strong> , si affronta il tema del progresso tecnologico e si riflette sui possibili effetti. Il candidato deve sintetizzare il contenuto del brano, individuare la tesi sostenuta, commentare alcune frasi e fare una serie di riflessioni.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-232981 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/06\/Ungaretti-Pirandello.jpg\" alt=\"Ungaretti Pirandello\" width=\"552\" height=\"342\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/06\/Ungaretti-Pirandello.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/06\/Ungaretti-Pirandello-300x186.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/06\/Ungaretti-Pirandello-768x475.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/06\/Ungaretti-Pirandello-679x420.jpg 679w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/06\/Ungaretti-Pirandello-150x93.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/06\/Ungaretti-Pirandello-696x431.jpg 696w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/06\/Ungaretti-Pirandello-356x220.jpg 356w\" sizes=\"auto, (max-width: 552px) 100vw, 552px\" \/><\/p>\n<div class=\"grid grid-rows-[0fr] transition-[grid-template-rows] duration-300 ease-in-out peer-checked:grid-rows-[1fr] peer-checked:duration-300\" data-testid=\"accordion-children-wrapper\">\n<p><strong>&#8220;Riscoprire il silenzio&#8221; della giornalista Nicoletta Polla Mattiot<\/strong><\/p>\n<p>&#8220;Riscoprire il silenzio&#8221; \u00e8 un altro degli gli argomenti proposti al primo scritto della Maturit\u00e0. Tra le tracce proposte per la prima prova scritta di Maturit\u00e0 c&#8217;\u00e8 anche <strong>&#8220;Profili, selfie e blog&#8221; in cui gli studenti sono chiamati ad analizzare le forme di comunicazione nell&#8217;era digitale<\/strong>. Si tratta di un testo tratto da Maurizio Caminito, intitolato appunto <strong>&#8220;Profili selfie e blog&#8221;<\/strong> del 2014 che\u00a0invita i maturandi a\u00a0una riflessione sull&#8217;importanza e il senso del diario nell&#8217;era digitale. <strong>Nicoletta Polla-Mattiot, laureata in Retorica a Lettere Antiche, \u00e8 giornalista con oltre vent\u2019anni di esperienza fra periodici e quotidiani<\/strong>. Nel 2010 ha fondato con Duccio Demetrio l\u2019Accademia del silenzio, scuola di pedagogia e comunicazione del silenzio. Suo il libro \u201cEsplorare il silenzio\u201d.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-232975 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/06\/Nicoletta-Polla-Mattiot.jpg\" alt=\"Nicoletta Polla Mattiot\" width=\"515\" height=\"290\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/06\/Nicoletta-Polla-Mattiot.jpg 1408w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/06\/Nicoletta-Polla-Mattiot-300x169.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/06\/Nicoletta-Polla-Mattiot-1024x576.jpg 1024w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/06\/Nicoletta-Polla-Mattiot-768x432.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/06\/Nicoletta-Polla-Mattiot-747x420.jpg 747w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/06\/Nicoletta-Polla-Mattiot-150x84.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/06\/Nicoletta-Polla-Mattiot-696x392.jpg 696w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/06\/Nicoletta-Polla-Mattiot-1068x601.jpg 1068w\" sizes=\"auto, (max-width: 515px) 100vw, 515px\" \/><\/p>\n<p><strong>L<\/strong>&#8216;<strong>Importanza della carta costituzionale in un testo di Maria Agostina Cabiddu<\/strong><\/p>\n<p>\u00c8 questa la traccia proposta ai maturandi come traccia per l&#8217;esame di Stato 2024. Nel testo &#8216;l&#8217;Intuizione dei costituenti \u00e8 definita <strong>&#8220;lungimirante&#8221;<\/strong>. <strong>Il testo di Pirandello sul progresso tecnologico. <\/strong>Nel testo di Pirandello, tratto da romanzo <strong>&#8216;Quaderni di Serafino Gubbio operatore&#8217; del 1925<\/strong> , si affronta il tema del progresso tecnologico e si riflette sui possibili effetti. Il candidato deve sintetizzare il contenuto del brano, individuare la tesi sostenuta, commentare alcune frasi e fare una serie di riflessioni.<\/p>\n<p><strong>Maturit\u00e0, scenario geopolitico con traccia su equilibrio del terrore. <\/strong>Legato al contesto internazionale e alla storia recente e meno recente, ai maturandi viene chiesto di parlare di &#8220;<strong>equilibrio del terrore<\/strong>&#8221; e se tale equilibri possano essere efficaci &#8220;anche nel mondo attuale&#8221; o se, invece, il contesto geopolitico attuale &#8220;richieda un approccio diverso&#8221;. <strong>La traccia rientra nella tipologia B &#8211; Analisi e produzione di un testo argomentativo.\u00a0<\/strong><\/p>\n<p>Una traccia di t<strong>esto argomentativo riguarda il tema della Guerra Fredda<\/strong>, partendo da un estratto da &#8220;<strong>Storia d&#8217;Europa&#8221; dello storico, giornalista e politico Giuseppe Galasso,<\/strong> chiamando in causa anche la questione del conflitto atomico, tra blocchi contrapposti.<\/p>\n<p><strong>Rita Levi Montalcini e &#8220;l\u2019elogio dell\u2019imperfezione&#8221;<\/strong><\/p>\n<p>Una delle tracce della maturit\u00e0 affronta l<strong>a questione dell&#8217;imperfezione<\/strong> <strong>come elemento distintivo e di valore<\/strong>, partendo dal libro della scienziata premio <strong>Nobel Rita Levi Montalcini, dal titolo &#8220;Elogio dell&#8217;imperfezione&#8221;.<\/strong> A partire dal brano e partendo dalle proprie esperienze, conoscenze e letture, viene chiesto allo studente di r<strong>iflettere su quale significato possa avere, nella societ\u00e0 contemporanea, l&#8217;elogio dell&#8217;imperfezione<\/strong>.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-232976 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/06\/Rita-Levi-Montalcini.jpg\" alt=\"Rita Levi Montalcini\" width=\"518\" height=\"346\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/06\/Rita-Levi-Montalcini.jpg 700w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/06\/Rita-Levi-Montalcini-300x201.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/06\/Rita-Levi-Montalcini-628x420.jpg 628w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/06\/Rita-Levi-Montalcini-150x100.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/06\/Rita-Levi-Montalcini-696x465.jpg 696w\" sizes=\"auto, (max-width: 518px) 100vw, 518px\" \/><\/p>\n<p><strong>Il patrimonio artistico da un testo della giurista Maria Agostina Cabiddu<\/strong><\/p>\n<p>Una traccia anche sul &#8220;<strong>valore del patrimonio artistico e culturale&#8221;<\/strong> con una riflessione tratta dall&#8217; estratto di un testo della gi<strong>urista e professoressa universitaria Maria Agostina Cabiddu,<\/strong> pubblicato sulla Rivista dell&#8217;Associazione Italiana dei Costituzionalisti. Agli studenti viene chiesto, tra le altre cose, perch\u00e9, a giudizio dell&#8217;autrice, la crescente domanda di bellezza non pu\u00f2 rientrare nella categoria dei beni di lusso.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-232977 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/06\/pellegrinelli.jpg\" alt=\"pellegrinelli\" width=\"566\" height=\"283\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/06\/pellegrinelli.jpg 770w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/06\/pellegrinelli-300x150.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/06\/pellegrinelli-768x384.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/06\/pellegrinelli-150x75.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/06\/pellegrinelli-696x348.jpg 696w\" sizes=\"auto, (max-width: 566px) 100vw, 566px\" \/><\/p>\n<\/div>\n<h3>Princi \u201cabbracciate il futuro senza paura\u201d<\/h3>\n<p>\u201cIn occasione dei prossimi esami di Stato, desidero rivolgere un sentito augurio a tutti voi maturandi che vi accingete a varcare la soglia di questo importante traguardo\u201d. Inizia, cos\u00ec, la lettera che <strong>Giusi Princi, vicepresidente della Giunta Regionale con delega all\u2019Istruzione, neoeletta al Parlamento Europeo, indirizza agli studenti maturandi<\/strong>.<\/p>\n<p>\u201cGli esami di maturit\u00e0 rappresentano un momento delicato e cruciale della vostra vita, segnando la conclusione di un quinquennio ricco di esperienze formative, relazioni profonde e crescita personale. <strong>\u00c8 il culmine di un cammino che vi ha visti trasformarvi da adolescenti a giovani adulti, arricchiti sotto il profilo affettivo, relazionale e cognitivo.<\/strong> Approcciate questa sfida come un&#8217;opportunit\u00e0 straordinaria per guardare avanti e progettare il vostro futuro. <strong>Portate con voi gli insegnamenti, le competenze, il metodo di studio e l&#8217;amore per la conoscenza che vi hanno trasmesso i vostri insegnanti; essi saranno i vostri alleati pi\u00f9 preziosi<\/strong>. Affrontate i giorni a venire con fiducia in voi stessi, d<strong>ando il massimo in ogni prova e mettendo in campo il vostro miglior impegno\u201d<\/strong>.<\/p>\n<p>Giusi Princi, con parole di incoraggiamento, rassicura gli studenti: \u201cR<strong>icordate che non siete soli: i commissari d&#8217;esame lavoreranno per creare un ambiente accogliente, sereno e motivante, dove ciascuno di voi potr\u00e0 esprimere il proprio pieno potenziale<\/strong>. I professori interni, che vi hanno accompagnato in questo percorso, conoscono le vostre capacit\u00e0 e il vostro impegno, mentre quelli esterni arricchiranno la valutazione con la loro esperienza e obiettivit\u00e0. Il merito, frutto del vostro impegno e della vostra dedizione durante tutto il percorso scolastico, sar\u00e0 ci\u00f2 che alla fine conta\u201d.<\/p>\n<p>\u201cIl mio augurio &#8211; prosegue la vicepresidente &#8211; \u00e8 c<strong>he questo possa essere per ciascuno di voi, non un punto di arrivo, ma di partenza: il trampolino di lancio verso un viaggio che vi porter\u00e0 a scoprire il mondo, a inseguire i vostri sogni e realizzare le vostre ambizioni<\/strong>. Da parte mia, nel mio nuovo ruolo di parlamentare europea, in linea con quanto sin qui svolto come vicepresidente della Giunta regionale con delega all\u2019Istruzione, insieme con il presidente Occhiuto, c<strong>ontinuer\u00f2 a sostenervi, a sostenere il mondo della scuola, affinch\u00e9 possiate avere l&#8217;opportunit\u00e0 di costruire il vostro futuro in una Calabria che sia all&#8217;altezza dei vostri sogni e delle vostre competenze\u201d<\/strong>.<\/p>\n<p>\u201cNelson Mandela diceva: \u201cU<strong>n vincitore \u00e8 solo un sognatore che non ha mai mollato\u201d. Prendete questo motto come fonte di ispirazion<\/strong>e- conclude la vicepresidente Princi &#8211; affrontate questa sfida con coraggio, abbracciate il futuro con fiducia e non abbiate timore di esplorare nuove strade e nuove possibilit\u00e0!\u201d.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ROMA &#8211; Ungaretti per l\u2019analisi della poesia poetica e Pirandello, testo in prosa, attesissimi. Poi un testo tratto da \u201cStoria d\u2019Europa\u201d di Galasso che invita i maturandi a riflettere sulla bomba atomica. Ancora, l\u2019elogio dell\u2019imperfezione di Rita Levi Montalcini, una riflessione su\u00a0selfie\u00a0e\u00a0blog, &#8220;Arte, musica, poesia, Natura fra ascolto e comunicazione&#8220; di Nicoletta\u00a0Polla-Mattiot o il\u00a0patrimonio artistico [&hellip;]<\/p>\n","protected":false},"author":61,"featured_media":204773,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[16],"tags":[19],"class_list":["post-232967","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-italia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/232967","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=232967"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/232967\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/204773"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=232967"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=232967"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=232967"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}