{"id":233246,"date":"2024-06-21T14:46:47","date_gmt":"2024-06-21T12:46:47","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=233246"},"modified":"2024-06-21T14:46:47","modified_gmt":"2024-06-21T12:46:47","slug":"autonomia-differenziata-riformisti-rende-peggiorera-la-gia-difficile-situazione-in-cui-versa-il-sud","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/autonomia-differenziata-riformisti-rende-peggiorera-la-gia-difficile-situazione-in-cui-versa-il-sud\/","title":{"rendered":"Autonomia differenziata, Riformisti Rende \u00abpeggiorer\u00e0 la gi\u00e0 difficile situazione in cui versa il Sud\u00bb"},"content":{"rendered":"<p>RENDE &#8211; &#8220;E cos\u00ec il &#8216;padre putativo del Porcellum&#8217; ha partorito un<strong> altro ignobile disegno di legge<\/strong>, approvato in via definitiva dal Parlamento Italiano mercoled\u00ec 19 maggio. <strong>Calderoli<\/strong>, nella sua pervicace azione anti-meridionale, ha \u201cperso il pelo ma non il vizio\u201d. La cosa tragica \u00e8 che questo vizietto \u00e8 stato condiviso da tutta la maggioranza di centrodestra, compresa Forza Italia, nonostante gli strepitii strumentali del nostro Presidente di Regione in \u201czona Cesarini\u201d. E cosa ancora pi\u00f9 grave, l\u2019Autonomia Differenziata \u00e8 stata voluta anche dalla patriota on. Meloni, che si \u00e8 resa responsabile, quindi, della disunit\u00e0 d\u2019Italia, proprio Lei che in giovent\u00f9 si \u00e8 formata ad una cultura che ha sempre idealizzato, per verit\u00e0, il concetto di nazione unita&#8221;.<\/p>\n<p>E&#8217; il commento della <strong>Federazione Riformista di Rende<\/strong> che sottolinea come &#8220;ovviamente, non possono che recare scandalo i tanti voti meridionali e calabresi conseguiti dalla Lega, i cui parlamentari eletti nel Sud hanno votato entusiasticamente la legge Calderoli, che rappresenta un successo del partito di <strong>Salvini<\/strong>. <strong>La Lega che \u00e8 nata secessionista<\/strong> si \u00e8 trasformata in partito nazionale, per partorire, con il concorso di uomini e donne del Sud, un provvedimento che assesta un colpo mortale alla speranza di sviluppo delle regioni meridionali e che allarga la forbice tra il Nord ed il Su<strong>d. \u00c8 evidente,<\/strong> pertanto, che l\u2019Autonomia Differenziata peggiorer\u00e0 la situazione difficile in cui gi\u00e0 versa il Mezzogiorno&#8221;.<\/p>\n<p>&#8220;Il presidente Occhiuto, insieme ad altri &#8211; proseguono i riformisti rendesi &#8211; si \u00e8 impegnato per definire i <strong>costi standard in tema di diritti civili e sociali,<\/strong> per conseguire l\u2019obiettivo di produrre i LEP uguali per tutte le regioni. Intanto andrebbero verificate le disponibilit\u00e0 finanziarie per sostenere i predetti LEP. Il presunto principio di uguaglianza, per\u00f2, che sarebbe garantito dai LEP, non riguarda le grandi infrastrutture, le strade, le autostrade, i porti, gli aeroporti, i rigassificatori, i termovalorizzatori e quant\u2019altro&#8221;.<\/p>\n<h4><strong>Il Sud e la Calabria &#8216;alla frutta&#8217;<\/strong><\/h4>\n<p>&#8220;Le <strong>regioni del Nord<\/strong>, per migliorare le proprie infrastrutture gi\u00e0 ora pi\u00f9 avanzate e moderne di quelle meridionali, certamente utilizzeranno <strong>rilevanti finanziamenti statali<\/strong> ed <strong>europei<\/strong>, per le predette infrastrutture strategiche per lo sviluppo dei territori; finanziamenti che ad esse saranno certamente garantiti da un Governo ad evidente trazione nordista. <strong>Grazie al centrodestra, compresa Foza<\/strong> Italia che non si pu\u00f2 tirare fuori avendo condiviso ed approvato tutte le follie di Calderoli, <strong>le regioni del Mezzogiorno<\/strong>, e la <strong>Calabria<\/strong> in particolare, <strong>sono alla frutta&#8221;.<\/strong><\/p>\n<h5><strong>Simona Loizzo e Mario Occhiuto: &#8220;alla Calabria rester\u00e0 solo la bandiera&#8221;\u00a0<\/strong><\/h5>\n<p>&#8220;Tra i parlamentari calabresi che hanno votato questa legge ingiusta ed infausta &#8211; proseguono i riformisti &#8211; spiccano l\u2019on. <strong>Simona Loizzo<\/strong> e il sen. <strong>Mario Occhiuto<\/strong>. La prima ha avuto la bella idea di <strong>sventolare<\/strong>, in segno di giubilo in aula a <strong>Montecitorio<\/strong>, <strong>la bandiera della Calabria<\/strong>. Forse, inconsciamente, si \u00e8 resa conto che <strong>alla Calabria rester\u00e0 solo la bandiera<\/strong>, grazie in particolare al suo amico Calderoli&#8221;.<\/p>\n<p>&#8220;Altro spessore ha il voto di <strong>Occhiuto senior<\/strong>. Da &#8216;<strong>allegro&#8217; ex sindaco di Cosenza<\/strong>, pi\u00f9 di altri dovrebbe sapere che i Comuni calabresi sono in codice rosso, a partire da quello della nostra citt\u00e0 capoluogo, che \u00e8 stata accompagnata affettuosamente al dissesto. <strong>L\u2019Occhiuto Junior,<\/strong> invece, <strong>piange lacrime di sdegno verso la legge Calderoli<\/strong>, dopo averla sostenuta da vice-capogruppo, da capogruppo a Montecitorio e da vicesegretario di Forza Italia. Staremo a vedere se le sue sono lacrime di coccodrillo a beneficio degli allocchi, oppure una presa di coscienza della sua responsabilit\u00e0 politica verso i calabresi che lo hanno eletto Presidente, responsabilit\u00e0 che dovrebbe indurlo a porre in essere tutti gli atti istituzionali per cancellare questa vergogna, che disonora la destra italiana e Forza Italia&#8221;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>RENDE &#8211; &#8220;E cos\u00ec il &#8216;padre putativo del Porcellum&#8217; ha partorito un altro ignobile disegno di legge, approvato in via definitiva dal Parlamento Italiano mercoled\u00ec 19 maggio. Calderoli, nella sua pervicace azione anti-meridionale, ha \u201cperso il pelo ma non il vizio\u201d. La cosa tragica \u00e8 che questo vizietto \u00e8 stato condiviso da tutta la maggioranza [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":233247,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563],"tags":[19],"class_list":["post-233246","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/233246","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=233246"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/233246\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/233247"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=233246"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=233246"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=233246"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}