{"id":233289,"date":"2024-06-22T09:40:31","date_gmt":"2024-06-22T07:40:31","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=233289"},"modified":"2024-06-22T09:42:16","modified_gmt":"2024-06-22T07:42:16","slug":"controlli-tra-scalea-e-san-nicola-arcella-a-depuratori-aziende-e-lidi-violazioni-e-sanzioni","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/controlli-tra-scalea-e-san-nicola-arcella-a-depuratori-aziende-e-lidi-violazioni-e-sanzioni\/","title":{"rendered":"Controlli tra Scalea e San Nicola Arcella a depuratori, aziende e lidi: violazioni e sanzioni"},"content":{"rendered":"<p>SCALEA (CS) &#8211; Operazione a tutela dell\u2019ambiente dei carabinieri tra <strong>Scalea<\/strong> e <strong>San Nicola Arcella<\/strong> mirata alla salvaguardia del rispetto delle legislazioni in <strong>materia di ambiente<\/strong>, lavoro, preservazione della <strong>sicurezza alimentare<\/strong>, tutela delle aree costiere demaniali e della pulizia delle acque marine prospicenti ai litorali. I militari anche insieme ai tecnici di Arpacal, hanno sottoposto a controllo<strong> 3 depuratori, 4 aziende zootecniche, 11 stabilimenti balneari, 1 cantiere edile, 5 vasche di raccolta reflui di altrettanti parchi condominiali, 1 cementificio e 1 autodemolitore.<\/strong><\/p>\n<p><strong>Nel corso delle operazioni sono stati accertati:<\/strong><\/p>\n<p>&#8211; lo <strong>scarico dei reflui fognari<\/strong> depurati con valori fuori tabella e la compilazione del registro di carico e scarico dei fanghi da depurazione con dati incompleti o inesatti;<\/p>\n<p>&#8211; in<strong> alcuni lidi<\/strong>, <strong>l\u2019assenza<\/strong> delle <strong>dotazioni di sicurezza<\/strong> previste da specifica ordinanza dell\u2019Ufficio Circondariale Marittimo di Maratea, illeciti amministrativi in materia di pesca e acquacultura con il sequestro amministrativo di <strong>circa 52 kg di prodotto ittico<\/strong> non <strong>tracciabile, mancanze igienico<\/strong> \u2013 sanitarie e dell\u2019haccp che hanno portato anche alla chiusura di un locale adibito a deposito alimenti;<\/p>\n<p>&#8211; in un cementificio, violazioni in materia di sicurezza sui luoghi di lavoro e il mancato stoccaggio di oli esausti in conformi contenitori.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-233292 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/06\/carabinieri-controlli-scalea-san-nicola02.jpg\" alt=\"\" width=\"583\" height=\"361\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/06\/carabinieri-controlli-scalea-san-nicola02.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/06\/carabinieri-controlli-scalea-san-nicola02-300x186.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/06\/carabinieri-controlli-scalea-san-nicola02-768x475.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/06\/carabinieri-controlli-scalea-san-nicola02-679x420.jpg 679w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/06\/carabinieri-controlli-scalea-san-nicola02-150x93.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/06\/carabinieri-controlli-scalea-san-nicola02-696x431.jpg 696w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/06\/carabinieri-controlli-scalea-san-nicola02-356x220.jpg 356w\" sizes=\"auto, (max-width: 583px) 100vw, 583px\" \/><\/p>\n<h4>Denunciate tre persone<\/h4>\n<p>Sono state deferite in stato di libert\u00e0 3 persone ovvero <strong>l\u2019amministratore unico di una ditta<\/strong> che aveva allestito un <strong>cantiere<\/strong> per la ristrutturazione di un\u2019abitazione privata, il proprietario di quest\u2019ultima e il <strong>direttore dei lavori<\/strong> per plurime violazioni della normativa in materia di sicurezza sui luoghi di lavoro e per aver costruito senza specifiche autorizzazioni in un\u2019area con vincolo paesaggistico e sismico.<strong>\u00a0L\u2019abitazione \u00e8 stata anche sottoposta a sequestro<\/strong>.<\/p>\n<p>Nell\u2019ambito di quest\u2019ultimo controllo \u00e8 stata verificata anche la presenza di <strong>3 lavoratori non regolarmente assunti. <\/strong>Sono state elevate sanzioni per un totale complessivo di circa 112mila euro, mentre in altre strutture controllate non sono emerse irregolarit\u00e0 di alcun tipo. Infine sono stati effettuati <strong>campionamenti in 3 depuratori e in 5 vasche di raccolta reflui da parte di personale dell\u2019ARPACAL<\/strong> allo scopo di intercettare eventuali flussi inquinanti e pianificare, in prospettiva futura, ulteriori mirati controlli.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" wp-image-233290 aligncenter\" src=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/06\/carabinieri-controlli-depuratori.jpg\" alt=\"\" width=\"570\" height=\"353\" title=\"\" srcset=\"https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/06\/carabinieri-controlli-depuratori.jpg 970w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/06\/carabinieri-controlli-depuratori-300x186.jpg 300w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/06\/carabinieri-controlli-depuratori-768x475.jpg 768w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/06\/carabinieri-controlli-depuratori-679x420.jpg 679w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/06\/carabinieri-controlli-depuratori-150x93.jpg 150w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/06\/carabinieri-controlli-depuratori-696x431.jpg 696w, https:\/\/quicosenza.it\/news\/wp-content\/uploads\/2024\/06\/carabinieri-controlli-depuratori-356x220.jpg 356w\" sizes=\"auto, (max-width: 570px) 100vw, 570px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>SCALEA (CS) &#8211; Operazione a tutela dell\u2019ambiente dei carabinieri tra Scalea e San Nicola Arcella mirata alla salvaguardia del rispetto delle legislazioni in materia di ambiente, lavoro, preservazione della sicurezza alimentare, tutela delle aree costiere demaniali e della pulizia delle acque marine prospicenti ai litorali. I militari anche insieme ai tecnici di Arpacal, hanno sottoposto [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":233291,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"video","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[576],"tags":[19,135],"class_list":["post-233289","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-tirreno","tag-copertina","tag-video","post_format-post-format-video"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/233289","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=233289"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/233289\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/233291"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=233289"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=233289"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=233289"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}