{"id":23355,"date":"2013-06-12T11:27:25","date_gmt":"2013-06-12T09:27:25","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=23355"},"modified":"2023-01-17T13:20:56","modified_gmt":"2023-01-17T12:20:56","slug":"9271-la-societa-acque-potabili-spa-chiude-i-rubinetti-di-200-rendesi","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/9271-la-societa-acque-potabili-spa-chiude-i-rubinetti-di-200-rendesi\/","title":{"rendered":"La societ\u00e0 Acque Potabili SpA chiude i rubinetti di 200 rendesi"},"content":{"rendered":"<p style=\"text-align: justify;\">RENDE \u2013 Contrada Dattoli a secco. La segnalazione arriva da un lettore.<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">\u201cEsiste un problema che riguarda diversi condomini di Rende ed il particolare quello in cui abito sperando che possiate dare voce ad un problema, che nonostante sia stato &nbsp;oggetto di un referendum un po&#8217; di tempo fa ed approvato quasi all&#8217;unanimit\u00e0 dai cittadini italiani, attanaglia ancora alcuni comuni. In particolare faccio un piccolo resoconto di quello che \u00e8 successo da fine maggio in poi al condominio, formato da 59 villette a schiera costruite con agevolazioni dello stato, sito in Contrada Dattoli di Rende. Il 29 maggio u.s. il nostro amministratore riceve un telegramma dalla societ\u00e0 ACQUE POTABILI SPA, che gestisce la rete idrica del comune di Rende, con una avviso di distacco della fornitura dell&#8217;acqua potabile per l&#8217;intero complesso, causa un debito di 19531 euro. &nbsp;Questo debito, stante alla documentazione richiesta in copia dal nostro amministratore, poich\u00e9 di bollette relative non ne aveva mai ricevute, era riconducibile &nbsp;a due bollette insolute di circa 11000 euro pi\u00f9 un acconto sul consumo presunto con scadenza al 19 giugno 2013. Fatta subito una assemblea urgente del condominio, si era stabilito di richiedere subito ai condomini morosi il dovuto, anche attraverso azioni legali, e di richiedere a tutti i condomini un acconto di 100 euro sulla bolletta in scadenza l&#8217;11 giugno. Inoltre, stando alla Corte Suprema di Cassazione &#8211; Sezioni Unite Civile Sentenza n. 9148\/2008 &#8211; deposito del 08 aprile 2008, in cui si chiarisce che la solidariet\u00e0 condominiale entra in gioco dopo che l&#8217;ente o l&#8217;azienda creditrice abbia effettuati tutti i passi necessari per avvalersi sui condomini morosi, l&#8217;amministratore inviava alla sede centrale della ACQUE POTABILI (Corso XI Febbraio, 22 &#8211; 12152 TORINO) l&#8217;elenco dei condomini morosi, con le cifre spettanti relative, e chiedeva alla sede di Rende un congruo periodo per poter effettuare le letture dei contatori di ciascuna villetta e predisporre la suddivisione del dovuto, fermo restando che i 100 euro di acconto di ognuno, appena raccolti sarebbero stati versati. Con sorpresa di tutti luned\u00ec 10 u.s. in mattinata, ci siamo accorti che non c&#8217;era pi\u00f9 l&#8217;erogazione idrica, ma visto le continue rotture dell&#8217;Abatemarco, l&#8217;abbiamo attribuito ad una di queste rotture. Solo il giorno dopo, quindi senza nessun avviso da parte di ACQUE POTABILI, casualmente alcuni condomini hanno scoperto che non c&#8217;era nessuna rottura, ma che l&#8217;azienda aveva interrotto il servizio lasciando senza servizio idrico 59 famiglie. Posso raccontare che nel mio condominio ci sono famiglie formate da anziani non autosufficienti, malati di tumore, famiglie con neonati o bimbi piccoli e che in estate, con le temperature che si avvicinano ai 30 gradi, possano crearsi anche rischi sanitari. Ma la cosa che mi ha lasciato basito \u00e8 la prepotenza e la supponenza di un\u2019azienda privata che toglie l&#8217;elemento primario per condurre una vita decente ad oltre 200 persone e tra questi la maggior parte, compreso lo scrivente, ha sempre onorato puntualmente i propri debiti verso l&#8217;ente. E&#8217; possibile che una societ\u00e0 privata, nonostante il referendum sull&#8217;acqua pubblica, possa comportarsi in questo modo, oserei dire a livello degli usurai o dei mafiosi che chiedono il pizzo? Spero che il vostro giornale possa farsi carico di un problema di carattere generale, non si possono togliere i beni primari ai cittadini, e far in modo che queste storture non avvengano pi\u00f9. &nbsp;L&#8217;acqua \u00e8 un bene di tutti e non ci si deve guadagnare sopra sulla pelle dei cittadini, soprattutto se una parte di questi ultimi \u00e8 incolpevole\u201d.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>RENDE \u2013 Contrada Dattoli a secco. La segnalazione arriva da un lettore.<\/p>\n","protected":false},"author":22,"featured_media":23356,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,563,44],"tags":[],"class_list":["post-23355","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-area-urbana","category-rende"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/23355","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=23355"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/23355\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/23356"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=23355"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=23355"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=23355"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}