{"id":233640,"date":"2024-06-26T19:42:14","date_gmt":"2024-06-26T17:42:14","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=233640"},"modified":"2024-06-26T20:33:20","modified_gmt":"2024-06-26T18:33:20","slug":"cosenza-sibari-conclusi-i-lavori-sulla-sp-197-tra-tarsia-e-la-statale-106-bis","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/cosenza-sibari-conclusi-i-lavori-sulla-sp-197-tra-tarsia-e-la-statale-106-bis\/","title":{"rendered":"Cosenza\u2013Sibari: conclusi i lavori sulla SP 197 tra Tarsia e la Statale 106 bis"},"content":{"rendered":"<p>COSENZA &#8211; <strong>Lavori finiti dopo anni di attesa per la<\/strong> <strong>&#8220;nuova costruzione e parziale adeguamento della strada di collegamento Cosenza \u2013 Sibari&#8221;<\/strong>. L&#8217;annuncio arriva dalla Provincia di Cosenza per il tratto compreso tra lo svincolo A3 uscita Tarsia e la Statale 106 bis \u2013 II Lotto&#8221; Fondo per lo Sviluppo e la Coesione (FSC) 2000-2006 e 2007-2013 \u2013 Delibera CIPE 89\/21. L&#8217;inaugurazione, alla presenza della presidente Rosaria Succurro, si terr\u00e0 gioved\u00ec 27 giugno alle ore 16:00.<\/p>\n<p>Il progetto ha visto la realizzazione di <strong>due gallerie<\/strong>, localizzate rispettivamente tra le progressive 0+695.00 Km. e 0+833.00 Km<strong> (galleria Diga di Tarsia)<\/strong> e tra le progressive 4+429.60 Km. e 4+640.40 Km<strong>\u00a0(galleria Serra Castello)<\/strong>. L\u2019importo dei lavori a base d\u2019asta \u00e8 pari a <strong>10.963.532,83 euro. <\/strong>L&#8217;intervento realizzato permette di incrementare la sicurezza stradale migliorando il livello di servizio complessivo della <strong>Strada Provinciale 197, collegando in maniera rapida i comuni della valle del Crati con quelli dello Jonio Cosentino.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>tri.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Lavori finiti dopo anni di attesa per la &#8220;nuova costruzione e parziale adeguamento della strada di collegamento Cosenza \u2013 Sibari&#8221;. L&#8217;annuncio arriva dalla Provincia di Cosenza per il tratto compreso tra lo svincolo A3 uscita Tarsia e la Statale 106 bis \u2013 II Lotto&#8221; Fondo per lo Sviluppo e la Coesione (FSC) 2000-2006 [&hellip;]<\/p>\n","protected":false},"author":58,"featured_media":233641,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[19],"class_list":["post-233640","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/233640","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/58"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=233640"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/233640\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/233641"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=233640"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=233640"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=233640"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}