{"id":233679,"date":"2024-06-27T11:00:09","date_gmt":"2024-06-27T09:00:09","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=233679"},"modified":"2024-06-27T10:43:10","modified_gmt":"2024-06-27T08:43:10","slug":"infibulazero-le-coperte-de-la-terra-di-piero-nelle-rsa-e-case-di-riposo","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/infibulazero-le-coperte-de-la-terra-di-piero-nelle-rsa-e-case-di-riposo\/","title":{"rendered":"&#8220;InfibulaZero&#8221;, le coperte de La terra di Piero nelle Rsa e case di riposo"},"content":{"rendered":"<p>COSENZA &#8211; Nuovo progetto solidale de La Terra di Piero odv all\u2019interno di \u201cInfibulaZero\u201d con le <strong>coperte solidali<\/strong> in <strong>quattro case di riposo per anziani all\u2019interno dell\u2019iniziativa<\/strong> \u201cDonare ci\u00f2 che ci \u00e8 stato donato dona gioia\u201d. Iniziativa che prevede la <strong>consegna di alcune coperte<\/strong> <strong>agli ospiti della struttura che hanno contribuito a realizzarle<\/strong>. Le strutture coinvolte sono <strong>Villa dei fiori, Rsa Quiete, Clinica Villa azzurra e Rsa Villa S. Stefano<\/strong>.<\/p>\n<p>Le coperte sono state donate agli ospiti delle strutture per creare una sorta di \u201cfilo solidale\u201d. Il progetto \u201cInfibulaZero\u201d \u00e8 stato presentato alla citt\u00e0 lo rra-di-piero-per-combattere-linfibulazione, <strong>Giornata mondiale contro le mutilazioni genitali femminili,<\/strong> spiegando come l\u2019infibulazione sia una pratica disumana, violenta, che ancora colpisce e devasta, nel fisico e nella psiche, tantissime giovani donne. <strong>L&#8217;associazione<\/strong> La Terra di Piero odv, <strong>nei mesi scorsi<\/strong>, ha lanciato una nuova iniziativa per combattere l&#8217;infibulazione, una pratica che consiste nell&#8217;asportazione totale o parziale dei genitali esterni femminili. L\u2019iniziativa si chiama, appunto, \u201c<strong>InfibulaZero<\/strong>\u201d e ha previsto la realizzazione di una <strong>coperta gigante<\/strong>, fatta di coperte all\u2019uncinetto, esposta in <a href=\"https:\/\/quicosenza.it\/news\/area-urbana\/cosenza-una-distesa-di-colori-contro-latroce-pratica-dellinfibulazione\"><strong>piazza Bilotti a Cosenza<\/strong><\/a> con l\u2019intento di ricoprire l\u2019intera superficie. La manifestazione si \u00e8 tenuta il 2 e 3 marzo ed \u00e8 andata oltre ogni previsione dando cos\u00ec la possibilit\u00e0 di<strong> poter gettare le basi per la costruzione di nuove scuole in Africa.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; Nuovo progetto solidale de La Terra di Piero odv all\u2019interno di \u201cInfibulaZero\u201d con le coperte solidali in quattro case di riposo per anziani all\u2019interno dell\u2019iniziativa \u201cDonare ci\u00f2 che ci \u00e8 stato donato dona gioia\u201d. Iniziativa che prevede la consegna di alcune coperte agli ospiti della struttura che hanno contribuito a realizzarle. Le strutture [&hellip;]<\/p>\n","protected":false},"author":42,"featured_media":233681,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42],"tags":[19],"class_list":["post-233679","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/233679","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/42"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=233679"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/233679\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/233681"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=233679"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=233679"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=233679"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}