{"id":23399,"date":"2013-06-14T03:18:50","date_gmt":"2013-06-14T01:18:50","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=23399"},"modified":"2023-01-17T13:20:59","modified_gmt":"2023-01-17T12:20:59","slug":"9293-democrazia-interrotta-il-coraggio-di-andare-avanti","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/9293-democrazia-interrotta-il-coraggio-di-andare-avanti\/","title":{"rendered":"Democrazia interrotta: il coraggio di andare avanti"},"content":{"rendered":"<p style=\"text-align: justify;\">GIOIA TAURO &#8211; Il movimento \u201cLiberi di Ricominciare\u201d nasce a San Luca lo scorso 2 giugno in occasione della Festa della Repubblica.<\/p>\n<p>  <!--more-->  <\/p>\n<p style=\"text-align: justify;\">Si \u00e8 deciso di fondare il movimento proprio in questo territorio della locride \u2013 \u201cricco\u201d di pregiudizi, lontano dalla citt\u00e0 e <strong>definito dal Fatto Quotidiano<\/strong> come la \u201cculla della ndrangheta\u201d \u2013 perch\u00e9 \u201cvittima\u201d dell\u2019ultimo episodio di \u201cantidemocrazia\u201d (avvenuto lo scorso 17 maggio) che ha provocato, a pochi giorni dalla scadenza elettorale, il commissariamento di un\u2019amministrazione giunta a fine mandato.<br \/>Il 2012 \u00e8 stato l&#8217;anno record dei comuni sciolti per mafia: risultato ottenuto grazie alla \u201cpresenza\u201d al Viminale di un ministro tecnico, di provenienza prefettizia. Il governo Monti ha commissariato ben 25 amministrazioni: sei in Campania, cinque in Sicilia, due in Piemonte, uno in Liguria ed undici in Calabria tra cui Reggio Calabria primo comune capoluogo! \u201cLiberi di Ricominciare\u201d mette in discussione la normativa che disciplina lo scioglimento dei consigli comunali per infiltrazioni mafiose (il cosiddetto decreto \u201cTaurianova\u201d n.164\/91) e, tra i principali obiettivi, si pone la necessit\u00e0 di \u201crivedere\u201d tale normativa. Alla manifestazione dello scorso 2 giugno, supportati dal giudice di cassazione dott. Romano De Grazia, \u201cpadre\u201d della legge Lazzati, il movimento Liberi di Ricominciare ha lanciato la proposta della costituzione di un \u201ccomitato per la difesa della democrazia negli enti locali\u201d composto da amministratori, rappresentanze territoriali ed esperti di settore, con lo scopo di predisporre la stesura di un\u2019idonea proposta di legge. Viste le considerevoli adesioni all\u2019iniziativa, provenienti da tutto il territorio provinciale e regionale, si \u00e8 deciso di creare incontri itineranti per illustrare, in tutta la Calabria, le reali limitazioni di questa arcaica legge. Agli amministratori, in carica e non, hanno aderito a questa iniziativa \u201ccoraggiosa\u201d anche movimenti e partiti politici. Tra i principali: Riformisti Italiani,&nbsp;Insieme per Gioia,&nbsp;Mondo Rurale, Ideali e Libert\u00e0.<\/p>\n<p style=\"text-align: justify;\">Con la storica sinergia tra Domenico Pirrotta (presidente di \u201cInsieme per Gioia\u201d) e Paolo Ferrara (presidente di \u201cLiberi di Ricominciare\u201d) \u00e8 stata organizzata la seconda tappa di <strong>\u201cDemocrazia Interrotta:<\/strong> <strong>IL CORAGGIO DI ANDARE AVANTI!\u201d che si svolger\u00e0 sabato 15 ore 10:00 presso il Palazzo Fallara di Gioia Tauro (RC)<\/strong>. Al dibattito saranno coinvolti oltre gli amministratori provinciali e regionali, anche i liberi cittadini (che rivendicano il diritto di eleggere democraticamente i propri rappresentanti) e le realt\u00e0 territoriali \u201cvittime\u201d di democrazia interrotta per l\u2019elaborazione di una proposta di legge capace di modificare la normativa esistente, necessaria a ridare serenit\u00e0 agli amministratori attuali e futuri. Apriranno i lavori: Anna Bagal\u00e0, socio fondatore di \u201cLiberi di Ricominciare\u201d in rappresentanza dell\u2019area tirrenica Rosario Sergi, socio fondatore di \u201cLiberi di Ricominciare\u201d in rappresentanza dell\u2019area ionica.<br \/>Interverranno: <strong>Domenico Pirrotta<\/strong>, Presidente di \u201cInsieme per Gioia\u201d <strong>Renato Bellofiore<\/strong>, Sindaco di Gioia Tauro <strong>Pierpaolo Zavettieri<\/strong>, Consigliere amministrazione provinciale di Reggio Calabria Paolo Ferrara, Presidente di \u201cLiberi di Ricominciare\u201d Salvatore Varano, Presidente \u201cIdeali e libert\u00e0\u201d e gi\u00e0 vicesindaco di Borgia (CZ) Giuseppe Angi\u00f2, socio fondatore di \u201cMondo rurale\u201d e consigliere comunale Ardore (RC) Antonio Demasi, gi\u00e0 Sindaco di Nardodipace (VV) Riccardo Ritorto, gi\u00e0 Sindaco di Siderno (RC) Antonino Castorina, responsabile Nazionale Legalit\u00e0 ed Enti Locali \u2013 Giovani Democratici Ilario Ammendolia, gi\u00e0 Presidente Associazione dei Sindaci della Locride e gi\u00e0 sindaco di Caulonia. Concluder\u00e0 i lavori: Vincenzo Pisano gi\u00e0 Presidente Commissione Antimafia della Regione Calabria.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>GIOIA TAURO &#8211; Il movimento \u201cLiberi di Ricominciare\u201d nasce a San Luca lo scorso 2 giugno in occasione della Festa della Repubblica.<\/p>\n","protected":false},"author":22,"featured_media":23400,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[548,17],"tags":[],"class_list":["post-23399","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archivio-storico-news","category-calabria"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/23399","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=23399"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/23399\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/23400"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=23399"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=23399"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=23399"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}