{"id":235050,"date":"2024-07-15T17:00:43","date_gmt":"2024-07-15T15:00:43","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=235050"},"modified":"2024-07-15T15:28:17","modified_gmt":"2024-07-15T13:28:17","slug":"bocchigliero-il-sindaco-benevento-promette-costruiremo-distributore-carburanti-e-piattaforma-elisoccorso","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/bocchigliero-il-sindaco-benevento-promette-costruiremo-distributore-carburanti-e-piattaforma-elisoccorso\/","title":{"rendered":"Bocchigliero, il sindaco Benevento promette: \u00abcostruiremo distributore carburanti e piattaforma elisoccorso\u00bb"},"content":{"rendered":"<p>BOCCHIGLIERO (CS) &#8211; <strong>Alfonso Benevento<\/strong> \u00e8 il sindaco, al suo secondo mando, eletto con la <strong>lista civica L\u2019aurora<\/strong> nell&#8217;ultima tornata elettorale a<strong> Bocchigliero,<\/strong> comune della provincia di Cosenza che conta 1.100 abitanti, situato nella Sila Grande. Intervistato per la nostra rubrica &#8216;Sindaci e territori: oltre la propaganda&#8217;, Benevento ci espone <strong>gli obiettivi del prossimo quinquennio<\/strong> precisando che l&#8217;obiettivo principale rimane quello di &#8220;mettere in atto i progetti programmati nel primo quinquennio, implementando i servizi essenziali che, come sappiamo tutti, stentano ad essere garantiti a in queste zone montane a causa di risorse ridotte al lumicino e risicate, facendoci carico di diverse cose che non spettano all&#8217;Ente&#8221;.<\/p>\n<h4><strong>&#8220;Costruiremo un distribuitore di carburanti per combattere l&#8217;isolamento&#8221;<\/strong><\/h4>\n<p><strong>Realizzare un impianto di distribuzioni carburanti \u00e8 sicuramente il primo step da perseguire,<\/strong> ci spiega il sindaco, e uno dei principi sul quale si \u00e8 basata la campagna elettorale. &#8220;Nel 2012 abbiamo perso un impianto di distribuzione carburanti. Nella rimodulazione del piano regionale addirittura, nelle aree montane e in tutti i paesi limitrofi, l&#8217;impianto di distribuzione carburanti \u00e8 stato pure tolto e <strong>questi territori sono stati abbandonati<\/strong>. Il problema \u00e8 che si parla di turismo ma io vorrei capire <strong>come fa il turista se viene a Bocchigliero, Campana o Longobucco?<\/strong>\u00a0<strong>Insieme alla valigia &#8211; chiosa il sindaco &#8211; dovrebbe portarsi anche una tanica di benzina<\/strong>&#8220;. Sulla scorta di questo abbiamo implementato un progetto che partir\u00e0 nei prossimi mesi per la realizzazione di una stazione di benzina gestita dal Comune. Attendiamo l&#8217;autorizzazione dei vigili del fuoco ma, sicuramente, la gara per l&#8217;esecuzione dei lavori la indiremo sicuramente in <strong>autunno<\/strong>&#8220;.<\/p>\n<p>Una problematica che tocca anche un aspetto sociale: se un cittadino scende a Rossano per fare benzina, sulla statale 106 a Mirto Crosia o addirittura andare a Camigliattelo &#8211; perch\u00e9 solo in questi posti pu\u00f2 fare benzina &#8211; unisce l&#8217;utile al dilettevole, recandosi nei negozi del territorio e togliendo risorse e indotto economico a Bocchigliero. L&#8217;economia circolante qui non c&#8217;\u00e8 se chi ci abita si reca all&#8217;esterno per sopperire alla mancanza di servizi&#8221;.<\/p>\n<h3><strong>&#8220;Cerchiamo di migliorare la viabilit\u00e0&#8221;<\/strong><\/h3>\n<p>Una delle pi\u00f9 grandi sfide in un&#8217;area montana come Bocchigliero \u00e8 quello di &#8220;migliorare la viabilit\u00e0. Noi vorremmo ricongiungerci &#8211; e abbiamo gi\u00e0 iniziato i lavori con un primo lotto &#8211; alla strada che stanno ricostruendo a Longobucco in quanto siamo limitrofi a questo Comune. Stiamo lavorando sul primo lotto, una piccola strada interpoderale di tre chilometri, per riportarla a una strada percorribile, in termini di norma, e <strong>ricongiungerci alla strada Sila-mare di Longobucco<\/strong>. <strong>Sono dieci chilometri totali<\/strong> &#8211;<strong> sei nel nostro Comune e tre\u00a0 in quelli di Longobucco &#8211;<\/strong> e sono partiti i lavori per i primi tre chilometri. Nel 2025 siamo in graduatoria per il secondo lotto e stiamo concertando sia con la Regione sia con il Comune di Longobucco i tre chilometri di competenza loro, perch\u00e9 per noi sarebbe uno sbocco migliore per raggiungere il mare.<\/p>\n<h3><strong>Sanit\u00e0, il progetto di una piattaforma per l&#8217;elissoccorso<\/strong><\/h3>\n<p>Nell&#8217;ambito della sanit\u00e0, prosegue ancora il sindaco, abbiamo ottenuto tramite la SNAI &#8211; Strategia Nazionale Aree Interne &#8211; un finanziamento di<strong> 176 mila euro<\/strong> per quanto riguarda la realizzazione di una <strong>piattaforma elisoccorso<\/strong> al fine di <strong>abbattere i tempi di percorrenza<\/strong> in quanto siamo distanti 80 chilometri da Cosenza, 50 chilometri da Rossano e 40 chilometri da Cariati. Un progetto &#8211; promette il sindaco &#8211; che <strong>verr\u00e0 realizzato nel 2025<\/strong> perch\u00e9 abbiamo gi\u00e0 gli stanziamenti e da qui a breve daremo l&#8217;incarico per la progettazione esecutiva e le verifiche del caso. Settimana scorsa abbiamo fatto un incontro in Regione per far rientrare il progetto, insieme all&#8217;Asp di Cosenza, nel piano delle piattaforme di elisoccorso. Questo \u00e8 un terzo punto sul quale s<strong>periamo di agire velocemente.<\/strong><\/p>\n<h3><strong>Istruzione e progetti dal PNRR e PSR Calabria<\/strong><\/h3>\n<p>Uno stanziamento di<strong> 2 milioni e 600 mila euro dal PNRR<\/strong> abbraccia invece diverse tematiche e realt\u00e0, dal sociale alle infrastrutture. Abbiamo un milione gi\u00e0 approvato sulla <strong>palestra<\/strong> mentre sul sociale abbiamo gi\u00e0 realizzato delle villette in esecuzione. Sulla parte della<strong> digitalizzazione<\/strong> abbiamo gi\u00e0 <strong>100mila euro<\/strong> e stiamo gi\u00e0 investendo per implementare i servizi negli uffici. Lavoriamo molto con il PSR Calabria per quanto riguarda le<strong> infrastutture e le nostre stradine interpoderali.<\/strong> A fine mese inizieremo ad asfaltare alcune strade extraurbane per far s\u00ec che chi abita nella nostra comunit\u00e0 viva con i migliori servizi possibili. Qui <strong>manteniamo le scuole grazie al progetto SPRAR,<\/strong> avviato gi\u00e0 da diversi anni da questa amministrazione, che permette un&#8217;integrazione a 360 gradi grazie anche alla popolazione, con bambini che provengono da situazioni disagiate, puntando ai nuclei monofamiliari. Tutto ci\u00f2 ci permettere di garantire la sopravvivenza delle scuole.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>BOCCHIGLIERO (CS) &#8211; Alfonso Benevento \u00e8 il sindaco, al suo secondo mando, eletto con la lista civica L\u2019aurora nell&#8217;ultima tornata elettorale a Bocchigliero, comune della provincia di Cosenza che conta 1.100 abitanti, situato nella Sila Grande. Intervistato per la nostra rubrica &#8216;Sindaci e territori: oltre la propaganda&#8217;, Benevento ci espone gli obiettivi del prossimo quinquennio [&hellip;]<\/p>\n","protected":false},"author":64,"featured_media":235066,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[28],"tags":[19],"class_list":["post-235050","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-provincia","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/235050","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/64"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=235050"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/235050\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/235066"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=235050"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=235050"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=235050"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}