{"id":235309,"date":"2024-07-17T17:00:30","date_gmt":"2024-07-17T15:00:30","guid":{"rendered":"https:\/\/www.quicosenza.it\/news\/?p=235309"},"modified":"2024-07-17T16:34:48","modified_gmt":"2024-07-17T14:34:48","slug":"inaugurata-prima-biblioteca-di-quartiere-nel-centro-storico-caruso-importante-traguardo","status":"publish","type":"post","link":"https:\/\/quicosenza.it\/news\/inaugurata-prima-biblioteca-di-quartiere-nel-centro-storico-caruso-importante-traguardo\/","title":{"rendered":"Inaugurata prima Biblioteca di Quartiere nel Centro Storico, Caruso: &#8220;importante traguardo&#8221;"},"content":{"rendered":"<div>COSENZA &#8211; &#8220;L&#8217;inaugurazione questa mattina della Biblioteca di Quartiere Chiappetta-Stancati in corso Garibaldi a Cosenza Vecchia, <strong>\u00e8 un nuovo importante atto che abbiamo compiuto per la costruzione di un ecosistema favorevole alla diffusione della lettura. Si tratta di un altro impegno mantenuto<\/strong>&#8220;. Lo afferma il sindaco Franz Caruso a seguito della presentazione ufficiale\u00a0 della Biblioteca di Quartiere Chiappetta-Stancati, svoltasi questa mattina\u00a0 nella sede operativa \u00a0dell&#8217;Associazione Insieme Odv a cui hanno preso parte, oltre al presidente Antonio Chiappetta e al volontario professor Roberto Stancati, promotori dell&#8217;iniziativa, anche la consigliera delegata alla Cultura, Antonietta Cozza, il presidente della Commissione Cultura, Mimmo Frammartino, con i membri della commissione stessa, e la consigliera \u00a0Alessandra Bresciani.<\/div>\n<div><\/div>\n<div>&#8220;Ritengo un vero e proprio dovere sociale incrementare ogni \u00a0forma di sostegno all&#8217;attivit\u00e0 di lettura \u2013 prosegue Franz Caruso \u2013 \u00a0<strong>volano di conoscenza e formazione capace di favorire l&#8217;ascolto, il pensiero critico, la condivisione e lo scambio di saperi.<\/strong> Non a caso abbiamo partecipato al progetto &#8220;Citt\u00e0 che legge&#8221; promosso e curato dal Centro per il libro e la lettura (Cepell) del Ministero della Cultura, \u00a0attivando il &#8220;Patto locale per la lettura di valenza intercomunale&#8221; sottoscritto anche dai Comuni di Marano Principato, Mendicino e Torano Castello, attraverso il quale, grazie alle numerose iniziative in programma, \u00e8 stato possibile coinvolgere un&#8217;ampia filiera di interlocutori che va dalle biblioteche alle scuole, dalle librerie agli editori, dagli autori ai lettori e a tutti i soggetti impegnati in progetti di lettura. Un&#8217;azione quella portata avanti che, \u00a0con l&#8217;iscrizione alla banca dati &#8220;Patti per la lettura&#8221;, <strong>ha consentito alla citt\u00e0 di Cosenza di ottenere la qualifica di &#8220;Citt\u00e0 che legge&#8221; per il biennio 2022-2023<\/strong>&#8220;.<\/div>\n<div><\/div>\n<div>&#8220;Oggi\u00a0 la prima Biblioteca di Quartiere che abbiamo inaugurato \u2013 conclude Franz Caruso \u2013 \u00e8 un nuovo<strong> importante traguardo \u00a0raggiunto<\/strong> a seguito della importante collaborazione \u00a0instaurata con l&#8217;associazione Insieme ODV, che ringrazio insieme alla dott.ssa Marilena Cerzoso <strong>che \u00e8 stata prodiga di sostegno ed all&#8217;intera Commissione Cultura che ha seguito con la mia consigliera delegata l&#8217;iniziativa&#8221;<\/strong>.<\/div>\n<div><\/div>\n<div>Nel corso dell&#8217;incontro di presentazione della Biblioteca di Quartiere Chiappetta-Stancati, \u00e8 stata sottolineata la novit\u00e0 che la stessa rappresenta, la prima nel suo genere, ed \u00e8 stato evidenziato \u00a0l&#8217;innovativo rapporto fra volontariato e istituzione municipale instaurato in citt\u00e0 con la sindacatura di Franz Caruso. <strong>&#8220;L&#8217;apertura alla cittadinanza del centro storico \u2013 \u00e8 stato affermato nel corso della presentazione &#8211; \u00a0e il tentativo di propiziare l&#8217;integrazione con i &#8220;nuovi cittadini&#8221; immigrati di Cosenza, connoteranno l&#8217;azione della Biblioteca<\/strong>, che si propone come elemento di propulsione e sviluppo del &#8220;libero pensiero&#8221; nell&#8217;illustrare la tradizione della citt\u00e0 di Telesio&#8221;.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>COSENZA &#8211; &#8220;L&#8217;inaugurazione questa mattina della Biblioteca di Quartiere Chiappetta-Stancati in corso Garibaldi a Cosenza Vecchia, \u00e8 un nuovo importante atto che abbiamo compiuto per la costruzione di un ecosistema favorevole alla diffusione della lettura. Si tratta di un altro impegno mantenuto&#8220;. Lo afferma il sindaco Franz Caruso a seguito della presentazione ufficiale\u00a0 della Biblioteca [&hellip;]<\/p>\n","protected":false},"author":61,"featured_media":235310,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2}},"categories":[563,42],"tags":[19],"class_list":["post-235309","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-area-urbana","category-cosenza","tag-copertina"],"acf":[],"jetpack_publicize_connections":[],"_links":{"self":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/235309","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/comments?post=235309"}],"version-history":[{"count":0,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/posts\/235309\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media\/235310"}],"wp:attachment":[{"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/media?parent=235309"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/categories?post=235309"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/quicosenza.it\/news\/wp-json\/wp\/v2\/tags?post=235309"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}